{"id":9990,"date":"2025-11-14T10:11:51","date_gmt":"2025-11-14T10:11:51","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=9990"},"modified":"2025-11-14T10:11:52","modified_gmt":"2025-11-14T10:11:52","slug":"defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/","title":{"rendered":"D\u00e9fense: Un Haut responsable militaire Russe \u00e9tait \u00e0 Malabo pour renforcer la coop\u00e9ration militaire"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le Pr\u00e9sident de la R\u00e9publique de Guin\u00e9e Equatoriale  Obiang Nguema Mbasogo a tenu le jeudi 13 novembre 2025 deux audiences au Palais du peuple de Malabo, avec le Dr Akinwumi Adesina, ancien pr\u00e9sident de la Banque africaine de d\u00e9veloppement, et une d\u00e9l\u00e9gation militaire de la F\u00e9d\u00e9ration de Russie conduite par le g\u00e9n\u00e9ral de lieutenant Andrei Averyanov.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors de la premi\u00e8re audience, le Chef de l&#8217;\u00c9tat a re\u00e7u le Dr Akinwumi Ayodeji Adesina, qui a jusqu&#8217;\u00e0 il y a quelques mois occup\u00e9 les fonctions de pr\u00e9sident de la Banque africaine de d\u00e9veloppement (BAD) et est reconnu comme l&#8217;un des plus \u00e9minents \u00e9conomistes et dirigeants du d\u00e9veloppement en Afrique.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"1152\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/582972738_1170296385294123_9218119454187881864_n-1-edited.jpg\" alt=\"\" class=\"wp-image-9992\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/582972738_1170296385294123_9218119454187881864_n-1-edited.jpg 2048w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/582972738_1170296385294123_9218119454187881864_n-1-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/582972738_1170296385294123_9218119454187881864_n-1-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/582972738_1170296385294123_9218119454187881864_n-1-edited-768x432.jpg 768w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/582972738_1170296385294123_9218119454187881864_n-1-edited-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><figcaption class=\"wp-element-caption\"><strong>l&#8217;ex Pr\u00e9sident de la BAD Dr Akinwumi Ayodeji Adesina et le Chef de l&#8217;Etat Equatoguin\u00e9en Obiang Ngiuema \u00e0 Malabo <\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Durant les dix ann\u00e9es pass\u00e9es par le Dr Adesina \u00e0 la t\u00eate de la BAD, il a entretenu des relations \u00e9troites avec le chef de l&#8217;\u00c9tat de la Guin\u00e9e \u00e9quatoriale, qui exerce actuellement la pr\u00e9sidence de la Communaut\u00e9 \u00e9conomique des \u00c9tats de l&#8217;Afrique centrale (CEEAC). En avril de cette ann\u00e9e, avant la fin de son mandat, le Dr Adesina a rendu visite au dirigeant \u00e9quato-guin\u00e9en pour lui dire officiellement au revoir. Ce jeudi, les deux se sont retrouv\u00e9s dans un environnement de cordialit\u00e9 et de reconnaissance mutuelle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors d&#8217;une deuxi\u00e8me audience, le Pr\u00e9sident de la R\u00e9publique a re\u00e7u une d\u00e9l\u00e9gation russe conduite par le g\u00e9n\u00e9ral d&#8217;arm\u00e9e Andrei Averyanov, dans le cadre des relations de coop\u00e9ration militaire entre la Guin\u00e9e \u00e9quatoriale et la F\u00e9d\u00e9ration de Russie. Les deux pays continuent de renforcer leurs liens d&#8217;amiti\u00e9 et de coop\u00e9ration en mati\u00e8re de d\u00e9fense et de s\u00e9curit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Source : Pr\u00e9sidence de la R\u00e9publique de Guin\u00e9e Equatoriale<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Pr\u00e9sident de la R\u00e9publique de Guin\u00e9e Equatoriale Obiang Nguema Mbasogo a tenu le jeudi 13 novembre 2025 deux audiences au Palais du peuple de Malabo, avec le Dr Akinwumi Adesina, ancien pr\u00e9sident de la Banque africaine de d\u00e9veloppement, et une d\u00e9l\u00e9gation militaire de la F\u00e9d\u00e9ration de Russie conduite par<\/p>\n","protected":false},"author":3,"featured_media":9994,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[51],"tags":[],"class_list":["post-9990","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diplomatie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited-1536x864.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited-1400x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Le Pr\u00e9sident de la R\u00e9publique de Guin\u00e9e Equatoriale Obiang Nguema Mbasogo a tenu le jeudi 13 novembre 2025 deux audiences au Palais du peuple de Malabo, avec le Dr Akinwumi Adesina, ancien pr\u00e9sident de la Banque africaine de d\u00e9veloppement, et une d\u00e9l\u00e9gation militaire de la F\u00e9d\u00e9ration de Russie conduite par","magazineBlocksPostCategories":["DIPLOMATIE"],"magazineBlocksPostViewCount":300,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited.jpg",2048,1152,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-51\">DIPLOMATIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>D\u00e9fense: Un Haut responsable militaire Russe \u00e9tait \u00e0 Malabo pour renforcer la coop\u00e9ration militaire - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9fense: Un Haut responsable militaire Russe \u00e9tait \u00e0 Malabo pour renforcer la coop\u00e9ration militaire - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Le Pr\u00e9sident de la R\u00e9publique de Guin\u00e9e Equatoriale Obiang Nguema Mbasogo a tenu le jeudi 13 novembre 2025 deux audiences au Palais du peuple de Malabo, avec le Dr Akinwumi Adesina, ancien pr\u00e9sident de la Banque africaine de d\u00e9veloppement, et une d\u00e9l\u00e9gation militaire de la F\u00e9d\u00e9ration de Russie conduite par\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-14T10:11:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-14T10:11:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"D\u00e9fense: Un Haut responsable militaire Russe \u00e9tait \u00e0 Malabo pour renforcer la coop\u00e9ration militaire\",\"datePublished\":\"2025-11-14T10:11:51+00:00\",\"dateModified\":\"2025-11-14T10:11:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/\"},\"wordCount\":344,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited.jpg\",\"articleSection\":[\"DIPLOMATIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/\",\"name\":\"D\u00e9fense: Un Haut responsable militaire Russe \u00e9tait \u00e0 Malabo pour renforcer la coop\u00e9ration militaire - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited.jpg\",\"datePublished\":\"2025-11-14T10:11:51+00:00\",\"dateModified\":\"2025-11-14T10:11:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited.jpg\",\"width\":2048,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9fense: Un Haut responsable militaire Russe \u00e9tait \u00e0 Malabo pour renforcer la coop\u00e9ration militaire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9fense: Un Haut responsable militaire Russe \u00e9tait \u00e0 Malabo pour renforcer la coop\u00e9ration militaire - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9fense: Un Haut responsable militaire Russe \u00e9tait \u00e0 Malabo pour renforcer la coop\u00e9ration militaire - Cooperation Internationale","og_description":"Le Pr\u00e9sident de la R\u00e9publique de Guin\u00e9e Equatoriale Obiang Nguema Mbasogo a tenu le jeudi 13 novembre 2025 deux audiences au Palais du peuple de Malabo, avec le Dr Akinwumi Adesina, ancien pr\u00e9sident de la Banque africaine de d\u00e9veloppement, et une d\u00e9l\u00e9gation militaire de la F\u00e9d\u00e9ration de Russie conduite par","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-11-14T10:11:51+00:00","article_modified_time":"2025-11-14T10:11:52+00:00","og_image":[{"width":2048,"height":1152,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"D\u00e9fense: Un Haut responsable militaire Russe \u00e9tait \u00e0 Malabo pour renforcer la coop\u00e9ration militaire","datePublished":"2025-11-14T10:11:51+00:00","dateModified":"2025-11-14T10:11:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/"},"wordCount":344,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited.jpg","articleSection":["DIPLOMATIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/","name":"D\u00e9fense: Un Haut responsable militaire Russe \u00e9tait \u00e0 Malabo pour renforcer la coop\u00e9ration militaire - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited.jpg","datePublished":"2025-11-14T10:11:51+00:00","dateModified":"2025-11-14T10:11:52+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited.jpg","width":2048,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/14\/defense-un-haut-responsable-militaire-russe-etait-a-malabo-pour-renforcer-la-cooperation-militaire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"D\u00e9fense: Un Haut responsable militaire Russe \u00e9tait \u00e0 Malabo pour renforcer la coop\u00e9ration militaire"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/583067060_1170296361960792_5362423517954087628_n-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/9990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=9990"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/9990\/revisions"}],"predecessor-version":[{"id":9995,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/9990\/revisions\/9995"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/9994"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=9990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=9990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=9990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}