{"id":9945,"date":"2025-11-13T08:35:11","date_gmt":"2025-11-13T08:35:11","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=9945"},"modified":"2025-11-13T08:35:12","modified_gmt":"2025-11-13T08:35:12","slug":"ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/","title":{"rendered":"CEO de la Fondation Merck rencontre la Premi\u00e8re Dame du S\u00e9n\u00e9gal et 6 Premi\u00e8res Dames Africaines lors de la 12\u00e8me \u00c9dition de la conf\u00e9rence Merck Foundation Africa Asia Luminary 2025 en Gambie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Avec la Premi\u00e8re Dame du S\u00e9n\u00e9gal, la Fondation Merck a fourni 29 bourses pour les m\u00e9decins locaux au S\u00e9n\u00e9gal dans de nombreuses sp\u00e9cialit\u00e9s critiques et mal desservies<\/em><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La Fondation Merck ,\u00a0<\/strong>branche philanthropique de Merck KGaA Allemagne, a r\u00e9cemment organis\u00e9 la\u00a0<strong>12\u00e8me \u00e9dition\u00a0<\/strong>de sa conf\u00e9rence annuelle<strong>, \u00ab Merck Foundation Africa Asia Luminary \u00bb,\u00a0<\/strong>en partenariat avec le Gouvernement Gambien. La conf\u00e9rence \u00e9tait copr\u00e9sid\u00e9e par\u00a0<strong>S.E. Mme FATOUMATTA BAH-BARROW, Premi\u00e8re Dame de Gambie et Ambassadrice de la Fondation Merck \u00ab Plus Qu\u2019une M\u00e8re \u00bb,\u00a0<\/strong>et le<strong>\u00a0Dr. Rasha Kelej, CEO de la Fondation Merck et Pr\u00e9sidente de \u00ab Plus Qu\u2019une M\u00e8re \u00bb. La Premi\u00e8re Dame du S\u00e9n\u00e9gal, S.E. Madame MARIE KHONE FAYE,\u00a0<\/strong>ainsi que les<strong>\u00a0Premi\u00e8res Dames du Burundi, R\u00e9publique Centrafricaine, Lib\u00e9ria, Nig\u00e9ria et Sao Tom\u00e9-et-Principe,\u00a0<\/strong>ont particip\u00e9 en tant qu\u2019invit\u00e9es d\u2019honneur et oratrices principales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S\u00e9natrice, Dr Rasha Kelej (Ret.),&nbsp;<\/strong>a d\u00e9clar\u00e9 : \u00ab Je suis tr\u00e8s heureuse d&#8217;avoir rencontr\u00e9 ma ch\u00e8re s\u0153ur,<strong>&nbsp;S.E. Madame MARIE KHONE FAYE, Premi\u00e8re Dame de la R\u00e9publique du S\u00e9n\u00e9gal et Ambassadrice de la Fondation Merck \u00ab Plus Qu&#8217;une M\u00e8re \u00bb.&nbsp;<\/strong>Nous avons eu une discussion tr\u00e8s enrichissante au sujet de nos programmes conjoints en cours dans le pays, visant \u00e0 transformer le syst\u00e8me de sant\u00e9 publique et \u00e0 sensibiliser le public \u00e0 un large \u00e9ventail de probl\u00e9matiques sanitaires. Je suis heureuse d&#8217;annoncer que nous avons, \u00e0 ce jour, octroy\u00e9<strong>&nbsp;29 bourses d&#8217;\u00e9tudes&nbsp;<\/strong>\u00e0 des m\u00e9decins s\u00e9n\u00e9galais dans de nombreuses sp\u00e9cialit\u00e9s telles que l&#8217;Oncologie, Diab\u00e8te, Fertilit\u00e9 et Embryologie. Nous avons \u00e9galement \u00e9voqu\u00e9 la possibilit\u00e9 d&#8217;\u00e9tendre ces programmes. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>S.E. Madame MARIE KHONE FAYE, Premi\u00e8re Dame de la R\u00e9publique du S\u00e9n\u00e9gal et Ambassadrice de la Fondation Merck \u00ab Plus Qu&#8217;une M\u00e8re \u00bb,&nbsp;<\/strong>a d\u00e9clar\u00e9 : \u00ab C&#8217;est un grand plaisir de collaborer \u00e9troitement avec la Fondation Merck. J&#8217;appr\u00e9cie profond\u00e9ment leurs programmes et je suis ravie d&#8217;annoncer que nous avons lanc\u00e9 ensemble le programme<strong>&nbsp;\u00ab \u00c9duquer Linda \u00bb&nbsp;<\/strong>dans mon pays. Gr\u00e2ce \u00e0 ce programme, nous offrons chaque ann\u00e9e des bourses d&#8217;\u00e9tudes \u00e0&nbsp;<strong>40 jeunes filles brillantes issues de milieux d\u00e9favoris\u00e9s.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par ailleurs, la Fondation Merck a octroy\u00e9 29 bourses d&#8217;\u00e9tudes \u00e0 nos m\u00e9decins dans des sp\u00e9cialit\u00e9s cl\u00e9s telles que l&#8217;Oncologie, Fertilit\u00e9, Embryologie et Diab\u00e8te. Toutes ces bourses sont essentielles et contribuent \u00e0 transformer notre syst\u00e8me de soins. \u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Retrouvez le discours de la Premi\u00e8re Dame du S\u00e9n\u00e9gal et Ambassadrice de la Fondation Merck \u00ab Plus Qu&#8217;une M\u00e8re \u00bb lors de la conf\u00e9rence Merck Foundation Africa Asia Luminary 2025 ici :&nbsp;<\/strong><a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/r.news.africa-wire.com\/mk\/cl\/f\/sh\/7nVU1aA2ng9SOhgC332iXQ8YZjd8ZDn\/6ssu0IcUUSAc\"><strong>https:\/\/youtu.be\/g7CoXpbG9CM<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Regardez la vid\u00e9o de la rencontre entre la&nbsp;<strong>CEO de la Fondation Merck, S\u00e9natrice, Dr. Rasha Kelej<\/strong>, et&nbsp;<strong>S.E. Madame MARIE KHONE FAYE, Premi\u00e8re Dame de la R\u00e9publique du S\u00e9n\u00e9gal et Ambassadrice de la Fondation Merck \u00ab Plus Qu&#8217;une M\u00e8re<\/strong>&nbsp;\u00bb :&nbsp;<a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/r.news.africa-wire.com\/mk\/cl\/f\/sh\/WCPzyXJTZ6vLwtroqk4eRmCTPVMbii8Z\/TRUyA-n0AF7d\"><strong>https:\/\/youtu.be\/lfIQgKsEuI0<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le premier jour de la conf\u00e9rence s&#8217;est tenue la Session Pl\u00e9ni\u00e8re du programme&nbsp;<strong>Merck Foundation Africa Asia Luminary 2025<\/strong>, avec des discours d&#8217;ouverture prononc\u00e9s par les Premi\u00e8res Dames d&#8217;Afrique. Par ailleurs, une table ronde minist\u00e9rielle de haut niveau a r\u00e9uni des ministres africains afin d&#8217;\u00e9changer sur la strat\u00e9gie du Sommet Africain de Recherche de la Fondation Merck (MARS), visant \u00e0 renforcer les capacit\u00e9s de recherche scientifique et \u00e0 promouvoir l&#8217;autonomisation des femmes dans les domaines des sciences, des technologies, de l&#8217;ing\u00e9nierie et des math\u00e9matiques (STEM), avec un accent particulier sur la recherche scientifique.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le deuxi\u00e8me jour de la conf\u00e9rence, une r\u00e9union du comit\u00e9&nbsp;<strong>de l&#8217;Initiative des Premi\u00e8res Dames de la Fondation Merck (MFFLI)<\/strong>&nbsp;a rassembl\u00e9 les&nbsp;<strong>Premi\u00e8res Dames d&#8217;Afrique et le Chairman et la CEO de la Fondation Merck<\/strong>. Les&nbsp;<strong>Premi\u00e8res Dames Africaines<\/strong>&nbsp;y ont pr\u00e9sent\u00e9 le rapport d&#8217;impact des programmes de la Fondation Merck dans leurs pays respectifs, et la strat\u00e9gie future a \u00e9t\u00e9 abord\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Regardez la vid\u00e9o de la r\u00e9union du comit\u00e9 MFFLI\u00a0<\/strong>:<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Dr. Rasha Kelej @ Merck Foundation First Ladies Initiative (MFFLI) Committee - 2025\" width=\"800\" height=\"450\" src=\"https:\/\/www.youtube.com\/embed\/sc2XFyU3s10?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Avec la&nbsp;<strong>Premi\u00e8re Dame du S\u00e9n\u00e9gal<\/strong>, la Fondation Merck a fourni&nbsp;<strong>29 bourses<\/strong>&nbsp;pour les m\u00e9decins locaux au S\u00e9n\u00e9gal dans de nombreuses sp\u00e9cialit\u00e9s critiques et mal desservies. Sur&nbsp;<strong>29 bourses :<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>8 bourses\u00a0<\/strong>ont \u00e9t\u00e9 offertes dans le domaine vital de l&#8217;Oncologie, afin que les patients puissent recevoir des soins du cancer de qualit\u00e9 et \u00e9quitables dans leur pays.<\/li>\n\n\n\n<li><strong>11 bourses\u00a0<\/strong>ont \u00e9t\u00e9 offertes \u00e0 nos m\u00e9decins pour une formation pratique en Fertilit\u00e9 et en Embryologie, ainsi que pour les Dipl\u00f4mes Post-Universitaire d&#8217;un an et de deux ans en Soins Sexuels et Reproductifs. Cela contribuera consid\u00e9rablement sur l&#8217;avancement de la sant\u00e9 des femmes et r\u00e9volutionnera les soins de reproduction et de fertilit\u00e9 au S\u00e9n\u00e9gal.<\/li>\n\n\n\n<li><strong>10 bourses\u00a0<\/strong>ont \u00e9t\u00e9 accord\u00e9es pour le Cours de Master du Diab\u00e8te. Une fois termin\u00e9, ces m\u00e9decins seront non seulement \u00e9quip\u00e9s pour prendre en charge efficacement les patients diab\u00e9tiques, mais joueront \u00e9galement un r\u00f4le cl\u00e9 dans la sensibilisation sur cette maladie et la promotion de l&#8217;importance d&#8217;un mode de vie sain dans nos communaut\u00e9s.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab La Fondation Merck a toujours cru en l\u2019importance du renforcement des capacit\u00e9s du syst\u00e8me de sant\u00e9 et \u0153uvre en ce sens depuis 2012. \u00c0 ce jour, nous avons octroy\u00e9&nbsp;<strong>plus de 2 400 bourses<\/strong>&nbsp;\u00e0 des professionnels de sant\u00e9 issus de&nbsp;<strong>52 pays<\/strong>&nbsp;et exer\u00e7ant dans&nbsp;<strong>44 sp\u00e9cialit\u00e9s m\u00e9dicales essentielles et mal desservies<\/strong>. Nous continuerons \u00e0 financer les bourses \u00e9tudes de m\u00e9decins du S\u00e9n\u00e9gal et d\u2019ailleurs \u00bb, a ajout\u00e9 le&nbsp;<strong>Dr Kelej<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La Fondation Merck,&nbsp;<\/strong>en partenariat avec la<strong>&nbsp;Premi\u00e8re Dame du S\u00e9n\u00e9gal,&nbsp;<\/strong>a lanc\u00e9 de nombreuses initiatives de sensibilisation communautaire pour aborder un large \u00e9ventail de probl\u00e9matiques sociales et sanitaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En collaboration avec le Bureau de la&nbsp;<strong>Premi\u00e8re Dame du S\u00e9n\u00e9gal<\/strong>, elle a r\u00e9cemment organis\u00e9 une Formation des M\u00e9dias sur la Sant\u00e9 En Ligne afin d&#8217;encourager les journalistes \u00e0 donner la parole aux personnes marginalis\u00e9es et \u00e0 impulser un changement culturel autour de questions sociales cruciales telles que le soutien \u00e0 l&#8217;\u00e9ducation des filles, l&#8217;\u00e9limination des violences sexistes et des mutilations g\u00e9nitales f\u00e9minines, l&#8217;autonomisation des femmes et la sensibilisation \u00e0 des probl\u00e8mes de sant\u00e9 comme le diab\u00e8te et l&#8217;hypertension.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>La Fondation Merck&nbsp;<\/strong>a \u00e9galement lanc\u00e9 un Appel \u00e0 Candidatures pour ses 8 prix importants, en partenariat avec la&nbsp;<strong>Premi\u00e8re Dame du S\u00e9n\u00e9gal<\/strong>, destin\u00e9s aux m\u00e9dias, aux musiciens, aux cr\u00e9ateurs de mode, aux cin\u00e9astes, aux \u00e9tudiants et aux nouveaux talents potentiels dans ces domaines.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De plus, en partenariat avec la&nbsp;<strong>Premi\u00e8re Dame du S\u00e9n\u00e9gal<\/strong>, la Fondation Merck a \u00e9galement lanc\u00e9 sept livres d&#8217;histoires pour enfants :&nbsp;<strong>\u00ab Plus Qu&#8217;une M\u00e8re \u00bb, \u00ab \u00c9duquer Linda \u00bb, \u00ab Le Secours de Jackline \u00bb, \u00ab Pas Qui Vous \u00eates \u00bb, \u00ab Une Balade vers le Futur \u00bb, \u00ab Jude Sans Sucre \u00bb et \u00ab La Tension de Mark \u00bb<\/strong>. Ces livres abordent diverses questions sociales et sanitaires, telles que la lutte contre la stigmatisation li\u00e9e \u00e0 l&#8217;infertilit\u00e9, le soutien \u00e0 l&#8217;\u00e9ducation des filles, la lutte contre la violence sexiste, la sensibilisation sur le diab\u00e8te et l&#8217;hypertension. Les livres de contes seront mis \u00e0 disposition en langue fran\u00e7aise, et ils seront distribu\u00e9s \u00e0 des milliers d&#8217;exemplaires aux \u00e9coliers.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em><u>R\u00e9sum\u00e9 des initiatives et de l\u2019impact de la Fondation Merck :<\/u><\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fondation Merck transforme le paysage des soins aux patients et \u00e9crit l&#8217;histoire avec ses partenaires en Afrique, en Asie et au-del\u00e0, \u00e0 travers :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Plus de 2400 Bourses offertes par la Fondation Merck pour les m\u00e9decins de 52 pays dans 44 sp\u00e9cialit\u00e9s m\u00e9dicales critiques et mal desservies.\u00a0<\/strong><\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">La Fondation Merck cr\u00e9e \u00e9galement un changement de culture et brise le silence sur un large \u00e9ventail de probl\u00e8mes sociaux et sanitaires en Afrique et dans les communaut\u00e9s mal desservies gr\u00e2ce \u00e0 :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Plus de\u00a0<strong>3700 Journalistes<\/strong>\u00a0de plus de 35 pays form\u00e9s pour mieux sensibiliser sur les diff\u00e9rents probl\u00e8mes sociaux et sanitaires.<\/li>\n\n\n\n<li><strong>8 Prix<\/strong>\u00a0Diff\u00e9rents lanc\u00e9s chaque ann\u00e9e pour la meilleure couverture m\u00e9diatique, les cr\u00e9ateurs de mode, les films et les chansons.<\/li>\n\n\n\n<li>Environ\u00a0<strong>30 chansons<\/strong>\u00a0pour aborder les probl\u00e8mes sanitaires et sociaux par des chanteurs locaux \u00e0 travers l&#8217;Afrique.<\/li>\n\n\n\n<li><strong>9 livres de contes<\/strong>\u00a0pour enfants en trois langues &#8211; anglais, fran\u00e7ais et portugais.<\/li>\n\n\n\n<li><strong>6 Films d&#8217;Animation<\/strong>\u00a0de Sensibilisation en cinq langues : Anglais, Fran\u00e7ais, Portugais, Espagnol et Swahili pour sensibiliser sur la pr\u00e9vention et le d\u00e9pistage pr\u00e9coce du diab\u00e8te et de l&#8217;hypertension et soutenir l&#8217;\u00e9ducation des filles.<\/li>\n\n\n\n<li><strong>Programme T\u00e9l\u00e9vis\u00e9 Panafricain<\/strong>\u00a0\u00ab Notre Afrique par la Fondation Merck \u00bb abordant les probl\u00e8mes sociaux et sanitaires en Afrique \u00e0 travers la communaut\u00e9 \u00ab Mode et L\u2019Art avec un But \u00bb.<\/li>\n\n\n\n<li><strong>Plus de 1040 bourses<\/strong>\u00a0accord\u00e9es \u00e0 des \u00e9coli\u00e8res africaines brillantes mais d\u00e9favoris\u00e9es pour leur permettre de terminer leurs \u00e9tudes.<\/li>\n\n\n\n<li><strong>15 cha\u00eenes<\/strong>\u00a0de r\u00e9seaux sociaux avec plus de 8.5 millions de d&#8217;abonn\u00e9s.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 propos de la Fondation Merck :&nbsp;<\/strong><br>La Fondation Merck, cr\u00e9\u00e9e en 2017, est la branche philanthropique de Merck KGaA Allemagne, vise \u00e0 am\u00e9liorer la sant\u00e9 et le bien-\u00eatre des populations et \u00e0 faire progresser leur vie gr\u00e2ce \u00e0 la science et \u00e0 la technologie. Nos efforts sont principalement ax\u00e9s sur l&#8217;am\u00e9lioration de l&#8217;acc\u00e8s \u00e0 des solutions de soins de sant\u00e9 de qualit\u00e9 et \u00e9quitables dans les communaut\u00e9s mal desservies, \u00e0 renforcer les capacit\u00e9s de recherche sur les soins de sant\u00e9 et la recherche scientifique, l&#8217;autonomisation des filles \u00e0 travers l&#8217;\u00e9ducation et l&#8217;autonomisation des personnes en STEM (Science, Technologie, Ing\u00e9nierie et Math\u00e9matiques) avec un accent particulier sur les femmes et les jeunes. Tous les communiqu\u00e9s de presse de la Fondation Merck sont distribu\u00e9s par e-mail en m\u00eame temps qu&#8217;ils deviennent disponibles sur le site Web de la Fondation Merck. Veuillez visiter&nbsp;<a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/r.news.africa-wire.com\/mk\/cl\/f\/sh\/WCPzyXJTZ83VQDJhMVwwpVyvUlj9mmcF\/7iX0b1yTcrY3\">www.Merck-Foundation.com<\/a>&nbsp;pour en savoir plus. Pour en savoir plus, contactez nos r\u00e9seaux sociaux de la Fondation Merck : Facebook&nbsp;(<a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/r.news.africa-wire.com\/mk\/cl\/f\/sh\/WCPzyXJTZ6vPisupShD7Lqv71q5bIC1b\/9JRBpn25fmZj\">https:\/\/apo-opa.co\/43onuWi<\/a>),&nbsp;X&nbsp;(<a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/r.news.africa-wire.com\/mk\/cl\/f\/sh\/WCPzyXJTZ73Cmv85omgn7b4uAcyiXtdj\/Uo1YrlrT1T3S\">https:\/\/apo-opa.co\/47DQ34w<\/a>),&nbsp;Instagram&nbsp;(<a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/r.news.africa-wire.com\/mk\/cl\/f\/sh\/WCPzyXJTZ7AzqxLMAsAStLEhJPrpnbFr\/JLL0DxfENyRu\">https:\/\/apo-opa.co\/4paIWqc<\/a>),&nbsp;YouTube&nbsp;(<a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/r.news.africa-wire.com\/mk\/cl\/f\/sh\/WCPzyXJTZ7ImuzYcWxe8f5OUSCkx3Irz\/gWZoMKuk5P4o\">https:\/\/apo-opa.co\/48ccnlS<\/a>), Threads (<a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/r.news.africa-wire.com\/mk\/cl\/f\/sh\/WCPzyXJTZ7QZz1lst37oQpYHaze4J0U7\/PU88Hksmxqz8\">https:\/\/apo-opa.co\/43onvtk<\/a>) et Flickr&nbsp;(<a rel=\"noreferrer noopener\" target=\"_blank\" href=\"https:\/\/r.news.africa-wire.com\/mk\/cl\/f\/sh\/WCPzyXJTZ7YN33z9F8bUCZi4jmXBYi6F\/GFA6_qJvSwjg\">https:\/\/apo-opa.co\/4r1JsIQ<\/a>).&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Fondation Merck se consacre \u00e0 l&#8217;am\u00e9lioration des r\u00e9sultats sociaux et sanitaires pour les communaut\u00e9s dans le besoin. Bien qu&#8217;elle collabore avec divers partenaires, y compris des gouvernements, pour atteindre ses objectifs humanitaires, la fondation reste strictement neutre sur le plan politique. Elle ne s&#8217;engage pas et ne soutient pas d&#8217;activit\u00e9s, d&#8217;\u00e9lections ou de r\u00e9gimes politiques, se focalise uniquement sur sa mission d&#8217;\u00e9lever l&#8217;humanit\u00e9 et d&#8217;am\u00e9liorer le bien-\u00eatre tout en maintenant une position strictement apolitique dans toutes ses activit\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SOURCE<\/strong><br>Merck Foundation<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avec la Premi\u00e8re Dame du S\u00e9n\u00e9gal, la Fondation Merck a fourni 29 bourses pour les m\u00e9decins locaux au S\u00e9n\u00e9gal dans de nombreuses sp\u00e9cialit\u00e9s critiques et mal desservies. La Fondation Merck ,\u00a0branche philanthropique de Merck KGaA Allemagne, a r\u00e9cemment organis\u00e9 la\u00a012\u00e8me \u00e9dition\u00a0de sa conf\u00e9rence annuelle, \u00ab Merck Foundation Africa Asia Luminary<\/p>\n","protected":false},"author":3,"featured_media":9946,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[51],"tags":[],"class_list":["post-9945","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diplomatie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-300x200.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-768x512.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-1024x683.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-1536x1024.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-2048x1365.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-1400x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Avec la Premi\u00e8re Dame du S\u00e9n\u00e9gal, la Fondation Merck a fourni 29 bourses pour les m\u00e9decins locaux au S\u00e9n\u00e9gal dans de nombreuses sp\u00e9cialit\u00e9s critiques et mal desservies. La Fondation Merck ,\u00a0branche philanthropique de Merck KGaA Allemagne, a r\u00e9cemment organis\u00e9 la\u00a012\u00e8me \u00e9dition\u00a0de sa conf\u00e9rence annuelle, \u00ab Merck Foundation Africa Asia Luminary","magazineBlocksPostCategories":["DIPLOMATIE"],"magazineBlocksPostViewCount":400,"magazineBlocksPostReadTime":10,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-scaled.jpg",2560,1707,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-300x200.jpg",300,200,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-51\">DIPLOMATIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CEO de la Fondation Merck rencontre la Premi\u00e8re Dame du S\u00e9n\u00e9gal et 6 Premi\u00e8res Dames Africaines lors de la 12\u00e8me \u00c9dition de la conf\u00e9rence Merck Foundation Africa Asia Luminary 2025 en Gambie - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CEO de la Fondation Merck rencontre la Premi\u00e8re Dame du S\u00e9n\u00e9gal et 6 Premi\u00e8res Dames Africaines lors de la 12\u00e8me \u00c9dition de la conf\u00e9rence Merck Foundation Africa Asia Luminary 2025 en Gambie - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Avec la Premi\u00e8re Dame du S\u00e9n\u00e9gal, la Fondation Merck a fourni 29 bourses pour les m\u00e9decins locaux au S\u00e9n\u00e9gal dans de nombreuses sp\u00e9cialit\u00e9s critiques et mal desservies. La Fondation Merck ,\u00a0branche philanthropique de Merck KGaA Allemagne, a r\u00e9cemment organis\u00e9 la\u00a012\u00e8me \u00e9dition\u00a0de sa conf\u00e9rence annuelle, \u00ab Merck Foundation Africa Asia Luminary\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-13T08:35:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-13T08:35:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"CEO de la Fondation Merck rencontre la Premi\u00e8re Dame du S\u00e9n\u00e9gal et 6 Premi\u00e8res Dames Africaines lors de la 12\u00e8me \u00c9dition de la conf\u00e9rence Merck Foundation Africa Asia Luminary 2025 en Gambie\",\"datePublished\":\"2025-11-13T08:35:11+00:00\",\"dateModified\":\"2025-11-13T08:35:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/\"},\"wordCount\":1926,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-scaled.jpg\",\"articleSection\":[\"DIPLOMATIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/\",\"name\":\"CEO de la Fondation Merck rencontre la Premi\u00e8re Dame du S\u00e9n\u00e9gal et 6 Premi\u00e8res Dames Africaines lors de la 12\u00e8me \u00c9dition de la conf\u00e9rence Merck Foundation Africa Asia Luminary 2025 en Gambie - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-scaled.jpg\",\"datePublished\":\"2025-11-13T08:35:11+00:00\",\"dateModified\":\"2025-11-13T08:35:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-scaled.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CEO de la Fondation Merck rencontre la Premi\u00e8re Dame du S\u00e9n\u00e9gal et 6 Premi\u00e8res Dames Africaines lors de la 12\u00e8me \u00c9dition de la conf\u00e9rence Merck Foundation Africa Asia Luminary 2025 en Gambie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CEO de la Fondation Merck rencontre la Premi\u00e8re Dame du S\u00e9n\u00e9gal et 6 Premi\u00e8res Dames Africaines lors de la 12\u00e8me \u00c9dition de la conf\u00e9rence Merck Foundation Africa Asia Luminary 2025 en Gambie - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/","og_locale":"fr_FR","og_type":"article","og_title":"CEO de la Fondation Merck rencontre la Premi\u00e8re Dame du S\u00e9n\u00e9gal et 6 Premi\u00e8res Dames Africaines lors de la 12\u00e8me \u00c9dition de la conf\u00e9rence Merck Foundation Africa Asia Luminary 2025 en Gambie - Cooperation Internationale","og_description":"Avec la Premi\u00e8re Dame du S\u00e9n\u00e9gal, la Fondation Merck a fourni 29 bourses pour les m\u00e9decins locaux au S\u00e9n\u00e9gal dans de nombreuses sp\u00e9cialit\u00e9s critiques et mal desservies. La Fondation Merck ,\u00a0branche philanthropique de Merck KGaA Allemagne, a r\u00e9cemment organis\u00e9 la\u00a012\u00e8me \u00e9dition\u00a0de sa conf\u00e9rence annuelle, \u00ab Merck Foundation Africa Asia Luminary","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-11-13T08:35:11+00:00","article_modified_time":"2025-11-13T08:35:12+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-scaled.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"CEO de la Fondation Merck rencontre la Premi\u00e8re Dame du S\u00e9n\u00e9gal et 6 Premi\u00e8res Dames Africaines lors de la 12\u00e8me \u00c9dition de la conf\u00e9rence Merck Foundation Africa Asia Luminary 2025 en Gambie","datePublished":"2025-11-13T08:35:11+00:00","dateModified":"2025-11-13T08:35:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/"},"wordCount":1926,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-scaled.jpg","articleSection":["DIPLOMATIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/","name":"CEO de la Fondation Merck rencontre la Premi\u00e8re Dame du S\u00e9n\u00e9gal et 6 Premi\u00e8res Dames Africaines lors de la 12\u00e8me \u00c9dition de la conf\u00e9rence Merck Foundation Africa Asia Luminary 2025 en Gambie - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-scaled.jpg","datePublished":"2025-11-13T08:35:11+00:00","dateModified":"2025-11-13T08:35:12+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-scaled.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/13\/ceo-de-la-fondation-merck-rencontre-la-premiere-dame-du-senegal-et-6-premieres-dames-africaines-lors-de-la-12eme-edition-de-la-conference-merck-foundation-africa-asia-luminary-2025-en-gambie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"CEO de la Fondation Merck rencontre la Premi\u00e8re Dame du S\u00e9n\u00e9gal et 6 Premi\u00e8res Dames Africaines lors de la 12\u00e8me \u00c9dition de la conf\u00e9rence Merck Foundation Africa Asia Luminary 2025 en Gambie"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/2a5d947b502d24c-scaled.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/9945","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=9945"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/9945\/revisions"}],"predecessor-version":[{"id":9947,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/9945\/revisions\/9947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/9946"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=9945"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=9945"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=9945"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}