{"id":9868,"date":"2025-11-09T18:35:44","date_gmt":"2025-11-09T18:35:44","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=9868"},"modified":"2025-11-09T18:39:09","modified_gmt":"2025-11-09T18:39:09","slug":"afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/","title":{"rendered":"Afreximbank accorde une facilit\u00e9 de financement de 36 millions de dollars US \u00e0 la soci\u00e9t\u00e9 \u00e9gyptienne SAMCO pour la construction d&#8217;un projet de stade en Ouganda"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong><em>Le projet contribuera aussi \u00e0 consolider la position de SAMCO en tant qu&#8217;entrepreneur africain de premier plan, capable d&#8217;ex\u00e9cuter des projets \u00e0 grande \u00e9chelle soutenus par les gouvernements \u00e0 travers le continent<\/em><\/strong>. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0La Banque Africaine d&#8217;Import-Export (Afreximbank)  a accord\u00e9 une facilit\u00e9 de financement de 36 millions de dollars US \u00e0 la SAMCO, la soci\u00e9t\u00e9 nationale de construction d&#8217;\u00c9gypte pour la construction du stade olympique Akii Bua en Ouganda. Le stade olympique Akii Bua, situ\u00e9 \u00e0 Lira, en Ouganda, devrait accueillir certains des matchs de la Coupe d&#8217;Afrique des Nations (AFCON) 2027 que l&#8217;Ouganda co-organise avec ses voisins d&#8217;Afrique de l&#8217;Est, le Kenya et la Tanzanie, dans le cadre d&#8217;une candidature conjointe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette facilit\u00e9 de 36,4 millions de dollars US, accord\u00e9e dans le cadre du programme Ing\u00e9nierie, Approvisionnement et Construction (EPC) d&#8217;Afreximbank, aide les entreprises EPC africaines \u00e0 soumissionner pour des contrats de grande envergure dans les pays africains. Elle devrait permettre de financer et de soutenir SAMCO dans la conception, la construction et le d\u00e9veloppement du projet de stade, ainsi que dans l&#8217;acquisition des composants essentiels n\u00e9cessaires \u00e0 la bonne r\u00e9alisation du projet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mme Kanayo Awani, Vice-pr\u00e9sident ex\u00e9cutive d&#8217;Afreximbank, en charge du commerce intra-africain et du d\u00e9veloppement des exportations,<\/strong>\u00a0a sign\u00e9 l&#8217;accord de facilit\u00e9 au nom d&#8217;Afreximbank lors d&#8217;une c\u00e9r\u00e9monie qui s&#8217;est tenue au Caire le 29 octobre ; tandis que l&#8217;ing\u00e9nieur Sameh Soliman, Pr\u00e9sident de SAMCO, a paraph\u00e9 le document au nom de son entreprise. Selon\u00a0<strong>Mme Awani<\/strong>, cet accord refl\u00e8te l&#8217;engagement profond d&#8217;Afreximbank \u00e0 renforcer les capacit\u00e9s locales dans la r\u00e9alisation de projets d&#8217;infrastructures complexes et \u00e0 grande \u00e9chelle.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Nous sommes ravis de soutenir une soci\u00e9t\u00e9 africaine EPC dans le cadre de l&#8217;initiative EPC d&#8217;Afreximbank, et de financer la construction d&#8217;un stade ultramoderne, align\u00e9 davantage sur notre strat\u00e9gie cr\u00e9ative \/ sportive dans l&#8217;un de nos pays membres (Ouganda). \u00c0 travers cette initiative, nous visons \u00e0 promouvoir une croissance \u00e9conomique durable, \u00e0 am\u00e9liorer les infrastructures r\u00e9gionales et \u00e0 faciliter l&#8217;accueil d&#8217;\u00e9v\u00e9nements sportifs approuv\u00e9s par la CAF et la FIFA qui contribueront au progr\u00e8s social et \u00e9conomique de l&#8217;Ouganda\u00a0\u00bb, a poursuivi Mme Awani.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"> Pour sa part, l&#8217;<strong>ing\u00e9nieur Sameh Soliman, Pr\u00e9sident de SAMCO<\/strong>, a d\u00e9clar\u00e9\u00a0: \u00ab\u00a0Nous nous f\u00e9licitons du partenariat et du soutien d&#8217;Afreximbank dans ce projet historique. Cette collaboration renforce notre engagement strat\u00e9gique \u00e0 \u00e9tendre notre pr\u00e9sence \u00e0 travers l&#8217;Afrique et \u00e0 renforcer notre r\u00f4le dans la fourniture de solutions d&#8217;infrastructure \u00e0 fort impact. Nous nous r\u00e9jouissons \u00e0 la perspective d&#8217;une relation \u00e0 long terme et mutuellement b\u00e9n\u00e9fique avec la Banque, qui stimulera la croissance et le d\u00e9veloppement durable sur l&#8217;ensemble du continent \u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le d\u00e9veloppement du stade olympique Akii Bua devrait grandement contribuer \u00e0 promouvoir le sport en Ouganda ainsi quel&#8217;int\u00e9gration r\u00e9gionale et le tourisme en Afrique de l&#8217;Est, tout en soutenant le d\u00e9veloppement des infrastructures. Il renforcera \u00e9galement le programme du gouvernement en mati\u00e8re de sport et d&#8217;infrastructure, en am\u00e9liorant la capacit\u00e9 du pays d&#8217;accueillir des \u00e9v\u00e9nements approuv\u00e9s par la CAF et la FIFA et en contribuant \u00e0 la fiert\u00e9 nationale, \u00e0 l&#8217;engagement des jeunes et \u00e0 la diversification \u00e9conomique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le projet contribuera aussi \u00e0 consolider la position de SAMCO en tant qu&#8217;entrepreneur africain de premier plan, capable d&#8217;ex\u00e9cuter des projets \u00e0 grande \u00e9chelle soutenus par les gouvernements \u00e0 travers le continent. La Facilit\u00e9 de financement aide SAMCO \u00e0 \u00e9tendre ses activit\u00e9s \u00e0 travers l&#8217;Afrique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En outre, le projet devrait catalyser la croissance \u00e9conomique locale en g\u00e9n\u00e9rant des opportunit\u00e9s d&#8217;emploi pendant les phases de construction et d&#8217;exploitation, en stimulant les cha\u00eenes d&#8217;approvisionnement locales et en attirant des \u00e9v\u00e9nements internationaux qui renforceront la visibilit\u00e9 mondiale de l&#8217;Ouganda.La Coupe d&#8217;Afrique des Nations 2027 marquera le retour de l&#8217;organisation du tournoi continental en Afrique de l&#8217;Est depuis 1976.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>L\u00e9gende Photo: De gauche \u00e0 droite : l\u2019ing\u00e9nieur Sameh Soliman, pr\u00e9sident de SAMCO, et Mme Kanayo Awani, vice-pr\u00e9sidente ex\u00e9cutive d\u2019Afreximbank, charg\u00e9e du commerce intra-africain et du d\u00e9veloppement des exportations, apr\u00e8s la signature de l\u2019accord de financement pour la construction du stade olympique d\u2019Akii Bua (Ouganda)<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00c0 propos d&#8217;Afreximbank\u00a0:<\/strong><br>La Banque Africaine d&#8217;Import-Export (Afreximbank) est une institution financi\u00e8re multilat\u00e9rale panafricaine d\u00e9di\u00e9e au financement et \u00e0 la promotion du commerce intra et extra-africain. Depuis 30 ans, Afreximbank d\u00e9ploie des structures innovantes pour fournir des solutions de financement qui facilitent la transformation de la structure du commerce africain et acc\u00e9l\u00e8rent l&#8217;industrialisation et le commerce intrar\u00e9gional, soutenant ainsi l&#8217;expansion \u00e9conomique en Afrique. Fervente d\u00e9fenseur de l&#8217;Accord sur la Zone de Libre-\u00c9change Continentale Africaine (ZLECAf), Afreximbank a lanc\u00e9 les le Syst\u00e8me panafricain de paiement et de r\u00e8glement (PAPSS) qui a \u00e9t\u00e9 adopt\u00e9 par l&#8217;Union africaine (UA) comme la plateforme de paiement et de r\u00e8glement devant appuyer la mise en \u0153uvre de la ZLECAf. En collaboration avec le Secr\u00e9tariat de la ZLECAf et l&#8217;UA, la Banque a mis en place un Fonds d&#8217;ajustement de 10 milliards de dollars US pour aider les pays \u00e0 participer de mani\u00e8re effective \u00e0 la ZLECAf. \u00c0 la fin de d\u00e9cembre 2024, le total des actifs et des garanties de la Banque s&#8217;\u00e9levait \u00e0 environ 40,1 milliards de dollars US et les fonds de ses actionnaires s&#8217;\u00e9tablissaient \u00e0 7,2 milliards de dollars US. Afreximbank est not\u00e9e A par GCR International Scale, Baa2 par Moody&#8217;s, AAA par China Chengxin International Credit Rating Co., Ltd (CCXI), A- par Japan Credit Rating Agency (JCR) et BBB par Fitch. Au fil des ans, Afreximbank est devenue un groupe constitu\u00e9 de la Banque, de sa filiale de financement \u00e0 impact appel\u00e9e Fonds de d\u00e9veloppement des exportations en Afrique (FEDA), et de sa filiale de gestion d&#8217;assurance, AfrexInsure, (les trois entit\u00e9s forment \u00ab\u00a0le Groupe\u00a0\u00bb). La Banque a son si\u00e8ge social au Caire, en \u00c9gypte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le projet contribuera aussi \u00e0 consolider la position de SAMCO en tant qu&#8217;entrepreneur africain de premier plan, capable d&#8217;ex\u00e9cuter des projets \u00e0 grande \u00e9chelle soutenus par les gouvernements \u00e0 travers le continent. \u00a0La Banque Africaine d&#8217;Import-Export (Afreximbank) a accord\u00e9 une facilit\u00e9 de financement de 36 millions de dollars US \u00e0<\/p>\n","protected":false},"author":3,"featured_media":9873,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[52],"tags":[],"class_list":["post-9868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited-1536x864.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited-2048x1151.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited-1400x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Le projet contribuera aussi \u00e0 consolider la position de SAMCO en tant qu&#8217;entrepreneur africain de premier plan, capable d&#8217;ex\u00e9cuter des projets \u00e0 grande \u00e9chelle soutenus par les gouvernements \u00e0 travers le continent. \u00a0La Banque Africaine d&#8217;Import-Export (Afreximbank) a accord\u00e9 une facilit\u00e9 de financement de 36 millions de dollars US \u00e0","magazineBlocksPostCategories":["ECONOMIE"],"magazineBlocksPostViewCount":492,"magazineBlocksPostReadTime":5,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited.jpg",2282,1283,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-52\">ECONOMIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Afreximbank accorde une facilit\u00e9 de financement de 36 millions de dollars US \u00e0 la soci\u00e9t\u00e9 \u00e9gyptienne SAMCO pour la construction d&#039;un projet de stade en Ouganda - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Afreximbank accorde une facilit\u00e9 de financement de 36 millions de dollars US \u00e0 la soci\u00e9t\u00e9 \u00e9gyptienne SAMCO pour la construction d&#039;un projet de stade en Ouganda - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Le projet contribuera aussi \u00e0 consolider la position de SAMCO en tant qu&#8217;entrepreneur africain de premier plan, capable d&#8217;ex\u00e9cuter des projets \u00e0 grande \u00e9chelle soutenus par les gouvernements \u00e0 travers le continent. \u00a0La Banque Africaine d&#8217;Import-Export (Afreximbank) a accord\u00e9 une facilit\u00e9 de financement de 36 millions de dollars US \u00e0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-09T18:35:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-09T18:39:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2282\" \/>\n\t<meta property=\"og:image:height\" content=\"1283\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Afreximbank accorde une facilit\u00e9 de financement de 36 millions de dollars US \u00e0 la soci\u00e9t\u00e9 \u00e9gyptienne SAMCO pour la construction d&#8217;un projet de stade en Ouganda\",\"datePublished\":\"2025-11-09T18:35:44+00:00\",\"dateModified\":\"2025-11-09T18:39:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/\"},\"wordCount\":1043,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited.jpg\",\"articleSection\":[\"ECONOMIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/\",\"name\":\"Afreximbank accorde une facilit\u00e9 de financement de 36 millions de dollars US \u00e0 la soci\u00e9t\u00e9 \u00e9gyptienne SAMCO pour la construction d'un projet de stade en Ouganda - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited.jpg\",\"datePublished\":\"2025-11-09T18:35:44+00:00\",\"dateModified\":\"2025-11-09T18:39:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited.jpg\",\"width\":2282,\"height\":1283},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Afreximbank accorde une facilit\u00e9 de financement de 36 millions de dollars US \u00e0 la soci\u00e9t\u00e9 \u00e9gyptienne SAMCO pour la construction d&#8217;un projet de stade en Ouganda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Afreximbank accorde une facilit\u00e9 de financement de 36 millions de dollars US \u00e0 la soci\u00e9t\u00e9 \u00e9gyptienne SAMCO pour la construction d'un projet de stade en Ouganda - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/","og_locale":"fr_FR","og_type":"article","og_title":"Afreximbank accorde une facilit\u00e9 de financement de 36 millions de dollars US \u00e0 la soci\u00e9t\u00e9 \u00e9gyptienne SAMCO pour la construction d'un projet de stade en Ouganda - Cooperation Internationale","og_description":"Le projet contribuera aussi \u00e0 consolider la position de SAMCO en tant qu&#8217;entrepreneur africain de premier plan, capable d&#8217;ex\u00e9cuter des projets \u00e0 grande \u00e9chelle soutenus par les gouvernements \u00e0 travers le continent. \u00a0La Banque Africaine d&#8217;Import-Export (Afreximbank) a accord\u00e9 une facilit\u00e9 de financement de 36 millions de dollars US \u00e0","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-11-09T18:35:44+00:00","article_modified_time":"2025-11-09T18:39:09+00:00","og_image":[{"width":2282,"height":1283,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Afreximbank accorde une facilit\u00e9 de financement de 36 millions de dollars US \u00e0 la soci\u00e9t\u00e9 \u00e9gyptienne SAMCO pour la construction d&#8217;un projet de stade en Ouganda","datePublished":"2025-11-09T18:35:44+00:00","dateModified":"2025-11-09T18:39:09+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/"},"wordCount":1043,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited.jpg","articleSection":["ECONOMIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/","name":"Afreximbank accorde une facilit\u00e9 de financement de 36 millions de dollars US \u00e0 la soci\u00e9t\u00e9 \u00e9gyptienne SAMCO pour la construction d'un projet de stade en Ouganda - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited.jpg","datePublished":"2025-11-09T18:35:44+00:00","dateModified":"2025-11-09T18:39:09+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited.jpg","width":2282,"height":1283},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/09\/afreximbank-accorde-une-facilite-de-financement-de-36-millions-de-dollars-us-a-la-societe-egyptienne-samco-pour-la-construction-dun-projet-de-stade-en-ouganda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Afreximbank accorde une facilit\u00e9 de financement de 36 millions de dollars US \u00e0 la soci\u00e9t\u00e9 \u00e9gyptienne SAMCO pour la construction d&#8217;un projet de stade en Ouganda"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/a7ceddbd0436ded-1-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/9868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=9868"}],"version-history":[{"count":2,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/9868\/revisions"}],"predecessor-version":[{"id":9874,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/9868\/revisions\/9874"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/9873"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=9868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=9868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=9868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}