{"id":9130,"date":"2025-10-08T09:34:54","date_gmt":"2025-10-08T09:34:54","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=9130"},"modified":"2025-10-08T09:50:23","modified_gmt":"2025-10-08T09:50:23","slug":"bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/","title":{"rendered":"BAD: Ouverture de la 3e R\u00e9union du Fonds Africain de D\u00e9veloppement \u00e0 Lusaka"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La 3e r\u00e9union du Fonds africain de d\u00e9veloppement (FAD) a d\u00e9but\u00e9 ce Mercredi 08 Octobre 2025 en Zambie, \u00e0 un moment cl\u00e9 du cycle de reconstitution des ressources. La reconstitution du FAD est vitale : elle renouvelle le financement concessionnel essentiel permettant aux pays africains \u00e0 faible revenu et en situation de fragilit\u00e9 d&#8217;investir dans les infrastructures, la r\u00e9silience climatique et les syst\u00e8mes agroalimentaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les partenaires conjuguent leurs efforts pour que le Fonds continue d&#8217;avoir un fort impact de d\u00e9veloppement en Afrique et des retomb\u00e9es partag\u00e9es \u00e0 l&#8217;\u00e9chelle mondiale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Fonds africain de d\u00e9veloppement est le guichet de financement concessionnel du Groupe de la Banque africaine de d\u00e9veloppement. Il fournit des ressources essentielles \u00e0 37 pays africains \u00e0 faible revenu et en situation de fragilit\u00e9 pour soutenir la r\u00e9silience climatique, l&#8217;int\u00e9gration r\u00e9gionale, le d\u00e9veloppement du secteur priv\u00e9 et les r\u00e9formes en mati\u00e8re de gouvernance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9union de Lusaka rassemblera les partenaires au d\u00e9veloppement, les gouvernements des pays b\u00e9n\u00e9ficiaires du FAD et les hauts responsables du Groupe de la Banque pour faire avancer les discussions sur les priorit\u00e9s et le cadre de financement de la 17<sup>e<\/sup>&nbsp;reconstitution des ressources. Les d\u00e9l\u00e9gu\u00e9s participeront \u00e9galement \u00e0 des visites de projets financ\u00e9s par le FAD en Zambie, ce qui leur permettra de se faire une id\u00e9e de leurs r\u00e9sultats et impact sur le terrain.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette r\u00e9union est le premier engagement du FAD-17 auquel participera le nouveau pr\u00e9sident du Groupe de la Banque africaine de d\u00e9veloppement, M. Sidi Ould Tah. Elle intervient \u00e0 un moment d\u00e9cisif du cycle de reconstitution des ressources, alors que les partenaires travaillent ensemble pour veiller \u00e0 ce que le Fonds continue d\u2019avoir un fort impact sur le d\u00e9veloppement \u00e0 travers l\u2019Afrique et de g\u00e9n\u00e9rer des b\u00e9n\u00e9fices partag\u00e9s \u00e0 l\u2019\u00e9chelle mondiale. La derni\u00e8re r\u00e9union et la session d\u2019annonces de contributions pour le FAD-17 se tiendront en d\u00e9cembre 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SOURCE: Banque Africaine de D\u00e9veloppement.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La 3e r\u00e9union du Fonds africain de d\u00e9veloppement (FAD) a d\u00e9but\u00e9 ce Mercredi 08 Octobre 2025 en Zambie, \u00e0 un moment cl\u00e9 du cycle de reconstitution des ressources. La reconstitution du FAD est vitale : elle renouvelle le financement concessionnel essentiel permettant aux pays africains \u00e0 faible revenu et en<\/p>\n","protected":false},"author":3,"featured_media":9133,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[52],"tags":[],"class_list":["post-9130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523-300x158.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523-768x406.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523-1024x541.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523-1280x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"La 3e r\u00e9union du Fonds africain de d\u00e9veloppement (FAD) a d\u00e9but\u00e9 ce Mercredi 08 Octobre 2025 en Zambie, \u00e0 un moment cl\u00e9 du cycle de reconstitution des ressources. La reconstitution du FAD est vitale : elle renouvelle le financement concessionnel essentiel permettant aux pays africains \u00e0 faible revenu et en","magazineBlocksPostCategories":["ECONOMIE"],"magazineBlocksPostViewCount":595,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523.jpg",1280,676,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523-300x158.jpg",300,158,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-52\">ECONOMIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BAD: Ouverture de la 3e R\u00e9union du Fonds Africain de D\u00e9veloppement \u00e0 Lusaka - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BAD: Ouverture de la 3e R\u00e9union du Fonds Africain de D\u00e9veloppement \u00e0 Lusaka - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"La 3e r\u00e9union du Fonds africain de d\u00e9veloppement (FAD) a d\u00e9but\u00e9 ce Mercredi 08 Octobre 2025 en Zambie, \u00e0 un moment cl\u00e9 du cycle de reconstitution des ressources. La reconstitution du FAD est vitale : elle renouvelle le financement concessionnel essentiel permettant aux pays africains \u00e0 faible revenu et en\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-08T09:34:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-08T09:50:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"676\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"BAD: Ouverture de la 3e R\u00e9union du Fonds Africain de D\u00e9veloppement \u00e0 Lusaka\",\"datePublished\":\"2025-10-08T09:34:54+00:00\",\"dateModified\":\"2025-10-08T09:50:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/\"},\"wordCount\":361,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523.jpg\",\"articleSection\":[\"ECONOMIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/\",\"name\":\"BAD: Ouverture de la 3e R\u00e9union du Fonds Africain de D\u00e9veloppement \u00e0 Lusaka - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523.jpg\",\"datePublished\":\"2025-10-08T09:34:54+00:00\",\"dateModified\":\"2025-10-08T09:50:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523.jpg\",\"width\":1280,\"height\":676},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BAD: Ouverture de la 3e R\u00e9union du Fonds Africain de D\u00e9veloppement \u00e0 Lusaka\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BAD: Ouverture de la 3e R\u00e9union du Fonds Africain de D\u00e9veloppement \u00e0 Lusaka - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/","og_locale":"fr_FR","og_type":"article","og_title":"BAD: Ouverture de la 3e R\u00e9union du Fonds Africain de D\u00e9veloppement \u00e0 Lusaka - Cooperation Internationale","og_description":"La 3e r\u00e9union du Fonds africain de d\u00e9veloppement (FAD) a d\u00e9but\u00e9 ce Mercredi 08 Octobre 2025 en Zambie, \u00e0 un moment cl\u00e9 du cycle de reconstitution des ressources. La reconstitution du FAD est vitale : elle renouvelle le financement concessionnel essentiel permettant aux pays africains \u00e0 faible revenu et en","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-10-08T09:34:54+00:00","article_modified_time":"2025-10-08T09:50:23+00:00","og_image":[{"width":1280,"height":676,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"BAD: Ouverture de la 3e R\u00e9union du Fonds Africain de D\u00e9veloppement \u00e0 Lusaka","datePublished":"2025-10-08T09:34:54+00:00","dateModified":"2025-10-08T09:50:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/"},"wordCount":361,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523.jpg","articleSection":["ECONOMIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/","name":"BAD: Ouverture de la 3e R\u00e9union du Fonds Africain de D\u00e9veloppement \u00e0 Lusaka - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523.jpg","datePublished":"2025-10-08T09:34:54+00:00","dateModified":"2025-10-08T09:50:23+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523.jpg","width":1280,"height":676},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/10\/08\/bad-ouverture-de-la-3e-reunion-du-fonds-africain-de-developpement-a-lusaka\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"BAD: Ouverture de la 3e R\u00e9union du Fonds Africain de D\u00e9veloppement \u00e0 Lusaka"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/10\/1001318523.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/9130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=9130"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/9130\/revisions"}],"predecessor-version":[{"id":9134,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/9130\/revisions\/9134"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/9133"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=9130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=9130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=9130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}