{"id":8465,"date":"2025-09-03T06:26:05","date_gmt":"2025-09-03T06:26:05","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=8465"},"modified":"2025-09-03T06:26:07","modified_gmt":"2025-09-03T06:26:07","slug":"le-senegal-mobilise-pour-faire-face-aux-changements-climatiques","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/","title":{"rendered":"Le S\u00e9n\u00e9gal mobilis\u00e9 pour faire face aux changements climatiques."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le Pr\u00e9sident de la R\u00e9publique.du S\u00e9n\u00e9gal Bassirou Diomaye Faye, a accord\u00e9 une audience le lundi 1er Septembre 2025 \u00e0 M. Ibrahima Cheikh Diongue, Directeur ex\u00e9cutif du Fonds de r\u00e9ponse aux pertes et dommages de la Convention-cadre des Nations Unies sur les changements climatiques (CCNUCC).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au cours de cette rencontre, les deux personnalit\u00e9s ont \u00e9chang\u00e9 sur la coop\u00e9ration entre le S\u00e9n\u00e9gal et ce Fonds, mobilis\u00e9 pour soutenir rapidement les pays les plus affect\u00e9s par les cons\u00e9quences du changement climatique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les discussions ont permis d\u2019aborder la pr\u00e9vention des inondations, la lutte contre l\u2019\u00e9rosion c\u00f4ti\u00e8re, ainsi que les enjeux de la d\u00e9sertification et de la gestion des catastrophes naturelles. Autant de d\u00e9fis qui appellent des r\u00e9ponses urgentes afin de renforcer la r\u00e9silience des communaut\u00e9s et de prot\u00e9ger durablement leurs moyens de subsistance.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les deux parties ont \u00e9galement r\u00e9affirm\u00e9 leur convergence de vues sur la n\u00e9cessit\u00e9 d\u2019une justice climatique plus \u00e9quitable : les pays les moins pollueurs sont souvent les plus durement touch\u00e9s, tandis que les plus \u00e9metteurs doivent assumer pleinement leurs responsabilit\u00e9s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>source: Pr\u00e9sidence du S\u00e9n\u00e9gal.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu&#8217;est-ce que la CCNUCC, la Convention-cadre des Nations unies sur les changements climatiques?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La CCNUCC est entr\u00e9e en vigueur le 21 mars 1994. Aujourd&#8217;hui, l\u2019adh\u00e9sion \u00e0 la Convention est quasi universelle. Les 197 pays qui l\u2019ont ratifi\u00e9e sont appel\u00e9s Parties \u00e0 la Convention.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La CCNUCC est une \u00ab Convention de Rio \u00bb, l&#8217;une des trois adopt\u00e9es lors du \u00ab Sommet de la Terre de Rio \u00bb en 1992. Ses conventions soeurs sont la Convention sur la diversit\u00e9 biologique (CDB) et la Convention sur la lutte contre la d\u00e9sertification (CLD). Les trois sont intrins\u00e8quement li\u00e9s. C&#8217;est dans ce contexte que le Groupe Mixte de Liaison a \u00e9t\u00e9 mis en place pour renforcer la coordination entre les trois Conventions de Rio, dans le but ultime de d\u00e9velopper des synergies dans leurs activit\u00e9s sur les questions d&#8217;int\u00e9r\u00eat mutuel. D\u00e9sormais, il int\u00e8gre aussi la Convention de Ramsar sur les zones humides.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pr\u00e9venir les activit\u00e9s humaines \u00ab dangereuses \u00bb pour le syst\u00e8me climatique est l&#8217;objectif ultime de la CCNUCC.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Pr\u00e9sident de la R\u00e9publique.du S\u00e9n\u00e9gal Bassirou Diomaye Faye, a accord\u00e9 une audience le lundi 1er Septembre 2025 \u00e0 M. Ibrahima Cheikh Diongue, Directeur ex\u00e9cutif du Fonds de r\u00e9ponse aux pertes et dommages de la Convention-cadre des Nations Unies sur les changements climatiques (CCNUCC). Au cours de cette rencontre, les<\/p>\n","protected":false},"author":3,"featured_media":8467,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11],"tags":[],"class_list":["post-8465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecologie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited-1536x864.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited-1400x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Le Pr\u00e9sident de la R\u00e9publique.du S\u00e9n\u00e9gal Bassirou Diomaye Faye, a accord\u00e9 une audience le lundi 1er Septembre 2025 \u00e0 M. Ibrahima Cheikh Diongue, Directeur ex\u00e9cutif du Fonds de r\u00e9ponse aux pertes et dommages de la Convention-cadre des Nations Unies sur les changements climatiques (CCNUCC). Au cours de cette rencontre, les","magazineBlocksPostCategories":["ECOLOGIE"],"magazineBlocksPostViewCount":675,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited.jpg",2048,1152,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-11\">ECOLOGIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le S\u00e9n\u00e9gal mobilis\u00e9 pour faire face aux changements climatiques. - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le S\u00e9n\u00e9gal mobilis\u00e9 pour faire face aux changements climatiques. - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Le Pr\u00e9sident de la R\u00e9publique.du S\u00e9n\u00e9gal Bassirou Diomaye Faye, a accord\u00e9 une audience le lundi 1er Septembre 2025 \u00e0 M. Ibrahima Cheikh Diongue, Directeur ex\u00e9cutif du Fonds de r\u00e9ponse aux pertes et dommages de la Convention-cadre des Nations Unies sur les changements climatiques (CCNUCC). Au cours de cette rencontre, les\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-03T06:26:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-03T06:26:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Le S\u00e9n\u00e9gal mobilis\u00e9 pour faire face aux changements climatiques.\",\"datePublished\":\"2025-09-03T06:26:05+00:00\",\"dateModified\":\"2025-09-03T06:26:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/\"},\"wordCount\":390,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited.jpg\",\"articleSection\":[\"ECOLOGIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/\",\"name\":\"Le S\u00e9n\u00e9gal mobilis\u00e9 pour faire face aux changements climatiques. - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited.jpg\",\"datePublished\":\"2025-09-03T06:26:05+00:00\",\"dateModified\":\"2025-09-03T06:26:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited.jpg\",\"width\":2048,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le S\u00e9n\u00e9gal mobilis\u00e9 pour faire face aux changements climatiques.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le S\u00e9n\u00e9gal mobilis\u00e9 pour faire face aux changements climatiques. - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/","og_locale":"fr_FR","og_type":"article","og_title":"Le S\u00e9n\u00e9gal mobilis\u00e9 pour faire face aux changements climatiques. - Cooperation Internationale","og_description":"Le Pr\u00e9sident de la R\u00e9publique.du S\u00e9n\u00e9gal Bassirou Diomaye Faye, a accord\u00e9 une audience le lundi 1er Septembre 2025 \u00e0 M. Ibrahima Cheikh Diongue, Directeur ex\u00e9cutif du Fonds de r\u00e9ponse aux pertes et dommages de la Convention-cadre des Nations Unies sur les changements climatiques (CCNUCC). Au cours de cette rencontre, les","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-09-03T06:26:05+00:00","article_modified_time":"2025-09-03T06:26:07+00:00","og_image":[{"width":2048,"height":1152,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Le S\u00e9n\u00e9gal mobilis\u00e9 pour faire face aux changements climatiques.","datePublished":"2025-09-03T06:26:05+00:00","dateModified":"2025-09-03T06:26:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/"},"wordCount":390,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited.jpg","articleSection":["ECOLOGIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/","name":"Le S\u00e9n\u00e9gal mobilis\u00e9 pour faire face aux changements climatiques. - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited.jpg","datePublished":"2025-09-03T06:26:05+00:00","dateModified":"2025-09-03T06:26:07+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited.jpg","width":2048,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/09\/03\/le-senegal-mobilise-pour-faire-face-aux-changements-climatiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Le S\u00e9n\u00e9gal mobilis\u00e9 pour faire face aux changements climatiques."}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/09\/1001171791-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/8465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=8465"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/8465\/revisions"}],"predecessor-version":[{"id":8468,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/8465\/revisions\/8468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/8467"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=8465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=8465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=8465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}