{"id":8242,"date":"2025-08-13T12:18:12","date_gmt":"2025-08-13T12:18:12","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=8242"},"modified":"2025-08-13T12:18:14","modified_gmt":"2025-08-13T12:18:14","slug":"rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/","title":{"rendered":"RCA- C\u00f4te d&#8217;Ivoire : Bangui s&#8217;inspire d&#8217;Abidjan en mati\u00e8re de Bonne Gouvernance."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le pr\u00e9sident de la Haute Autorit\u00e9 charg\u00e9e de la Bonne gouvernance (HABG) de la R\u00e9publique centrafricaine, Guy-Eug\u00e8ne Demba, est arriv\u00e9 \u00e0 Abidjan, en C\u00f4te d&#8217;Ivoire, accompagn\u00e9 d&#8217;une forte d\u00e9l\u00e9gation, pour une mission d&#8217;impr\u00e9gnation qui se d\u00e9roule du 12 au 15 ao\u00fbt 2025. L&#8217;objectif de cette visite est de s&#8217;inspirer des pratiques de la Haute Autorit\u00e9 pour la Bonne gouvernance (HABG) de C\u00f4te d&#8217;Ivoire, notamment en mati\u00e8re de d\u00e9claration de patrimoine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lors d&#8217;une rencontre, ce mardi au si\u00e8ge de la HABG de C\u00f4te d&#8217;Ivoire, Guy-Eug\u00e8ne Demba a partag\u00e9 \u00e0 son homologue ivoirien, Zoro Epiphane Ballo, sa volont\u00e9 de renforcer le syst\u00e8me de d\u00e9claration de patrimoine dans son pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Nous sommes venus nous inspirer des bonnes pratiques de la Haute Autorit\u00e9 pour la Bonne Gouvernance de C\u00f4te d&#8217;Ivoire, notamment sur le syst\u00e8me de d\u00e9claration de patrimoine, afin de l&#8217;impl\u00e9menter dans notre pays \u00bb a-t-il d\u00e9clar\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette mission vise \u00e0 permettre \u00e0 la d\u00e9l\u00e9gation centrafricaine une immersion dans le fonctionnement pratique et op\u00e9rationnel de la HABG ivoirienne, reconnue pour son expertise dans la pr\u00e9vention et la lutte contre la corruption.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au programme de cette mission, des sessions de formation intensives, des ateliers pratiques et des \u00e9changes d&#8217;exp\u00e9riences autour des outils innovants, du cadre juridique rigoureux et des m\u00e9canismes op\u00e9rationnels li\u00e9s \u00e0 la d\u00e9claration de patrimoine, la transparence dans la gestion publique, et la coop\u00e9ration strat\u00e9gique.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"607\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096634-edited.jpg\" alt=\"\" class=\"wp-image-8246\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096634-edited.jpg 1080w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096634-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096634-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096634-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Guy-Eug\u00e8ne Demba a salu\u00e9 la qualit\u00e9 de l&#8217;accueil et exprim\u00e9 la d\u00e9termination de son institution \u00e0 mettre en \u0153uvre dans son pays les acquis de cette immersion, notamment en vue de l&#8217;op\u00e9rationnalisation pr\u00e9vue de la d\u00e9claration de patrimoine en d\u00e9cembre 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour sa part, Zoro Epiphane Ballo a rappel\u00e9 que cette initiative illustre l&#8217;engagement de la C\u00f4te d&#8217;Ivoire \u00e0 partager son expertise et \u00e0 promouvoir la gouvernance \u00e9thique \u00e0 l&#8217;\u00e9chelle r\u00e9gionale, renfor\u00e7ant ainsi les capacit\u00e9s des institutions africaines dans la lutte contre la corruption.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par cette visite, la HABG de C\u00f4te d&#8217;Ivoire confirme son r\u00f4le strat\u00e9gique comme un centre d&#8217;expertise et de partage des meilleures pratiques, au service d&#8217;une Afrique plus transparente, int\u00e8gre et responsable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Source : Gouvernement de C\u00f4te d&#8217;Ivoire.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le pr\u00e9sident de la Haute Autorit\u00e9 charg\u00e9e de la Bonne gouvernance (HABG) de la R\u00e9publique centrafricaine, Guy-Eug\u00e8ne Demba, est arriv\u00e9 \u00e0 Abidjan, en C\u00f4te d&#8217;Ivoire, accompagn\u00e9 d&#8217;une forte d\u00e9l\u00e9gation, pour une mission d&#8217;impr\u00e9gnation qui se d\u00e9roule du 12 au 15 ao\u00fbt 2025. L&#8217;objectif de cette visite est de s&#8217;inspirer des<\/p>\n","protected":false},"author":3,"featured_media":8244,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50],"tags":[],"class_list":["post-8242","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cooperation"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited-1080x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Le pr\u00e9sident de la Haute Autorit\u00e9 charg\u00e9e de la Bonne gouvernance (HABG) de la R\u00e9publique centrafricaine, Guy-Eug\u00e8ne Demba, est arriv\u00e9 \u00e0 Abidjan, en C\u00f4te d&#8217;Ivoire, accompagn\u00e9 d&#8217;une forte d\u00e9l\u00e9gation, pour une mission d&#8217;impr\u00e9gnation qui se d\u00e9roule du 12 au 15 ao\u00fbt 2025. L&#8217;objectif de cette visite est de s&#8217;inspirer des","magazineBlocksPostCategories":["COOPERATION"],"magazineBlocksPostViewCount":829,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited.jpg",1080,607,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-50\">COOPERATION<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RCA- C\u00f4te d&#039;Ivoire : Bangui s&#039;inspire d&#039;Abidjan en mati\u00e8re de Bonne Gouvernance. - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RCA- C\u00f4te d&#039;Ivoire : Bangui s&#039;inspire d&#039;Abidjan en mati\u00e8re de Bonne Gouvernance. - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Le pr\u00e9sident de la Haute Autorit\u00e9 charg\u00e9e de la Bonne gouvernance (HABG) de la R\u00e9publique centrafricaine, Guy-Eug\u00e8ne Demba, est arriv\u00e9 \u00e0 Abidjan, en C\u00f4te d&#8217;Ivoire, accompagn\u00e9 d&#8217;une forte d\u00e9l\u00e9gation, pour une mission d&#8217;impr\u00e9gnation qui se d\u00e9roule du 12 au 15 ao\u00fbt 2025. L&#8217;objectif de cette visite est de s&#8217;inspirer des\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-13T12:18:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-13T12:18:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"RCA- C\u00f4te d&#8217;Ivoire : Bangui s&#8217;inspire d&#8217;Abidjan en mati\u00e8re de Bonne Gouvernance.\",\"datePublished\":\"2025-08-13T12:18:12+00:00\",\"dateModified\":\"2025-08-13T12:18:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/\"},\"wordCount\":413,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited.jpg\",\"articleSection\":[\"COOPERATION\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/\",\"name\":\"RCA- C\u00f4te d'Ivoire : Bangui s'inspire d'Abidjan en mati\u00e8re de Bonne Gouvernance. - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited.jpg\",\"datePublished\":\"2025-08-13T12:18:12+00:00\",\"dateModified\":\"2025-08-13T12:18:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited.jpg\",\"width\":1080,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RCA- C\u00f4te d&#8217;Ivoire : Bangui s&#8217;inspire d&#8217;Abidjan en mati\u00e8re de Bonne Gouvernance.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RCA- C\u00f4te d'Ivoire : Bangui s'inspire d'Abidjan en mati\u00e8re de Bonne Gouvernance. - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/","og_locale":"fr_FR","og_type":"article","og_title":"RCA- C\u00f4te d'Ivoire : Bangui s'inspire d'Abidjan en mati\u00e8re de Bonne Gouvernance. - Cooperation Internationale","og_description":"Le pr\u00e9sident de la Haute Autorit\u00e9 charg\u00e9e de la Bonne gouvernance (HABG) de la R\u00e9publique centrafricaine, Guy-Eug\u00e8ne Demba, est arriv\u00e9 \u00e0 Abidjan, en C\u00f4te d&#8217;Ivoire, accompagn\u00e9 d&#8217;une forte d\u00e9l\u00e9gation, pour une mission d&#8217;impr\u00e9gnation qui se d\u00e9roule du 12 au 15 ao\u00fbt 2025. L&#8217;objectif de cette visite est de s&#8217;inspirer des","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-08-13T12:18:12+00:00","article_modified_time":"2025-08-13T12:18:14+00:00","og_image":[{"width":1080,"height":607,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"RCA- C\u00f4te d&#8217;Ivoire : Bangui s&#8217;inspire d&#8217;Abidjan en mati\u00e8re de Bonne Gouvernance.","datePublished":"2025-08-13T12:18:12+00:00","dateModified":"2025-08-13T12:18:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/"},"wordCount":413,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited.jpg","articleSection":["COOPERATION"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/","name":"RCA- C\u00f4te d'Ivoire : Bangui s'inspire d'Abidjan en mati\u00e8re de Bonne Gouvernance. - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited.jpg","datePublished":"2025-08-13T12:18:12+00:00","dateModified":"2025-08-13T12:18:14+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited.jpg","width":1080,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/13\/rca-cote-divoire-bangui-sinspire-dabidjan-en-matiere-de-bonne-gouvernance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"RCA- C\u00f4te d&#8217;Ivoire : Bangui s&#8217;inspire d&#8217;Abidjan en mati\u00e8re de Bonne Gouvernance."}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001096633-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/8242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=8242"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/8242\/revisions"}],"predecessor-version":[{"id":8247,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/8242\/revisions\/8247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/8244"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=8242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=8242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=8242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}