{"id":8070,"date":"2025-08-04T06:48:56","date_gmt":"2025-08-04T06:48:56","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=8070"},"modified":"2025-08-04T06:56:36","modified_gmt":"2025-08-04T06:56:36","slug":"energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/","title":{"rendered":"Gabon\/Energie: Le Turc Aska Energy Veut Construire une Centrale \u00c9lectrique \u00e0 Gaz de 1000 MW dans la Ngouni\u00e9."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">En marge de la visite officielle de du Pr\u00e9sident gabonais Brice Clotaire OLIGUI NGUEMA, en R\u00e9publique de Turquie, un forum d\u2019affaires et d\u2019investissements s\u2019est tenu \u00e0 Istanbul le 1er ao\u00fbt 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 cette occasion, le Ministre gabonais de l\u2019Acc\u00e8s Universel \u00e0 l\u2019Eau et \u00e0 l\u2019\u00c9nergie, M.Philippe TONANGOYE a sign\u00e9 un protocole d\u2019accord majeur avec le PDG de la soci\u00e9t\u00e9 turque Aksa Energy, en pr\u00e9sence du Chef de l\u2019\u00c9tat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Objet : Financement, construction et exploitation d\u2019une centrale \u00e9lectrique \u00e0 gaz de 1 000 MW<br>Localisation : Entre Mandji Ndoulou et Fougamou (Ngouni\u00e9)<br>Objectif : Renforcer l\u2019offre \u00e9nerg\u00e9tique du Gabon, r\u00e9pondre \u00e0 la demande industrielle et domestique, contribuer \u00e0 l\u2019autonomie \u00e9nerg\u00e9tique nationale.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le projet pr\u00e9voit \u00e9galement la construction d\u2019une ligne d\u2019\u00e9vacuation d\u2019\u00e9nergie vers le r\u00e9seau national.Ce partenariat structurant marque un tournant dans la strat\u00e9gie \u00e9nerg\u00e9tique du Gabon et t\u00e9moigne de la volont\u00e9 du Gouvernement de multiplier les investissements d\u2019envergure pour un avenir durable et souverain.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"900\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068261-1-edited.jpg\" alt=\"\" class=\"wp-image-8078\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068261-1-edited.jpg 1600w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068261-1-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068261-1-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068261-1-edited-768x432.jpg 768w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068261-1-edited-1536x864.jpg 1536w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><figcaption class=\"wp-element-caption\"><strong><em>Le Pr\u00e9sident gabonais Brice Clotaire Oligui Nguema, son Ministre de l&#8217;\u00e9nergie, Philippe TONANGOYE et les Dirigeants de l&#8217;entreprise Aska le 01\/08\/2025 \u00e0 Istanbul \u00a9 Photo Gouvernement gabonais <\/em><\/strong><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"> Aksa Enerji est une entreprise turque d&#8217;envergure internationale sp\u00e9cialis\u00e9e dans la production et la vente d&#8217;\u00e9lectricit\u00e9, avec une pr\u00e9sence notable en Afrique, notamment au Congo, o\u00f9 elle est impliqu\u00e9e dans le projet de la centrale de Djeno.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Source: Gouvernement gabonais.<\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En marge de la visite officielle de du Pr\u00e9sident gabonais Brice Clotaire OLIGUI NGUEMA, en R\u00e9publique de Turquie, un forum d\u2019affaires et d\u2019investissements s\u2019est tenu \u00e0 Istanbul le 1er ao\u00fbt 2025. \u00c0 cette occasion, le Ministre gabonais de l\u2019Acc\u00e8s Universel \u00e0 l\u2019Eau et \u00e0 l\u2019\u00c9nergie, M.Philippe TONANGOYE a sign\u00e9 un<\/p>\n","protected":false},"author":3,"featured_media":8074,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50],"tags":[],"class_list":["post-8070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cooperation"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited-1536x864.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited-1400x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"En marge de la visite officielle de du Pr\u00e9sident gabonais Brice Clotaire OLIGUI NGUEMA, en R\u00e9publique de Turquie, un forum d\u2019affaires et d\u2019investissements s\u2019est tenu \u00e0 Istanbul le 1er ao\u00fbt 2025. \u00c0 cette occasion, le Ministre gabonais de l\u2019Acc\u00e8s Universel \u00e0 l\u2019Eau et \u00e0 l\u2019\u00c9nergie, M.Philippe TONANGOYE a sign\u00e9 un","magazineBlocksPostCategories":["COOPERATION"],"magazineBlocksPostViewCount":840,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited.jpg",1600,900,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-50\">COOPERATION<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gabon\/Energie: Le Turc Aska Energy Veut Construire une Centrale \u00c9lectrique \u00e0 Gaz de 1000 MW dans la Ngouni\u00e9. - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gabon\/Energie: Le Turc Aska Energy Veut Construire une Centrale \u00c9lectrique \u00e0 Gaz de 1000 MW dans la Ngouni\u00e9. - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"En marge de la visite officielle de du Pr\u00e9sident gabonais Brice Clotaire OLIGUI NGUEMA, en R\u00e9publique de Turquie, un forum d\u2019affaires et d\u2019investissements s\u2019est tenu \u00e0 Istanbul le 1er ao\u00fbt 2025. \u00c0 cette occasion, le Ministre gabonais de l\u2019Acc\u00e8s Universel \u00e0 l\u2019Eau et \u00e0 l\u2019\u00c9nergie, M.Philippe TONANGOYE a sign\u00e9 un\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-04T06:48:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-04T06:56:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Gabon\/Energie: Le Turc Aska Energy Veut Construire une Centrale \u00c9lectrique \u00e0 Gaz de 1000 MW dans la Ngouni\u00e9.\",\"datePublished\":\"2025-08-04T06:48:56+00:00\",\"dateModified\":\"2025-08-04T06:56:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/\"},\"wordCount\":261,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited.jpg\",\"articleSection\":[\"COOPERATION\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/\",\"name\":\"Gabon\/Energie: Le Turc Aska Energy Veut Construire une Centrale \u00c9lectrique \u00e0 Gaz de 1000 MW dans la Ngouni\u00e9. - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited.jpg\",\"datePublished\":\"2025-08-04T06:48:56+00:00\",\"dateModified\":\"2025-08-04T06:56:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gabon\/Energie: Le Turc Aska Energy Veut Construire une Centrale \u00c9lectrique \u00e0 Gaz de 1000 MW dans la Ngouni\u00e9.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gabon\/Energie: Le Turc Aska Energy Veut Construire une Centrale \u00c9lectrique \u00e0 Gaz de 1000 MW dans la Ngouni\u00e9. - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/","og_locale":"fr_FR","og_type":"article","og_title":"Gabon\/Energie: Le Turc Aska Energy Veut Construire une Centrale \u00c9lectrique \u00e0 Gaz de 1000 MW dans la Ngouni\u00e9. - Cooperation Internationale","og_description":"En marge de la visite officielle de du Pr\u00e9sident gabonais Brice Clotaire OLIGUI NGUEMA, en R\u00e9publique de Turquie, un forum d\u2019affaires et d\u2019investissements s\u2019est tenu \u00e0 Istanbul le 1er ao\u00fbt 2025. \u00c0 cette occasion, le Ministre gabonais de l\u2019Acc\u00e8s Universel \u00e0 l\u2019Eau et \u00e0 l\u2019\u00c9nergie, M.Philippe TONANGOYE a sign\u00e9 un","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-08-04T06:48:56+00:00","article_modified_time":"2025-08-04T06:56:36+00:00","og_image":[{"width":1600,"height":900,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Gabon\/Energie: Le Turc Aska Energy Veut Construire une Centrale \u00c9lectrique \u00e0 Gaz de 1000 MW dans la Ngouni\u00e9.","datePublished":"2025-08-04T06:48:56+00:00","dateModified":"2025-08-04T06:56:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/"},"wordCount":261,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited.jpg","articleSection":["COOPERATION"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/","name":"Gabon\/Energie: Le Turc Aska Energy Veut Construire une Centrale \u00c9lectrique \u00e0 Gaz de 1000 MW dans la Ngouni\u00e9. - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited.jpg","datePublished":"2025-08-04T06:48:56+00:00","dateModified":"2025-08-04T06:56:36+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/04\/energie-le-turc-aska-energy-veut-construire-une-centrale-electrique-a-gaz-de-1000-mw-au-gabon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Gabon\/Energie: Le Turc Aska Energy Veut Construire une Centrale \u00c9lectrique \u00e0 Gaz de 1000 MW dans la Ngouni\u00e9."}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001068260-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/8070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=8070"}],"version-history":[{"count":3,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/8070\/revisions"}],"predecessor-version":[{"id":8080,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/8070\/revisions\/8080"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/8074"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=8070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=8070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=8070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}