{"id":8057,"date":"2025-08-03T07:44:01","date_gmt":"2025-08-03T07:44:01","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=8057"},"modified":"2025-08-03T16:46:55","modified_gmt":"2025-08-03T16:46:55","slug":"beac-remise-de-diplome-a-la-41e-promotion-de-lissea","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/","title":{"rendered":"BEAC: Remise de dipl\u00f4me \u00e0 la 41e Promotion de l&#8217;ISSEA"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Une c\u00e9r\u00e9monie historique pour une g\u00e9n\u00e9ration talentueuse<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Banque des \u00c9tats de l\u2019Afrique Centrale (BEAC) a accueilli le mercredi 30 Juillet 2025, dans la salle polyvalente de l\u2019immeuble Si\u00e8ge, la c\u00e9r\u00e9monie de remise des dipl\u00f4mes  et de parrainage de la 41\u1d49 promotion de l\u2019ISSEA.Cette c\u00e9r\u00e9monie  marque l\u2019entr\u00e9e sur le march\u00e9 professionnel des&nbsp;<strong>Analystes Statisticiens et Ing\u00e9nieurs Statisticiens \u00c9conomistes<\/strong>&nbsp;de l\u2019ISSEA incarnant l\u2019excellence acad\u00e9mique et la vision strat\u00e9gique n\u00e9cessaires pour impulser le d\u00e9veloppement de l\u2019Afrique.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette \u00e9dition a \u00e9t\u00e9 marqu\u00e9e par la pr\u00e9sence du Ministre de l\u2019\u00c9conomie, de la Planification et de l\u2019Am\u00e9nagement du Territoire, Monsieur Alamine Ousmane MEY, du Gouverneur de la BEAC, Monsieur Yvon SANA BANGUI, et du Directeur g\u00e9n\u00e9ral de l\u2019ISSEA, Monsieur Marcel OPOUMBA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Parrain de cette cuv\u00e9e 2025 <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">compos\u00e9e de la 3\u1d49 promotion des Analystes Statisticiens et de la 19\u1d49 promotion des Ing\u00e9nieurs Statisticiens \u00c9conomistes \u2013 le Gouverneur de la BEAC a adress\u00e9 aux laur\u00e9ats un message fort :<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\"> Votre dipl\u00f4me atteste de votre savoir-faire. Votre carri\u00e8re, elle, sera b\u00e2tie sur votre savoir-\u00eatre. Soyez reconnaissants envers vos pays. Vos talents vous m\u00e8neront peut-\u00eatre loin, mais o\u00f9 que vous alliez, n\u2019oubliez jamais vos origines. Restez attach\u00e9s \u00e0 cette terre qui vous a vus na\u00eetre. Votre plus grand accomplissement sera toujours de contribuer, d\u2019une mani\u00e8re ou d\u2019une autre, \u00e0 son d\u00e9veloppement. \u00bb<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un partenariat strat\u00e9gique pour&nbsp;<\/strong> l&#8217;emploi <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 cette occasion, un nouveau partenariat de stage entre l\u2019ISSEA et la BEAC sera officialis\u00e9, offrant aux futurs dipl\u00f4m\u00e9s un acc\u00e8s privil\u00e9gi\u00e9 aux opportunit\u00e9s du secteur bancaire et statistique en Afrique centrale. Cette collaboration renforce l\u2019engagement des deux institutions en faveur de la formation de talents rigoureux et innovants, pr\u00eats \u00e0 relever les d\u00e9fis \u00e9conomiques du continent. &nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Une g\u00e9n\u00e9ration pr\u00eate \u00e0 transformer l\u2019Afrique<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Form\u00e9s \u00e0 la rigueur analytique et \u00e0 la strat\u00e9gie \u00e9conomique, les dipl\u00f4m\u00e9s de l\u2019ISSEA 2025 poss\u00e8dent des comp\u00e9tences essentielles pour impacter favorablement la croissance du continent. Leur int\u00e9gration sur le march\u00e9 de l\u2019emploi marque une \u00e9tape cl\u00e9 dans la professionnalisation des m\u00e9tiers de la statistique et de l\u2019\u00e9conomie.  Un moment solennel, empreint de fiert\u00e9, de transmission et d\u2019inspiration entre g\u00e9n\u00e9rations.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Source: BEAC &amp; ISSEA <\/em><\/strong><\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Une c\u00e9r\u00e9monie historique pour une g\u00e9n\u00e9ration talentueuse La Banque des \u00c9tats de l\u2019Afrique Centrale (BEAC) a accueilli le mercredi 30 Juillet 2025, dans la salle polyvalente de l\u2019immeuble Si\u00e8ge, la c\u00e9r\u00e9monie de remise des dipl\u00f4mes et de parrainage de la 41\u1d49 promotion de l\u2019ISSEA.Cette c\u00e9r\u00e9monie marque l\u2019entr\u00e9e sur le march\u00e9<\/p>\n","protected":false},"author":3,"featured_media":8060,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[52],"tags":[],"class_list":["post-8057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-economie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited-1080x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Une c\u00e9r\u00e9monie historique pour une g\u00e9n\u00e9ration talentueuse La Banque des \u00c9tats de l\u2019Afrique Centrale (BEAC) a accueilli le mercredi 30 Juillet 2025, dans la salle polyvalente de l\u2019immeuble Si\u00e8ge, la c\u00e9r\u00e9monie de remise des dipl\u00f4mes et de parrainage de la 41\u1d49 promotion de l\u2019ISSEA.Cette c\u00e9r\u00e9monie marque l\u2019entr\u00e9e sur le march\u00e9","magazineBlocksPostCategories":["ECONOMIE"],"magazineBlocksPostViewCount":988,"magazineBlocksPostReadTime":3,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited.jpg",1080,607,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-52\">ECONOMIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BEAC: Remise de dipl\u00f4me \u00e0 la 41e Promotion de l&#039;ISSEA - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BEAC: Remise de dipl\u00f4me \u00e0 la 41e Promotion de l&#039;ISSEA - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Une c\u00e9r\u00e9monie historique pour une g\u00e9n\u00e9ration talentueuse La Banque des \u00c9tats de l\u2019Afrique Centrale (BEAC) a accueilli le mercredi 30 Juillet 2025, dans la salle polyvalente de l\u2019immeuble Si\u00e8ge, la c\u00e9r\u00e9monie de remise des dipl\u00f4mes et de parrainage de la 41\u1d49 promotion de l\u2019ISSEA.Cette c\u00e9r\u00e9monie marque l\u2019entr\u00e9e sur le march\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-03T07:44:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-03T16:46:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"BEAC: Remise de dipl\u00f4me \u00e0 la 41e Promotion de l&#8217;ISSEA\",\"datePublished\":\"2025-08-03T07:44:01+00:00\",\"dateModified\":\"2025-08-03T16:46:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/\"},\"wordCount\":422,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited.jpg\",\"articleSection\":[\"ECONOMIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/\",\"name\":\"BEAC: Remise de dipl\u00f4me \u00e0 la 41e Promotion de l'ISSEA - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited.jpg\",\"datePublished\":\"2025-08-03T07:44:01+00:00\",\"dateModified\":\"2025-08-03T16:46:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited.jpg\",\"width\":1080,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BEAC: Remise de dipl\u00f4me \u00e0 la 41e Promotion de l&#8217;ISSEA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BEAC: Remise de dipl\u00f4me \u00e0 la 41e Promotion de l'ISSEA - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/","og_locale":"fr_FR","og_type":"article","og_title":"BEAC: Remise de dipl\u00f4me \u00e0 la 41e Promotion de l'ISSEA - Cooperation Internationale","og_description":"Une c\u00e9r\u00e9monie historique pour une g\u00e9n\u00e9ration talentueuse La Banque des \u00c9tats de l\u2019Afrique Centrale (BEAC) a accueilli le mercredi 30 Juillet 2025, dans la salle polyvalente de l\u2019immeuble Si\u00e8ge, la c\u00e9r\u00e9monie de remise des dipl\u00f4mes et de parrainage de la 41\u1d49 promotion de l\u2019ISSEA.Cette c\u00e9r\u00e9monie marque l\u2019entr\u00e9e sur le march\u00e9","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-08-03T07:44:01+00:00","article_modified_time":"2025-08-03T16:46:55+00:00","og_image":[{"width":1080,"height":607,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"BEAC: Remise de dipl\u00f4me \u00e0 la 41e Promotion de l&#8217;ISSEA","datePublished":"2025-08-03T07:44:01+00:00","dateModified":"2025-08-03T16:46:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/"},"wordCount":422,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited.jpg","articleSection":["ECONOMIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/","name":"BEAC: Remise de dipl\u00f4me \u00e0 la 41e Promotion de l'ISSEA - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited.jpg","datePublished":"2025-08-03T07:44:01+00:00","dateModified":"2025-08-03T16:46:55+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited.jpg","width":1080,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/08\/03\/beac-remise-de-diplome-a-la-41e-promotion-de-lissea\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"BEAC: Remise de dipl\u00f4me \u00e0 la 41e Promotion de l&#8217;ISSEA"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/08\/1001065863-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/8057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=8057"}],"version-history":[{"count":2,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/8057\/revisions"}],"predecessor-version":[{"id":8069,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/8057\/revisions\/8069"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/8060"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=8057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=8057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=8057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}