{"id":7291,"date":"2025-06-28T04:21:53","date_gmt":"2025-06-28T04:21:53","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=7291"},"modified":"2025-06-28T04:27:08","modified_gmt":"2025-06-28T04:27:08","slug":"la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/","title":{"rendered":"La Rdc et le Rwanda ont sign\u00e9 un accord de paix  aux \u00c9tats-Unis d\u2019Am\u00e9rique"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Au cours d\u2019une br\u00e8ve c\u00e9r\u00e9monie organis\u00e9e ce vendredi en milieu de journ\u00e9e, au D\u00e9partement d\u2019\u00c9tat am\u00e9ricain \u00e0 Washington (USA), la R\u00e9publique D\u00e9mocratique du Congo (RDC) et le Rwanda ont sign\u00e9 un Accord de paix.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La signature a eu lieu dans les bureaux du Secr\u00e9taire d\u2019\u00c9tat am\u00e9ricain Marco Rubio, situ\u00e9s au 7\u00e8me \u00e9tage du b\u00e2timent du d\u00e9partement d\u2019\u00c9tat.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le premier cercle de l\u2019administration Trump s\u2019est mobilis\u00e9 pour cet \u00e9v\u00e9nement. Le Conseiller principal du Pr\u00e9sident Donald Trump pour l\u2019Afrique, Massad Boulos, a assur\u00e9 la mod\u00e9ration, tandis que le patron de la diplomatie &nbsp;am\u00e9ricaine, Marco Rubio, \u00e9tait assis au milieu de deux repr\u00e9sentants de la RDC et du Rwanda.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u00f4te \u00e0 c\u00f4te, les deux signataires ont fait leur entr\u00e9e par une salve d\u2019applaudissements. Dans une atmosph\u00e8re &nbsp;tr\u00e8s d\u00e9tendue, Massad Boulos a expliqu\u00e9 le sens de cet accord. \u00ab Pour les \u00c9tats-Unis d\u2019Am\u00e9rique, il est temps de r\u00e9tablir la paix en RDC \u00bb, a-t-il d\u00e9clar\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chacun des deux ministres s\u2019est bri\u00e8vement exprim\u00e9. Premier \u00e0 prendre la parole, le ministre rwandais a remerci\u00e9 le Pr\u00e9sident Trump et rappel\u00e9 toutes les p\u00e9rip\u00e9ties ayant conduit \u00e0 cette \u00e9tape cruciale. Selon Olivier Nduhungirehe, son pays attend beaucoup de cet accord &nbsp;de paix.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"932\" height=\"524\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959217-edited.jpg\" alt=\"\" class=\"wp-image-7285\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959217-edited.jpg 932w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959217-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959217-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 932px) 100vw, 932px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pour sa part, Mme Th\u00e9r\u00e8se Kayikwamba a remerci\u00e9 les Pr\u00e9sidents Trump et F\u00e9lix Tshisekedi pour l\u2019aboutissement heureux de cet accord. La cheffe de la diplomatie congolaise a rendu hommage \u00e0 ces deux dirigeants pour leur leadership exemplaire. Elle a par la m\u00eame occasion lou\u00e9 l\u2019accompagnement de l\u2019Union africaine et du Qatar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Nous voulons une paix durable &nbsp;et r\u00e9elle pour les populations de la RDC \u00bb, a affirm\u00e9 Mme Th\u00e9r\u00e8se Kayikwamba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Intervenant \u00e0 son tour, le Secr\u00e9taire d\u2019\u00c9tat am\u00e9ricain a d\u00e9clar\u00e9 que le Pr\u00e9sident Donald Trump est un homme de paix et tient beaucoup au retour de celle-ci dans la r\u00e9gion des Grands Lacs et particuli\u00e8rement entre la RDC et le Rwanda. \u00ab Il veut poursuivre cette entreprise de pacification partout o\u00f9 il n\u2019y a pas de paix dans le monde \u00bb, a rassur\u00e9 Marco Rubio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"544\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959277-1024x544.jpg\" alt=\"\" class=\"wp-image-7288\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959277-1024x544.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959277-300x159.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959277-768x408.jpg 768w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959277.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Poign\u00e9e de main entre les ministres des Affaires \u00e9trang\u00e8res du Rwanda et de la R\u00e9publique d\u00e9mocratique du Congo apr\u00e8s la signature de l\u2019accord de paix entre les deux pays, le 27 juin 2025 \u00e0 Washington.\u00a0\u00a9 YouTube \/ U.S. Department of State (capture d\u2019\u00e9cran)<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En pr\u00e9sence de plusieurs personnalit\u00e9s am\u00e9ricaines, des chefs de la diplomatie du Qatar et du Togo, les ministres Th\u00e9r\u00e8se Kayikwamba et Olivier Nduhungirehe ont sign\u00e9 l\u2019accord de paix et partag\u00e9, pour la premi\u00e8re fois, une poign\u00e9e de main.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chaque signataire \u00e9tait accompagn\u00e9 de 4 officiels. La d\u00e9l\u00e9gation congolaise avait dans ses rangs le Directeur de cabinet adjoint du Chef de l\u2019\u00c9tat charg\u00e9 des Finances, Andr\u00e9 Wameso, l\u2019Ambassadeur itin\u00e9rant du Chef de l\u2019\u00c9tat, Patrick Luabeya, le Haut repr\u00e9sentant du Chef de l\u2019\u00c9tat &nbsp;, Sumbu &nbsp;Sita &nbsp;Mambu, et le G\u00e9n\u00e9ral-major Augustin Mamba.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 l\u2019issue de cette c\u00e9r\u00e9monie, les deux ministres ont \u00e9t\u00e9 invit\u00e9s \u00e0 la Maison blanche pour y \u00eatre re\u00e7us par le Pr\u00e9sident Donald Trump.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"973\" height=\"547\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/Screenshot_20250627-211500-edited.jpg\" alt=\"\" class=\"wp-image-7298\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/Screenshot_20250627-211500-edited.jpg 973w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/Screenshot_20250627-211500-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/Screenshot_20250627-211500-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 973px) 100vw, 973px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Source : Pr\u00e9sidence RDC<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au cours d\u2019une br\u00e8ve c\u00e9r\u00e9monie organis\u00e9e ce vendredi en milieu de journ\u00e9e, au D\u00e9partement d\u2019\u00c9tat am\u00e9ricain \u00e0 Washington (USA), la R\u00e9publique D\u00e9mocratique du Congo (RDC) et le Rwanda ont sign\u00e9 un Accord de paix. La signature a eu lieu dans les bureaux du Secr\u00e9taire d\u2019\u00c9tat am\u00e9ricain Marco Rubio, situ\u00e9s au<\/p>\n","protected":false},"author":3,"featured_media":7293,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[51],"tags":[],"class_list":["post-7291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diplomatie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited-1280x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Au cours d\u2019une br\u00e8ve c\u00e9r\u00e9monie organis\u00e9e ce vendredi en milieu de journ\u00e9e, au D\u00e9partement d\u2019\u00c9tat am\u00e9ricain \u00e0 Washington (USA), la R\u00e9publique D\u00e9mocratique du Congo (RDC) et le Rwanda ont sign\u00e9 un Accord de paix. La signature a eu lieu dans les bureaux du Secr\u00e9taire d\u2019\u00c9tat am\u00e9ricain Marco Rubio, situ\u00e9s au","magazineBlocksPostCategories":["DIPLOMATIE"],"magazineBlocksPostViewCount":971,"magazineBlocksPostReadTime":3,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited.jpg",1280,720,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-51\">DIPLOMATIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Rdc et le Rwanda ont sign\u00e9 un accord de paix aux \u00c9tats-Unis d\u2019Am\u00e9rique - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Rdc et le Rwanda ont sign\u00e9 un accord de paix aux \u00c9tats-Unis d\u2019Am\u00e9rique - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Au cours d\u2019une br\u00e8ve c\u00e9r\u00e9monie organis\u00e9e ce vendredi en milieu de journ\u00e9e, au D\u00e9partement d\u2019\u00c9tat am\u00e9ricain \u00e0 Washington (USA), la R\u00e9publique D\u00e9mocratique du Congo (RDC) et le Rwanda ont sign\u00e9 un Accord de paix. La signature a eu lieu dans les bureaux du Secr\u00e9taire d\u2019\u00c9tat am\u00e9ricain Marco Rubio, situ\u00e9s au\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-28T04:21:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-28T04:27:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"La Rdc et le Rwanda ont sign\u00e9 un accord de paix aux \u00c9tats-Unis d\u2019Am\u00e9rique\",\"datePublished\":\"2025-06-28T04:21:53+00:00\",\"dateModified\":\"2025-06-28T04:27:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/\"},\"wordCount\":587,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited.jpg\",\"articleSection\":[\"DIPLOMATIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/\",\"name\":\"La Rdc et le Rwanda ont sign\u00e9 un accord de paix aux \u00c9tats-Unis d\u2019Am\u00e9rique - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited.jpg\",\"datePublished\":\"2025-06-28T04:21:53+00:00\",\"dateModified\":\"2025-06-28T04:27:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Rdc et le Rwanda ont sign\u00e9 un accord de paix aux \u00c9tats-Unis d\u2019Am\u00e9rique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Rdc et le Rwanda ont sign\u00e9 un accord de paix aux \u00c9tats-Unis d\u2019Am\u00e9rique - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/","og_locale":"fr_FR","og_type":"article","og_title":"La Rdc et le Rwanda ont sign\u00e9 un accord de paix aux \u00c9tats-Unis d\u2019Am\u00e9rique - Cooperation Internationale","og_description":"Au cours d\u2019une br\u00e8ve c\u00e9r\u00e9monie organis\u00e9e ce vendredi en milieu de journ\u00e9e, au D\u00e9partement d\u2019\u00c9tat am\u00e9ricain \u00e0 Washington (USA), la R\u00e9publique D\u00e9mocratique du Congo (RDC) et le Rwanda ont sign\u00e9 un Accord de paix. La signature a eu lieu dans les bureaux du Secr\u00e9taire d\u2019\u00c9tat am\u00e9ricain Marco Rubio, situ\u00e9s au","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-06-28T04:21:53+00:00","article_modified_time":"2025-06-28T04:27:08+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"La Rdc et le Rwanda ont sign\u00e9 un accord de paix aux \u00c9tats-Unis d\u2019Am\u00e9rique","datePublished":"2025-06-28T04:21:53+00:00","dateModified":"2025-06-28T04:27:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/"},"wordCount":587,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited.jpg","articleSection":["DIPLOMATIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/","name":"La Rdc et le Rwanda ont sign\u00e9 un accord de paix aux \u00c9tats-Unis d\u2019Am\u00e9rique - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited.jpg","datePublished":"2025-06-28T04:21:53+00:00","dateModified":"2025-06-28T04:27:08+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/28\/la-rdc-et-le-rwanda-ont-signe-un-accord-de-paix-aux-etats-unis-damerique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"La Rdc et le Rwanda ont sign\u00e9 un accord de paix aux \u00c9tats-Unis d\u2019Am\u00e9rique"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000959930-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/7291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=7291"}],"version-history":[{"count":2,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/7291\/revisions"}],"predecessor-version":[{"id":7299,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/7291\/revisions\/7299"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/7293"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=7291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=7291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=7291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}