{"id":7118,"date":"2025-06-18T07:18:32","date_gmt":"2025-06-18T07:18:32","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=7118"},"modified":"2025-06-18T07:18:33","modified_gmt":"2025-06-18T07:18:33","slug":"vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/","title":{"rendered":"Vienne: Burkina Faso aux discussions des partenaires Arabes sur le Sahel"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> Le Burkina Faso, par la voix du ministre de l\u2019\u00c9conomie, et des Finances, Dr Aboubakar NACANABO, prend une part active \u00e0 la Table ronde des partenaires techniques et financiers arabes, organis\u00e9e par le Comit\u00e9 permanent inter-\u00c9tats de lutte contre la s\u00e9cheresse dans le Sahel (CILSS). Cette rencontre strat\u00e9gique, qui s\u2019est tenue le 16 juin 2025, dans la capitale autrichienne, vise \u00e0 renforcer la coop\u00e9ration avec les institutions arabes et \u00e0 mobiliser des financements en faveur du d\u00e9veloppement durable au Sahel et en Afrique de l\u2019Ouest.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La table ronde, qui r\u00e9unit les plus grandes institutions financi\u00e8res arabes telles que la Banque Islamique de D\u00e9veloppement (BID), la Banque Arabe pour le D\u00e9veloppement \u00c9conomique en Afrique (BADEA), ou encore les fonds souverains saoudien, qatari, kowe\u00eftien et \u00e9mirati, marque un tournant d\u00e9cisif pour les pays sah\u00e9liens dans leur qu\u00eate de r\u00e9silience et de transformation structurelle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au nom du Burkina Faso, le ministre NACANABO a port\u00e9 la vision d\u2019un d\u00e9veloppement int\u00e9gr\u00e9, fond\u00e9 sur la modernisation des syst\u00e8mes agro-pastoraux, la valorisation des cha\u00eenes de valeur, la s\u00e9curisation alimentaire et la gestion durable des ressources naturelles. Il a plaid\u00e9 pour une solidarit\u00e9 agissante, au service des priorit\u00e9s nationales et r\u00e9gionales, dans un contexte marqu\u00e9 par des d\u00e9fis climatiques et s\u00e9curitaires croissants.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019initiative s\u2019inscrit dans la dynamique du plan strat\u00e9gique 2050 du CILSS, qui place l\u2019innovation, la ma\u00eetrise de l\u2019eau et l\u2019acc\u00e8s aux march\u00e9s au c\u0153ur de la r\u00e9silience des communaut\u00e9s sah\u00e9liennes. La participation du Burkina Faso \u00e0 ce rendez-vous de haut niveau traduit sa volont\u00e9 d\u2019\u00eatre un acteur de premier plan dans la construction d\u2019un partenariat arabo-sah\u00e9lien durable et efficace.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Organis\u00e9e avec l\u2019appui de la BADEA et du Fonds de l\u2019OPEP pour le D\u00e9veloppement international, la rencontre de Vienne est un signal fort envoy\u00e9 \u00e0 la communaut\u00e9 internationale : celui d\u2019un Sahel debout, solidaire et r\u00e9solument tourn\u00e9 vers l\u2019action.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Source: \ud835\udc03\ud835\udc02\ud835\udc11\ud835\udc0f\/\ud835\udc0c\ud835\udc04\ud835\udc05 \u00a9 Photo \ud835\udc03\ud835\udc06\ud835\udc02\ud835\udc0e\ud835\udc0e\ud835\udc0f<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Burkina Faso, par la voix du ministre de l\u2019\u00c9conomie, et des Finances, Dr Aboubakar NACANABO, prend une part active \u00e0 la Table ronde des partenaires techniques et financiers arabes, organis\u00e9e par le Comit\u00e9 permanent inter-\u00c9tats de lutte contre la s\u00e9cheresse dans le Sahel (CILSS). Cette rencontre strat\u00e9gique, qui s\u2019est<\/p>\n","protected":false},"author":3,"featured_media":7120,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50],"tags":[],"class_list":["post-7118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cooperation"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited-1536x864.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited-1400x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Le Burkina Faso, par la voix du ministre de l\u2019\u00c9conomie, et des Finances, Dr Aboubakar NACANABO, prend une part active \u00e0 la Table ronde des partenaires techniques et financiers arabes, organis\u00e9e par le Comit\u00e9 permanent inter-\u00c9tats de lutte contre la s\u00e9cheresse dans le Sahel (CILSS). Cette rencontre strat\u00e9gique, qui s\u2019est","magazineBlocksPostCategories":["COOPERATION"],"magazineBlocksPostViewCount":939,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited.jpg",2000,1125,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-50\">COOPERATION<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vienne: Burkina Faso aux discussions des partenaires Arabes sur le Sahel - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vienne: Burkina Faso aux discussions des partenaires Arabes sur le Sahel - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Le Burkina Faso, par la voix du ministre de l\u2019\u00c9conomie, et des Finances, Dr Aboubakar NACANABO, prend une part active \u00e0 la Table ronde des partenaires techniques et financiers arabes, organis\u00e9e par le Comit\u00e9 permanent inter-\u00c9tats de lutte contre la s\u00e9cheresse dans le Sahel (CILSS). Cette rencontre strat\u00e9gique, qui s\u2019est\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-18T07:18:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T07:18:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1125\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Vienne: Burkina Faso aux discussions des partenaires Arabes sur le Sahel\",\"datePublished\":\"2025-06-18T07:18:32+00:00\",\"dateModified\":\"2025-06-18T07:18:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/\"},\"wordCount\":357,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited.jpg\",\"articleSection\":[\"COOPERATION\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/\",\"name\":\"Vienne: Burkina Faso aux discussions des partenaires Arabes sur le Sahel - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited.jpg\",\"datePublished\":\"2025-06-18T07:18:32+00:00\",\"dateModified\":\"2025-06-18T07:18:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited.jpg\",\"width\":2000,\"height\":1125},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vienne: Burkina Faso aux discussions des partenaires Arabes sur le Sahel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vienne: Burkina Faso aux discussions des partenaires Arabes sur le Sahel - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/","og_locale":"fr_FR","og_type":"article","og_title":"Vienne: Burkina Faso aux discussions des partenaires Arabes sur le Sahel - Cooperation Internationale","og_description":"Le Burkina Faso, par la voix du ministre de l\u2019\u00c9conomie, et des Finances, Dr Aboubakar NACANABO, prend une part active \u00e0 la Table ronde des partenaires techniques et financiers arabes, organis\u00e9e par le Comit\u00e9 permanent inter-\u00c9tats de lutte contre la s\u00e9cheresse dans le Sahel (CILSS). Cette rencontre strat\u00e9gique, qui s\u2019est","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-06-18T07:18:32+00:00","article_modified_time":"2025-06-18T07:18:33+00:00","og_image":[{"width":2000,"height":1125,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Vienne: Burkina Faso aux discussions des partenaires Arabes sur le Sahel","datePublished":"2025-06-18T07:18:32+00:00","dateModified":"2025-06-18T07:18:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/"},"wordCount":357,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited.jpg","articleSection":["COOPERATION"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/","name":"Vienne: Burkina Faso aux discussions des partenaires Arabes sur le Sahel - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited.jpg","datePublished":"2025-06-18T07:18:32+00:00","dateModified":"2025-06-18T07:18:33+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited.jpg","width":2000,"height":1125},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/18\/vienne-burkina-faso-aux-discussions-des-partenaires-arabes-sur-le-sahel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Vienne: Burkina Faso aux discussions des partenaires Arabes sur le Sahel"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000929635-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/7118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=7118"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/7118\/revisions"}],"predecessor-version":[{"id":7121,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/7118\/revisions\/7121"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/7120"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=7118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=7118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=7118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}