{"id":7011,"date":"2025-06-08T20:14:48","date_gmt":"2025-06-08T20:14:48","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=7011"},"modified":"2025-06-08T20:14:50","modified_gmt":"2025-06-08T20:14:50","slug":"la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/","title":{"rendered":"La SADC s&#8217;associe \u00e0 la Communaut\u00e9 Internationale pour relever les d\u00e9fis \u00e9mergents"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Communaut\u00e9 de d\u00e9veloppement de l&#8217;Afrique australe (SADC) a r\u00e9affirm\u00e9 son engagement envers la r\u00e9silience r\u00e9gionale et la gouvernance des risques de catastrophe lors de la Plateforme mondiale 2025 pour la r\u00e9duction des risques de catastrophe (GP2025), convoqu\u00e9e sous le th\u00e8me \u00ab Chaque jour compte, agissez pour la r\u00e9silience aujourd&#8217;hui. \u201d La r\u00e9gion de la SADC conna\u00eet des extr\u00eames climatiques, des risques transfronti\u00e8res et des fragilit\u00e9s croissantes. Le GP2025 a fourni \u00e0 la SADC une plate-forme de haut niveau pour aligner les efforts r\u00e9gionaux sur les cadres mondiaux, notamment le Cadre de Sendai pour la r\u00e9duction des risques de catastrophe (2015-2030), l&#8217;Accord de Paris et les objectifs de d\u00e9veloppement durable (ODD).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La plate-forme a \u00e9galement donn\u00e9 \u00e0 la r\u00e9gion de la SADC l&#8217;occasion de r\u00e9fl\u00e9chir et d&#8217;exprimer sa position concernant la mise en \u0153uvre du Cadre de Sendai et a permis aux \u00c9tats membres de la SADC d&#8217;\u00e9valuer les progr\u00e8s r\u00e9alis\u00e9s, d&#8217;identifier les lacunes, d&#8217;engager des dialogues strat\u00e9giques et d&#8217;obtenir un financement pour renforcer la r\u00e9duction des risques Il a \u00e9galement facilit\u00e9 l&#8217;apprentissage par les pairs de pays du monde entier dans des contextes similaires et a soulign\u00e9 l&#8217;importance d&#8217;un redressement r\u00e9silient et d&#8217;un financement durable de la r\u00e9duction<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ancr\u00e9e par la strat\u00e9gie et le plan d&#8217;action de la SADC pour la gestion des risques de catastrophe (2022-2030) et le Cadre de r\u00e9silience, la r\u00e9gion s&#8217;est jointe aux acteurs mondiaux pour explorer le financement durable, les syst\u00e8mes d&#8217;alerte rapide et l&#8217;innovation locale pour r\u00e9duire les risques de catastrophe et renforcer la r\u00e9s La plate-forme a \u00e9galement permis \u00e0 la SADC d&#8217;articuler des priorit\u00e9s communes dans le cadre du projet de position commune pour l&#8217;Afrique et de s&#8217;engager dans des \u00e9changes de pairs sur les innovations en mati\u00e8re de gouvernance des risques .<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1039\" height=\"584\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902983-edited.jpg\" alt=\"\" class=\"wp-image-7015\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902983-edited.jpg 1039w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902983-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902983-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902983-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1039px) 100vw, 1039px\" \/><figcaption class=\"wp-element-caption\"><em>M.Ignazio Cassis, Ministre Suisse des Affaires \u00c9trang\u00e8res \u00a9 Photo SADC<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">M. Ignazio Cassis, Ministre suisse des affaires \u00e9trang\u00e8res et membre du Conseil f\u00e9d\u00e9ral suisse, a soulign\u00e9 la n\u00e9cessit\u00e9 d&#8217;une approche unifi\u00e9e et ax\u00e9e sur les r\u00e9sultats de la gestion des risques de catastrophe. Il a appel\u00e9 \u00e0 l&#8217;utilisation strat\u00e9gique de la science, de la technologie, de l&#8217;innovation, de l&#8217;intelligence artificielle et de l&#8217;analyse pr\u00e9dictive, m\u00e9lang\u00e9e aux connaissances traditionnelles, pour \u00e9claire Il a soulign\u00e9 l&#8217;importance de l&#8217;appropriation nationale et locale, plaidant pour le principe de subsidiarit\u00e9 : \u00ab Penser globalement, agir localement n&#8217;est pas un slogan &#8211; c&#8217;est une exigence. \u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">M. Cassis a \u00e9galement mis en lumi\u00e8re les d\u00e9fis aggravants du changement climatique et des conflits arm\u00e9s, en insistant sur la n\u00e9cessit\u00e9 urgente d&#8217;une action d\u00e9cisive fond\u00e9e sur les principes du Cadre de Sendai.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mme Amina J. Mohammed, le Secr\u00e9taire g\u00e9n\u00e9ral adjoint des Nations Unies (ONU) a exhort\u00e9 les communaut\u00e9s internationales \u00e0 renforcer la solidarit\u00e9 mondiale face aux catastrophes de plus en plus interconnect\u00e9es et transfronti\u00e8res. Elle a insist\u00e9 sur le besoin urgent de syst\u00e8mes d&#8217;alerte pr\u00e9coce robustes et d&#8217;am\u00e9liorer la r\u00e9silien Mme Mohammed a r\u00e9affirm\u00e9 les engagements pris au titre du Cadre de Sendai, de l&#8217;Accord de Paris et des Objectifs de d\u00e9veloppement durable (ODD), soulignant que les progr\u00e8s r\u00e9alis\u00e9s dans ces programmes sont \u00e0 la tra\u00eene.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"710\" height=\"399\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902987-edited.jpg\" alt=\"\" class=\"wp-image-7017\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902987-edited.jpg 710w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902987-edited-300x169.jpg 300w\" sizes=\"auto, (max-width: 710px) 100vw, 710px\" \/><figcaption class=\"wp-element-caption\"><em>Mme Amina J.Mohammed, Secr\u00e9taire G\u00e9n\u00e9ral Adjoint des Nations-Unies <\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Citant le Rapport d&#8217;\u00e9valuation mondiale 2025 sur la r\u00e9duction des risques de catastrophe, elle a not\u00e9 que les pertes annuelles directes r\u00e9sultant des catastrophes s&#8217;\u00e9levaient \u00e0 environ 202 milliards de dollars, les pertes li\u00e9es aux \u00e9cosyst\u00e8mes \u00e9tant estim\u00e9es \u00e0 plus de 2,3 billions de dollars. En outre, elle a soulign\u00e9 la projection alarmante de l&#8217;Organisation m\u00e9t\u00e9orologique mondiale (OMM) selon laquelle les temp\u00e9ratures devraient d\u00e9passer le seuil de 1,5 \u00b0C au cours des cinq prochaines ann\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Malgr\u00e9 les difficult\u00e9s, elle a reconnu des progr\u00e8s positifs tels que la baisse mondiale des taux de mortalit\u00e9 par catastrophe et l&#8217;expansion des syst\u00e8mes d&#8217;alerte pr\u00e9coce, les deux tiers des pays ayant maintenant des strat\u00e9gies nationales de r\u00e9duction des risques de catastrophe. Elle a appel\u00e9 \u00e0 acc\u00e9l\u00e9rer la mise en \u0153uvre de syst\u00e8mes d&#8217;alerte rapide pour tous d&#8217;ici 2027, en encourageant la collaboration entre tous les secteurs de la soci\u00e9t\u00e9, y compris les gouvernements, les jeunes, le secteur priv\u00e9 et<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le GP2025 a pr\u00e9sent\u00e9 un large \u00e9ventail de r\u00e9unions de haut niveau, d&#8217;\u00e9v\u00e9nements parall\u00e8les, de sessions th\u00e9matiques, d&#8217;expositions et d&#8217;\u00e9changes de connaissances. Ces engagements ont permis aux parties prenantes de partager les meilleures pratiques, d&#8217;explorer des outils novateurs et de discuter des derni\u00e8res tendances en mati\u00e8re de r\u00e9duction des risques de catastrophe. La plate-forme a offert aux parties prenantes un espace unique pour r\u00e9affirmer leur engagement et prendre des mesures concr\u00e8tes pour acc\u00e9l\u00e9rer la mise en \u0153uvre de la DRR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le GP2025 devrait donner les r\u00e9sultats suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Bilan consolid\u00e9 sur les progr\u00e8s de la mise en \u0153uvre du Cadre de Sendai et les d\u00e9fis auxquels sont confront\u00e9s les \u00c9tats membres et les parties prenantes \u00e0 tous les niveaux pertinents, ainsi que sur les objectifs li\u00e9s aux risques de catastrophe du Programme 2030 pour le d\u00e9veloppement durable;<\/li>\n\n\n\n<li>Conform\u00e9ment \u00e0 une approche pangouvernementale, des recommandations d&#8217;actions \u00e0 l&#8217;intention des d\u00e9cideurs dans tous les secteurs, y compris dans les domaines du d\u00e9veloppement durable, des finances et de la planification \u00e9conomique, des infrastructures, des actions li\u00e9es au climat et aux \u00e9cosyst\u00e8mes, de la coop\u00e9ration internationale en mati\u00e8re de r\u00e9duction des risques de catastrophe, de pr\u00e9paration, des Les recommandations devraient tenir compte des besoins variables et pr\u00e9ciser selon les r\u00e9gions et les groupes, y compris (mais pas exclusivement) les besoins sp\u00e9cifiques des pays les moins avanc\u00e9s (PMA), des petits \u00c9tats insulaires en d\u00e9veloppement (PEID), des pays en d\u00e9veloppement sans littoral (PMA) et des pays africains et \u00e0 revenu interm\u00e9diaire (PMI) qui font face \u00e0 des d\u00e9fis sp\u00e9cifiques, en veillant \u00e0 ce que les un et aucun pays n&#8217;est laiss\u00e9 derri\u00e8re ;<\/li>\n\n\n\n<li>Sensibilisation accrue aux bonnes pratiques dans la mise en \u0153uvre du Cadre de Sendai, notamment sur l&#8217;am\u00e9lioration de la disponibilit\u00e9 et de l&#8217;acc\u00e8s aux donn\u00e9es sur les catastrophes, et le renforcement de la r\u00e9silience \u00e0 l&#8217;aide d&#8217;approches, d<\/li>\n\n\n\n<li>Un engagement politique r\u00e9affirm\u00e9 \u00e0 faire progresser les efforts acc\u00e9l\u00e9r\u00e9s pour atteindre le Cadre de Sendai.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Plusieurs chefs d&#8217;\u00c9tat, ministres, repr\u00e9sentants gouvernementaux, organisations non gouvernementales, partenaires de d\u00e9veloppement, secteur priv\u00e9, milieux universitaires et soci\u00e9t\u00e9 civile ont particip\u00e9 \u00e0 cette manifestation.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;engagement actif de la SADC dans le GP2025 souligne son leadership croissant dans la promotion d&#8217;un programme de rel\u00e8vement r\u00e9silient qui soit inclusif, ax\u00e9 sur la r\u00e9gion et ax\u00e9 sur l&#8217;avenir. Guid\u00e9e par la Strat\u00e9gie de gestion des risques de catastrophe de la SADC, le Cadre de r\u00e9silience, la Vision 2050 de la SADC et le Plan strat\u00e9gique indicatif r\u00e9gional de d\u00e9veloppement (RISDP) 2020-2030, la r\u00e9gion prend des mesures d\u00e9cisives pour renforcer la r\u00e9silience urbaine, am\u00e9liorer la gouvernance des risques et construire des syst\u00e8mes responsables de r\u00e9duction des risques de catastrophe dirig\u00e9s localement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Face aux chocs climatiques croissants, aux crises humanitaires prolong\u00e9es et \u00e0 la dynamique politique complexe, la SADC reconna\u00eet l&#8217;urgence de mettre en \u0153uvre le lien humanitaire-d\u00e9veloppement-paix. La r\u00e9silience ne peut pas \u00eatre atteinte sans rapprocher ces secteurs et en int\u00e9grant la r\u00e9duction des risques dans les processus de planification, d&#8217;investissement et<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La r\u00e9gion est pr\u00eate \u00e0 acc\u00e9l\u00e9rer la mise en \u0153uvre de syst\u00e8mes int\u00e9gr\u00e9s d&#8217;alerte pr\u00e9coce, \u00e0 investir dans une planification urbaine ax\u00e9e sur les risques et \u00e0 donner aux acteurs locaux les moyens de diriger les efforts de renforcement de la Une coop\u00e9ration r\u00e9gionale plus forte et un engagement politique soutenu sont essentiels pour garantir que le rel\u00e8vement soit non seulement possible mais transformateur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong><em>Source: Communication SADC<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Communaut\u00e9 de d\u00e9veloppement de l&#8217;Afrique australe (SADC) a r\u00e9affirm\u00e9 son engagement envers la r\u00e9silience r\u00e9gionale et la gouvernance des risques de catastrophe lors de la Plateforme mondiale 2025 pour la r\u00e9duction des risques de catastrophe (GP2025), convoqu\u00e9e sous le th\u00e8me \u00ab Chaque jour compte, agissez pour la r\u00e9silience aujourd&#8217;hui.<\/p>\n","protected":false},"author":3,"featured_media":7013,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50],"tags":[],"class_list":["post-7011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cooperation"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited-1181x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"La Communaut\u00e9 de d\u00e9veloppement de l&#8217;Afrique australe (SADC) a r\u00e9affirm\u00e9 son engagement envers la r\u00e9silience r\u00e9gionale et la gouvernance des risques de catastrophe lors de la Plateforme mondiale 2025 pour la r\u00e9duction des risques de catastrophe (GP2025), convoqu\u00e9e sous le th\u00e8me \u00ab Chaque jour compte, agissez pour la r\u00e9silience aujourd&#8217;hui.","magazineBlocksPostCategories":["COOPERATION"],"magazineBlocksPostViewCount":831,"magazineBlocksPostReadTime":7,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited.jpg",1181,664,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-50\">COOPERATION<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La SADC s&#039;associe \u00e0 la Communaut\u00e9 Internationale pour relever les d\u00e9fis \u00e9mergents - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La SADC s&#039;associe \u00e0 la Communaut\u00e9 Internationale pour relever les d\u00e9fis \u00e9mergents - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"La Communaut\u00e9 de d\u00e9veloppement de l&#8217;Afrique australe (SADC) a r\u00e9affirm\u00e9 son engagement envers la r\u00e9silience r\u00e9gionale et la gouvernance des risques de catastrophe lors de la Plateforme mondiale 2025 pour la r\u00e9duction des risques de catastrophe (GP2025), convoqu\u00e9e sous le th\u00e8me \u00ab Chaque jour compte, agissez pour la r\u00e9silience aujourd&#8217;hui.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-08T20:14:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-08T20:14:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1181\" \/>\n\t<meta property=\"og:image:height\" content=\"664\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"La SADC s&#8217;associe \u00e0 la Communaut\u00e9 Internationale pour relever les d\u00e9fis \u00e9mergents\",\"datePublished\":\"2025-06-08T20:14:48+00:00\",\"dateModified\":\"2025-06-08T20:14:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/\"},\"wordCount\":1437,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited.jpg\",\"articleSection\":[\"COOPERATION\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/\",\"name\":\"La SADC s'associe \u00e0 la Communaut\u00e9 Internationale pour relever les d\u00e9fis \u00e9mergents - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited.jpg\",\"datePublished\":\"2025-06-08T20:14:48+00:00\",\"dateModified\":\"2025-06-08T20:14:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited.jpg\",\"width\":1181,\"height\":664},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La SADC s&#8217;associe \u00e0 la Communaut\u00e9 Internationale pour relever les d\u00e9fis \u00e9mergents\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La SADC s'associe \u00e0 la Communaut\u00e9 Internationale pour relever les d\u00e9fis \u00e9mergents - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/","og_locale":"fr_FR","og_type":"article","og_title":"La SADC s'associe \u00e0 la Communaut\u00e9 Internationale pour relever les d\u00e9fis \u00e9mergents - Cooperation Internationale","og_description":"La Communaut\u00e9 de d\u00e9veloppement de l&#8217;Afrique australe (SADC) a r\u00e9affirm\u00e9 son engagement envers la r\u00e9silience r\u00e9gionale et la gouvernance des risques de catastrophe lors de la Plateforme mondiale 2025 pour la r\u00e9duction des risques de catastrophe (GP2025), convoqu\u00e9e sous le th\u00e8me \u00ab Chaque jour compte, agissez pour la r\u00e9silience aujourd&#8217;hui.","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-06-08T20:14:48+00:00","article_modified_time":"2025-06-08T20:14:50+00:00","og_image":[{"width":1181,"height":664,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"La SADC s&#8217;associe \u00e0 la Communaut\u00e9 Internationale pour relever les d\u00e9fis \u00e9mergents","datePublished":"2025-06-08T20:14:48+00:00","dateModified":"2025-06-08T20:14:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/"},"wordCount":1437,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited.jpg","articleSection":["COOPERATION"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/","name":"La SADC s'associe \u00e0 la Communaut\u00e9 Internationale pour relever les d\u00e9fis \u00e9mergents - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited.jpg","datePublished":"2025-06-08T20:14:48+00:00","dateModified":"2025-06-08T20:14:50+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited.jpg","width":1181,"height":664},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/06\/08\/la-sadc-sassocie-a-la-communaute-internationale-pour-relever-les-defis-emergents\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"La SADC s&#8217;associe \u00e0 la Communaut\u00e9 Internationale pour relever les d\u00e9fis \u00e9mergents"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/06\/1000902988-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/7011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=7011"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/7011\/revisions"}],"predecessor-version":[{"id":7018,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/7011\/revisions\/7018"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/7013"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=7011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=7011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=7011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}