{"id":6322,"date":"2025-05-06T08:51:15","date_gmt":"2025-05-06T08:51:15","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=6322"},"modified":"2025-05-06T08:51:16","modified_gmt":"2025-05-06T08:51:16","slug":"gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/","title":{"rendered":"Gabon: Le Chef de l\u2019\u00c9tat re\u00e7oit un envoy\u00e9 sp\u00e9cial du Pr\u00e9sident XI JINPING"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le Pr\u00e9sident de la R\u00e9publique,  Brice Clotaire Oligui Nguema, a re\u00e7u le lundi 05 mai en audience Monsieur Mu Hong, envoy\u00e9 sp\u00e9cial du Pr\u00e9sident de la R\u00e9publique populaire de Chine et Vice-Pr\u00e9sident du Comit\u00e9 National de la Conf\u00e9rence Consultative Politique du Peuple Chinois (CCPPC), porteur d\u2019un message personnel du Pr\u00e9sident chinois Xi Jinping, adress\u00e9 \u00e0 son homologue gabonais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette rencontre a \u00e9t\u00e9 l\u2019occasion pour l\u2019envoy\u00e9 sp\u00e9cial de transmettre les f\u00e9licitations du Pr\u00e9sident Chinois au Chef de l\u2019\u00c9tat gabonais pour son investiture qui a eu lieu le 3 mai dernier. Par ailleurs, Il a r\u00e9it\u00e9r\u00e9 la volont\u00e9 de la Chine de renforcer davantage les relations d\u2019amiti\u00e9 et de coop\u00e9ration bilat\u00e9rale entre nos deux pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Enfin, Monsieur Mu Hong a r\u00e9affirm\u00e9 l\u2019engagement de la Chine \u00e0 accompagner le Gabon, dans le domaine des infrastructures , notamment l\u2019am\u00e9nagement du S\u00e9nat, la construction de l\u2019h\u00f4tel des Affaires Etrang\u00e8res et la construction d\u2019un h\u00f4pital \u00e0 Oyem.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"607\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805653-edited.jpg\" alt=\"\" class=\"wp-image-6326\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805653-edited.jpg 1080w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805653-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805653-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805653-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>source: Communication de la Pr\u00e9sidence de la R\u00e9publique gabonaise.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Pr\u00e9sident de la R\u00e9publique, Brice Clotaire Oligui Nguema, a re\u00e7u le lundi 05 mai en audience Monsieur Mu Hong, envoy\u00e9 sp\u00e9cial du Pr\u00e9sident de la R\u00e9publique populaire de Chine et Vice-Pr\u00e9sident du Comit\u00e9 National de la Conf\u00e9rence Consultative Politique du Peuple Chinois (CCPPC), porteur d\u2019un message personnel du Pr\u00e9sident<\/p>\n","protected":false},"author":3,"featured_media":6324,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[51],"tags":[],"class_list":["post-6322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diplomatie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited-1080x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Le Pr\u00e9sident de la R\u00e9publique, Brice Clotaire Oligui Nguema, a re\u00e7u le lundi 05 mai en audience Monsieur Mu Hong, envoy\u00e9 sp\u00e9cial du Pr\u00e9sident de la R\u00e9publique populaire de Chine et Vice-Pr\u00e9sident du Comit\u00e9 National de la Conf\u00e9rence Consultative Politique du Peuple Chinois (CCPPC), porteur d\u2019un message personnel du Pr\u00e9sident","magazineBlocksPostCategories":["DIPLOMATIE"],"magazineBlocksPostViewCount":525,"magazineBlocksPostReadTime":1,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited.jpg",1080,608,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-51\">DIPLOMATIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gabon: Le Chef de l\u2019\u00c9tat re\u00e7oit un envoy\u00e9 sp\u00e9cial du Pr\u00e9sident XI JINPING - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gabon: Le Chef de l\u2019\u00c9tat re\u00e7oit un envoy\u00e9 sp\u00e9cial du Pr\u00e9sident XI JINPING - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Le Pr\u00e9sident de la R\u00e9publique, Brice Clotaire Oligui Nguema, a re\u00e7u le lundi 05 mai en audience Monsieur Mu Hong, envoy\u00e9 sp\u00e9cial du Pr\u00e9sident de la R\u00e9publique populaire de Chine et Vice-Pr\u00e9sident du Comit\u00e9 National de la Conf\u00e9rence Consultative Politique du Peuple Chinois (CCPPC), porteur d\u2019un message personnel du Pr\u00e9sident\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-06T08:51:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-06T08:51:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Gabon: Le Chef de l\u2019\u00c9tat re\u00e7oit un envoy\u00e9 sp\u00e9cial du Pr\u00e9sident XI JINPING\",\"datePublished\":\"2025-05-06T08:51:15+00:00\",\"dateModified\":\"2025-05-06T08:51:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/\"},\"wordCount\":204,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited.jpg\",\"articleSection\":[\"DIPLOMATIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/\",\"name\":\"Gabon: Le Chef de l\u2019\u00c9tat re\u00e7oit un envoy\u00e9 sp\u00e9cial du Pr\u00e9sident XI JINPING - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited.jpg\",\"datePublished\":\"2025-05-06T08:51:15+00:00\",\"dateModified\":\"2025-05-06T08:51:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited.jpg\",\"width\":1080,\"height\":608},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gabon: Le Chef de l\u2019\u00c9tat re\u00e7oit un envoy\u00e9 sp\u00e9cial du Pr\u00e9sident XI JINPING\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gabon: Le Chef de l\u2019\u00c9tat re\u00e7oit un envoy\u00e9 sp\u00e9cial du Pr\u00e9sident XI JINPING - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/","og_locale":"fr_FR","og_type":"article","og_title":"Gabon: Le Chef de l\u2019\u00c9tat re\u00e7oit un envoy\u00e9 sp\u00e9cial du Pr\u00e9sident XI JINPING - Cooperation Internationale","og_description":"Le Pr\u00e9sident de la R\u00e9publique, Brice Clotaire Oligui Nguema, a re\u00e7u le lundi 05 mai en audience Monsieur Mu Hong, envoy\u00e9 sp\u00e9cial du Pr\u00e9sident de la R\u00e9publique populaire de Chine et Vice-Pr\u00e9sident du Comit\u00e9 National de la Conf\u00e9rence Consultative Politique du Peuple Chinois (CCPPC), porteur d\u2019un message personnel du Pr\u00e9sident","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-05-06T08:51:15+00:00","article_modified_time":"2025-05-06T08:51:16+00:00","og_image":[{"width":1080,"height":608,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Gabon: Le Chef de l\u2019\u00c9tat re\u00e7oit un envoy\u00e9 sp\u00e9cial du Pr\u00e9sident XI JINPING","datePublished":"2025-05-06T08:51:15+00:00","dateModified":"2025-05-06T08:51:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/"},"wordCount":204,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited.jpg","articleSection":["DIPLOMATIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/","name":"Gabon: Le Chef de l\u2019\u00c9tat re\u00e7oit un envoy\u00e9 sp\u00e9cial du Pr\u00e9sident XI JINPING - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited.jpg","datePublished":"2025-05-06T08:51:15+00:00","dateModified":"2025-05-06T08:51:16+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited.jpg","width":1080,"height":608},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/05\/06\/gabon-le-chef-de-letat-recoit-un-envoye-special-du-president-xi-jinping\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Gabon: Le Chef de l\u2019\u00c9tat re\u00e7oit un envoy\u00e9 sp\u00e9cial du Pr\u00e9sident XI JINPING"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/05\/1000805654-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/6322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=6322"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/6322\/revisions"}],"predecessor-version":[{"id":6327,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/6322\/revisions\/6327"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/6324"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=6322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=6322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=6322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}