{"id":6160,"date":"2025-04-28T09:10:57","date_gmt":"2025-04-28T09:10:57","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=6160"},"modified":"2025-04-28T09:12:19","modified_gmt":"2025-04-28T09:12:19","slug":"togo-celebration-des-65-ans-de-lindependance","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/","title":{"rendered":"Togo : C\u00e9l\u00e9bration des 65 ans de l&#8217;ind\u00e9pendance."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Le Pr\u00e9sident Faure Essozimna GNASSINGB\u00c9 a pr\u00e9sid\u00e9 un important d\u00e9fil\u00e9 militaire et civil en pr\u00e9sence de  plusieurs personnalit\u00e9s diplomatiques.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">27 avril 1960-27 avril 2025. Il y a 65 ans jour pour jour, le Togo acc\u00e8de \u00e0 la souverainet\u00e9 internationale. Dans une ambiance de grande mobilisation populaire, les Togolais ont c\u00e9l\u00e9br\u00e9 cet anniversaire de l\u2019ind\u00e9pendance du pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A cet effet, le Pr\u00e9sident de la R\u00e9publique, Faure Essozimna Gnassingb\u00e9 a pr\u00e9sid\u00e9 un impressionnant d\u00e9fil\u00e9 militaire, paramilitaire et civil, au cours duquel diff\u00e9rents groupes ont d\u00e9montr\u00e9 leur attachement aux valeurs r\u00e9publicaines et au patriotisme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le chef de l\u2019Etat togolais \u00e9tait entour\u00e9 pour la circonstance, des membres du gouvernement, des pr\u00e9sidents des institutions et de plusieurs personnalit\u00e9s diplomatiques, politiques, militaires, administratives, traditionnelles et religieuses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A son arriv\u00e9e sur les lieux des manifestations \u00e0 la Place des f\u00eates de Lom\u00e92, le Pr\u00e9sident de la R\u00e9publique, chef des arm\u00e9es a \u00e9t\u00e9 accueilli avec les honneurs militaires au cours d\u2019une prise d\u2019armes avec la revue des troupes et l\u2019hymne national \u00ab Terre de nos a\u00efeux \u00bb.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780608-edited.jpg\" alt=\"\" class=\"wp-image-6162\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780608-edited.jpg 1080w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780608-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780608-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780608-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s ce c\u00e9r\u00e9monial protocolaire qui traduit l\u2019engagement et la loyaut\u00e9 des forces de d\u00e9fense et de s\u00e9curit\u00e9, en symbiose avec les couches socioprofessionnelles, l\u2019assistance a suivi avec int\u00e9r\u00eat les prestations des diff\u00e9rents corps des Forces arm\u00e9es togolaise (FAT) et de s\u00e9curit\u00e9 : terre, air, mer, gendarmerie, sapeurs-pompiers, police, douanes, eaux et for\u00eat et \u00e9coles de formation militaire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A l\u2019issue de ce d\u00e9fil\u00e9 militaire et paramilitaire fortement ovationn\u00e9, le chef des arm\u00e9es a adress\u00e9 ses vives f\u00e9licitations aux troupes, pour la bonne tenue et la parfaite organisation de cette parade.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"607\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780604-edited.jpg\" alt=\"\" class=\"wp-image-6164\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780604-edited.jpg 1080w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780604-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780604-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780604-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le passage des groupes organis\u00e9s repr\u00e9sentant toutes les r\u00e9gions du pays pour r\u00e9affirmer la coh\u00e9sion nationale a donn\u00e9 un cachet particulier \u00e0 cette \u00e9dition. Il en est de m\u00eame pour les universit\u00e9s publiques et priv\u00e9es, l\u2019Ecole nationale d\u2019administration (ENA), les \u00e9tablissements d\u2019enseignement primaire et secondaire ainsi que les groupes folkloriques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette d\u00e9monstration populaire refl\u00e8te l\u2019adh\u00e9sion des institutions et des forces vives de la nation aux initiatives de d\u00e9veloppement \u00e9conomique, social et de consolidation de la paix et la stabilit\u00e9 au Togo, conform\u00e9ment \u00e0 la vision du chef de l\u2019Etat.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"607\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780606-edited.jpg\" alt=\"\" class=\"wp-image-6166\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780606-edited.jpg 1080w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780606-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780606-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780606-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Parall\u00e8lement aux festivit\u00e9s qui se sont d\u00e9roul\u00e9es dans la capitale, des manifestations tout aussi significatives ont \u00e9t\u00e9 \u00e9galement organis\u00e9es dans les chefs-lieux des diff\u00e9rentes r\u00e9gions et pr\u00e9fectures du pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cet important d\u00e9fil\u00e9 est le point culminant d\u2019une s\u00e9rie d\u2019activit\u00e9s organis\u00e9es \u00e0 l\u2019occasion de ce 65\u00e8 anniversaire de l\u2019accession du Togo \u00e0 la souverainet\u00e9 internationale notamment l\u2019inauguration et la pose de la premi\u00e8re pierre de plusieurs infrastructures \u00e9conomiques, \u00e9nerg\u00e9tiques et sanitaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A travers cette c\u00e9l\u00e9bration, le peuple togolais a une fois de plus r\u00e9affirm\u00e9 sa d\u00e9termination de faire de l\u2019ind\u00e9pendance du pays non seulement un devoir de m\u00e9moire pour c\u00e9l\u00e9brer les h\u00e9ros nationaux, mais aussi un instrument d\u2019unit\u00e9 nationale et un catalyseur de progr\u00e8s, dans le respect des principes de souverainet\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Source: Communication de la Pr\u00e9sidence du Togo.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Pr\u00e9sident Faure Essozimna GNASSINGB\u00c9 a pr\u00e9sid\u00e9 un important d\u00e9fil\u00e9 militaire et civil en pr\u00e9sence de plusieurs personnalit\u00e9s diplomatiques. 27 avril 1960-27 avril 2025. Il y a 65 ans jour pour jour, le Togo acc\u00e8de \u00e0 la souverainet\u00e9 internationale. Dans une ambiance de grande mobilisation populaire, les Togolais ont c\u00e9l\u00e9br\u00e9<\/p>\n","protected":false},"author":3,"featured_media":6170,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[51],"tags":[],"class_list":["post-6160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diplomatie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited-1080x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Le Pr\u00e9sident Faure Essozimna GNASSINGB\u00c9 a pr\u00e9sid\u00e9 un important d\u00e9fil\u00e9 militaire et civil en pr\u00e9sence de plusieurs personnalit\u00e9s diplomatiques. 27 avril 1960-27 avril 2025. Il y a 65 ans jour pour jour, le Togo acc\u00e8de \u00e0 la souverainet\u00e9 internationale. Dans une ambiance de grande mobilisation populaire, les Togolais ont c\u00e9l\u00e9br\u00e9","magazineBlocksPostCategories":["DIPLOMATIE"],"magazineBlocksPostViewCount":540,"magazineBlocksPostReadTime":3,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited.jpg",1080,607,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-51\">DIPLOMATIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Togo : C\u00e9l\u00e9bration des 65 ans de l&#039;ind\u00e9pendance. - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Togo : C\u00e9l\u00e9bration des 65 ans de l&#039;ind\u00e9pendance. - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Le Pr\u00e9sident Faure Essozimna GNASSINGB\u00c9 a pr\u00e9sid\u00e9 un important d\u00e9fil\u00e9 militaire et civil en pr\u00e9sence de plusieurs personnalit\u00e9s diplomatiques. 27 avril 1960-27 avril 2025. Il y a 65 ans jour pour jour, le Togo acc\u00e8de \u00e0 la souverainet\u00e9 internationale. Dans une ambiance de grande mobilisation populaire, les Togolais ont c\u00e9l\u00e9br\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T09:10:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-28T09:12:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Togo : C\u00e9l\u00e9bration des 65 ans de l&#8217;ind\u00e9pendance.\",\"datePublished\":\"2025-04-28T09:10:57+00:00\",\"dateModified\":\"2025-04-28T09:12:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/\"},\"wordCount\":567,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited.jpg\",\"articleSection\":[\"DIPLOMATIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/\",\"name\":\"Togo : C\u00e9l\u00e9bration des 65 ans de l'ind\u00e9pendance. - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited.jpg\",\"datePublished\":\"2025-04-28T09:10:57+00:00\",\"dateModified\":\"2025-04-28T09:12:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited.jpg\",\"width\":1080,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Togo : C\u00e9l\u00e9bration des 65 ans de l&#8217;ind\u00e9pendance.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Togo : C\u00e9l\u00e9bration des 65 ans de l'ind\u00e9pendance. - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/","og_locale":"fr_FR","og_type":"article","og_title":"Togo : C\u00e9l\u00e9bration des 65 ans de l'ind\u00e9pendance. - Cooperation Internationale","og_description":"Le Pr\u00e9sident Faure Essozimna GNASSINGB\u00c9 a pr\u00e9sid\u00e9 un important d\u00e9fil\u00e9 militaire et civil en pr\u00e9sence de plusieurs personnalit\u00e9s diplomatiques. 27 avril 1960-27 avril 2025. Il y a 65 ans jour pour jour, le Togo acc\u00e8de \u00e0 la souverainet\u00e9 internationale. Dans une ambiance de grande mobilisation populaire, les Togolais ont c\u00e9l\u00e9br\u00e9","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-04-28T09:10:57+00:00","article_modified_time":"2025-04-28T09:12:19+00:00","og_image":[{"width":1080,"height":607,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Togo : C\u00e9l\u00e9bration des 65 ans de l&#8217;ind\u00e9pendance.","datePublished":"2025-04-28T09:10:57+00:00","dateModified":"2025-04-28T09:12:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/"},"wordCount":567,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited.jpg","articleSection":["DIPLOMATIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/","name":"Togo : C\u00e9l\u00e9bration des 65 ans de l'ind\u00e9pendance. - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited.jpg","datePublished":"2025-04-28T09:10:57+00:00","dateModified":"2025-04-28T09:12:19+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited.jpg","width":1080,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/28\/togo-celebration-des-65-ans-de-lindependance\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Togo : C\u00e9l\u00e9bration des 65 ans de l&#8217;ind\u00e9pendance."}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000780607-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/6160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=6160"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/6160\/revisions"}],"predecessor-version":[{"id":6168,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/6160\/revisions\/6168"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/6170"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=6160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=6160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=6160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}