{"id":5716,"date":"2025-04-11T16:13:02","date_gmt":"2025-04-11T16:13:02","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=5716"},"modified":"2025-04-11T16:13:04","modified_gmt":"2025-04-11T16:13:04","slug":"cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/","title":{"rendered":"C\u00f4te d&#8217;Ivoire : Lancement de la 1\u00e8re \u00c9dition du Forum \u00c9conomique de Coop\u00e9ration Bilat\u00e9rale C\u00f4te d&#8217;Ivoire -Afrique Centrale."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L&#8217; Ambassade de C\u00f4te d&#8217;Ivoire pr\u00e8s la R\u00e9publique du Cameroun, du Tchad et de la Centrafrique a lanc\u00e9 la premi\u00e8re \u00e9dition du &#8220;Forum \u00e9conomique de coop\u00e9ration bilat\u00e9rale C\u00f4te d&#8217;Ivoire-Afrique centrale (secteur public-secteur priv\u00e9)&#8221;, le mercredi 09 avril 2025 au Palais de la culture de Treichville, \u00e0 la salle Lougah Fran\u00e7ois, en pr\u00e9sence des chefs de d\u00e9l\u00e9gations africains de la Centrafrique, du Tchad et du Cameroun, des chefs d&#8217;entreprises, des Pr\u00e9sidents des patronats des quatre (4) pays, des hauts cadres de l&#8217;administration et des \u00c9tudiants des grandes \u00e9coles professionnelles de commerce d&#8217;Abidjan.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce Forum a \u00e9t\u00e9 pr\u00e9sid\u00e9 par le Premier Ministre repr\u00e9sent\u00e9 par le Ministre des Ressources Animales et Halieutiques Sidi Tiemoko Tour\u00e9.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731028-edited-1024x576.jpg\" alt=\"\" class=\"wp-image-5720\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731028-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731028-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731028-edited-768x432.jpg 768w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731028-edited.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Plusieurs Stands d&#8217;exposition des produits agroalimentaires des.pays participants ont \u00e9t\u00e9 visit\u00e9s par les officiels.\u00a9 Photo MAE <\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Dans son allocution, le ministre a soulign\u00e9 que ce forum marque une \u00e9tape importante dans le renforcement des relations \u00e9conomiques et diplomatiques de la C\u00f4te d&#8217;Ivoire et de ses diff\u00e9rents pays d&#8217;Afrique centrale afin de cr\u00e9er des synergies d\u00e9finies et une collaboration qui transcendent les fronti\u00e8res, sur laquelle reposent les principes de transparence, d&#8217;\u00e9quit\u00e9 et de vision.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce forum dispose de plusieurs secteurs d&#8217;activit\u00e9s, dont l&#8217;agroalimentaire, les infrastructures immobili\u00e8res, l&#8217;\u00e9nergie, ainsi que les institutions diplomatiques et les \u00e9tablissements professionnels.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rappelons que ce forum initi\u00e9 par Son Monsieur Filbert Gleglaud, Ambassadeur de C\u00f4te d&#8217;Ivoire au Cameroun, a pris fin ce vendredi 11 avril 2025.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Source: Minist\u00e8re des affaires \u00e9trang\u00e8res de C\u00f4te d&#8217;Ivoire.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217; Ambassade de C\u00f4te d&#8217;Ivoire pr\u00e8s la R\u00e9publique du Cameroun, du Tchad et de la Centrafrique a lanc\u00e9 la premi\u00e8re \u00e9dition du &#8220;Forum \u00e9conomique de coop\u00e9ration bilat\u00e9rale C\u00f4te d&#8217;Ivoire-Afrique centrale (secteur public-secteur priv\u00e9)&#8221;, le mercredi 09 avril 2025 au Palais de la culture de Treichville, \u00e0 la salle Lougah Fran\u00e7ois,<\/p>\n","protected":false},"author":3,"featured_media":5718,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50],"tags":[],"class_list":["post-5716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cooperation"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited-1080x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"L&#8217; Ambassade de C\u00f4te d&#8217;Ivoire pr\u00e8s la R\u00e9publique du Cameroun, du Tchad et de la Centrafrique a lanc\u00e9 la premi\u00e8re \u00e9dition du &#8220;Forum \u00e9conomique de coop\u00e9ration bilat\u00e9rale C\u00f4te d&#8217;Ivoire-Afrique centrale (secteur public-secteur priv\u00e9)&#8221;, le mercredi 09 avril 2025 au Palais de la culture de Treichville, \u00e0 la salle Lougah Fran\u00e7ois,","magazineBlocksPostCategories":["COOPERATION"],"magazineBlocksPostViewCount":565,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited.jpg",1080,607,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-50\">COOPERATION<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f4te d&#039;Ivoire : Lancement de la 1\u00e8re \u00c9dition du Forum \u00c9conomique de Coop\u00e9ration Bilat\u00e9rale C\u00f4te d&#039;Ivoire -Afrique Centrale. - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f4te d&#039;Ivoire : Lancement de la 1\u00e8re \u00c9dition du Forum \u00c9conomique de Coop\u00e9ration Bilat\u00e9rale C\u00f4te d&#039;Ivoire -Afrique Centrale. - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"L&#8217; Ambassade de C\u00f4te d&#8217;Ivoire pr\u00e8s la R\u00e9publique du Cameroun, du Tchad et de la Centrafrique a lanc\u00e9 la premi\u00e8re \u00e9dition du &#8220;Forum \u00e9conomique de coop\u00e9ration bilat\u00e9rale C\u00f4te d&#8217;Ivoire-Afrique centrale (secteur public-secteur priv\u00e9)&#8221;, le mercredi 09 avril 2025 au Palais de la culture de Treichville, \u00e0 la salle Lougah Fran\u00e7ois,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-11T16:13:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-11T16:13:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"C\u00f4te d&#8217;Ivoire : Lancement de la 1\u00e8re \u00c9dition du Forum \u00c9conomique de Coop\u00e9ration Bilat\u00e9rale C\u00f4te d&#8217;Ivoire -Afrique Centrale.\",\"datePublished\":\"2025-04-11T16:13:02+00:00\",\"dateModified\":\"2025-04-11T16:13:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/\"},\"wordCount\":297,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited.jpg\",\"articleSection\":[\"COOPERATION\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/\",\"name\":\"C\u00f4te d'Ivoire : Lancement de la 1\u00e8re \u00c9dition du Forum \u00c9conomique de Coop\u00e9ration Bilat\u00e9rale C\u00f4te d'Ivoire -Afrique Centrale. - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited.jpg\",\"datePublished\":\"2025-04-11T16:13:02+00:00\",\"dateModified\":\"2025-04-11T16:13:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited.jpg\",\"width\":1080,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f4te d&#8217;Ivoire : Lancement de la 1\u00e8re \u00c9dition du Forum \u00c9conomique de Coop\u00e9ration Bilat\u00e9rale C\u00f4te d&#8217;Ivoire -Afrique Centrale.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f4te d'Ivoire : Lancement de la 1\u00e8re \u00c9dition du Forum \u00c9conomique de Coop\u00e9ration Bilat\u00e9rale C\u00f4te d'Ivoire -Afrique Centrale. - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/","og_locale":"fr_FR","og_type":"article","og_title":"C\u00f4te d'Ivoire : Lancement de la 1\u00e8re \u00c9dition du Forum \u00c9conomique de Coop\u00e9ration Bilat\u00e9rale C\u00f4te d'Ivoire -Afrique Centrale. - Cooperation Internationale","og_description":"L&#8217; Ambassade de C\u00f4te d&#8217;Ivoire pr\u00e8s la R\u00e9publique du Cameroun, du Tchad et de la Centrafrique a lanc\u00e9 la premi\u00e8re \u00e9dition du &#8220;Forum \u00e9conomique de coop\u00e9ration bilat\u00e9rale C\u00f4te d&#8217;Ivoire-Afrique centrale (secteur public-secteur priv\u00e9)&#8221;, le mercredi 09 avril 2025 au Palais de la culture de Treichville, \u00e0 la salle Lougah Fran\u00e7ois,","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-04-11T16:13:02+00:00","article_modified_time":"2025-04-11T16:13:04+00:00","og_image":[{"width":1080,"height":607,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"C\u00f4te d&#8217;Ivoire : Lancement de la 1\u00e8re \u00c9dition du Forum \u00c9conomique de Coop\u00e9ration Bilat\u00e9rale C\u00f4te d&#8217;Ivoire -Afrique Centrale.","datePublished":"2025-04-11T16:13:02+00:00","dateModified":"2025-04-11T16:13:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/"},"wordCount":297,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited.jpg","articleSection":["COOPERATION"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/","name":"C\u00f4te d'Ivoire : Lancement de la 1\u00e8re \u00c9dition du Forum \u00c9conomique de Coop\u00e9ration Bilat\u00e9rale C\u00f4te d'Ivoire -Afrique Centrale. - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited.jpg","datePublished":"2025-04-11T16:13:02+00:00","dateModified":"2025-04-11T16:13:04+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited.jpg","width":1080,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/11\/cote-divoire-lancement-de-la-1ere-edition-du-forum-economique-de-cooperation-bilaterale-cote-divoire-afrique-centrale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"C\u00f4te d&#8217;Ivoire : Lancement de la 1\u00e8re \u00c9dition du Forum \u00c9conomique de Coop\u00e9ration Bilat\u00e9rale C\u00f4te d&#8217;Ivoire -Afrique Centrale."}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000731035-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/5716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=5716"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/5716\/revisions"}],"predecessor-version":[{"id":5722,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/5716\/revisions\/5722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/5718"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=5716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=5716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=5716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}