{"id":5671,"date":"2025-04-10T06:34:00","date_gmt":"2025-04-10T06:34:00","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=5671"},"modified":"2025-04-10T06:34:02","modified_gmt":"2025-04-10T06:34:02","slug":"gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/","title":{"rendered":"Gabon-Pr\u00e9sidentielle 2025: l&#8217;OIF entend d\u00e9ployer ses Experts sur le terrain."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Ministre de l&#8217;Int\u00e9rieur et de la S\u00e9curit\u00e9 M Hermann a re\u00e7u le mercredi 9 avril 2025, la Mission d&#8217;observation \u00e9lectorale de l&#8217;Organisation Internationale de la Francophonie (OIF).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conduite par l&#8217;Ambassadeur D\u00e9sir\u00e9 NYAHUHIRIRA, Conseiller sp\u00e9cial politique et diplomatique de la Secr\u00e9taire G\u00e9n\u00e9rale de cette organisation, la mission est venue r\u00e9it\u00e9rer, \u00e0 3 jours du scrutin, le soutien, l&#8217;accompagnement et les f\u00e9licitations de l&#8217;OIF \u00e0 la Transition gabonaise de par le respect de son chronogramme, et s&#8217;informer de l&#8217;\u00e9tat global des pr\u00e9paratifs du scrutin du 12 avril.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;OIF s&#8217;est f\u00e9licit\u00e9 du bon d\u00e9roulement de la Transition gabonaise. Elle entend d\u00e9ployer ses experts dans plusieurs circonscriptions du pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dirig\u00e9e par l\u2019Ambassadeur D\u00e9sir\u00e9 Nyaruhirira, la mission \u00e9lectorale de l\u2019OIF sera \u00e0 Libreville du 7 au 15 avril 2025. La d\u00e9l\u00e9gation comprend une parlementaire de l\u2019Assembl\u00e9e parlementaire de la Francophonie (APF) ainsi que des experts venus de plusieurs \u00c9tats membres de l\u2019Organisation internationale de la Francophonie (OIF).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tout au long de leur s\u00e9jour, les membres de la MEF auront des \u00e9changes avec les autorit\u00e9s responsables des \u00e9lections, les candidats et acteurs politiques, les repr\u00e9sentants de la soci\u00e9t\u00e9 civile, ainsi que les partenaires internationaux pr\u00e9sents en R\u00e9publique gabonaise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette mission s\u2019inscrit dans le respect des principes d\u00e9finis par la D\u00e9claration de Bamako du 3 novembre 2000, qui vise \u00e0 garantir la tenue d\u2019\u00e9lections libres, transparentes et cr\u00e9dibles. Le jour du scrutin, les membres de la MEF se rendront dans divers centres et bureaux de vote pour observer le d\u00e9roulement des op\u00e9rations \u00e9lectorales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une fois le processus \u00e9lectoral termin\u00e9, la MEF dressera un rapport contenant ses constats et recommandations, qui sera remis aux autorit\u00e9s gabonaises.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Source: Minist\u00e8re de l&#8217;int\u00e9rieur &amp; OIF Gabon.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Ministre de l&#8217;Int\u00e9rieur et de la S\u00e9curit\u00e9 M Hermann a re\u00e7u le mercredi 9 avril 2025, la Mission d&#8217;observation \u00e9lectorale de l&#8217;Organisation Internationale de la Francophonie (OIF). Conduite par l&#8217;Ambassadeur D\u00e9sir\u00e9 NYAHUHIRIRA, Conseiller sp\u00e9cial politique et diplomatique de la Secr\u00e9taire G\u00e9n\u00e9rale de cette organisation, la mission est venue r\u00e9it\u00e9rer,<\/p>\n","protected":false},"author":3,"featured_media":5672,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50],"tags":[],"class_list":["post-5671","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cooperation"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601-1080x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Le Ministre de l&#8217;Int\u00e9rieur et de la S\u00e9curit\u00e9 M Hermann a re\u00e7u le mercredi 9 avril 2025, la Mission d&#8217;observation \u00e9lectorale de l&#8217;Organisation Internationale de la Francophonie (OIF). Conduite par l&#8217;Ambassadeur D\u00e9sir\u00e9 NYAHUHIRIRA, Conseiller sp\u00e9cial politique et diplomatique de la Secr\u00e9taire G\u00e9n\u00e9rale de cette organisation, la mission est venue r\u00e9it\u00e9rer,","magazineBlocksPostCategories":["COOPERATION"],"magazineBlocksPostViewCount":924,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601.jpg",1080,608,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-50\">COOPERATION<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gabon-Pr\u00e9sidentielle 2025: l&#039;OIF entend d\u00e9ployer ses Experts sur le terrain. - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gabon-Pr\u00e9sidentielle 2025: l&#039;OIF entend d\u00e9ployer ses Experts sur le terrain. - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Le Ministre de l&#8217;Int\u00e9rieur et de la S\u00e9curit\u00e9 M Hermann a re\u00e7u le mercredi 9 avril 2025, la Mission d&#8217;observation \u00e9lectorale de l&#8217;Organisation Internationale de la Francophonie (OIF). Conduite par l&#8217;Ambassadeur D\u00e9sir\u00e9 NYAHUHIRIRA, Conseiller sp\u00e9cial politique et diplomatique de la Secr\u00e9taire G\u00e9n\u00e9rale de cette organisation, la mission est venue r\u00e9it\u00e9rer,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-10T06:34:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-10T06:34:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"608\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Gabon-Pr\u00e9sidentielle 2025: l&#8217;OIF entend d\u00e9ployer ses Experts sur le terrain.\",\"datePublished\":\"2025-04-10T06:34:00+00:00\",\"dateModified\":\"2025-04-10T06:34:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/\"},\"wordCount\":326,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601.jpg\",\"articleSection\":[\"COOPERATION\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/\",\"name\":\"Gabon-Pr\u00e9sidentielle 2025: l'OIF entend d\u00e9ployer ses Experts sur le terrain. - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601.jpg\",\"datePublished\":\"2025-04-10T06:34:00+00:00\",\"dateModified\":\"2025-04-10T06:34:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601.jpg\",\"width\":1080,\"height\":608},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gabon-Pr\u00e9sidentielle 2025: l&#8217;OIF entend d\u00e9ployer ses Experts sur le terrain.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gabon-Pr\u00e9sidentielle 2025: l'OIF entend d\u00e9ployer ses Experts sur le terrain. - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/","og_locale":"fr_FR","og_type":"article","og_title":"Gabon-Pr\u00e9sidentielle 2025: l'OIF entend d\u00e9ployer ses Experts sur le terrain. - Cooperation Internationale","og_description":"Le Ministre de l&#8217;Int\u00e9rieur et de la S\u00e9curit\u00e9 M Hermann a re\u00e7u le mercredi 9 avril 2025, la Mission d&#8217;observation \u00e9lectorale de l&#8217;Organisation Internationale de la Francophonie (OIF). Conduite par l&#8217;Ambassadeur D\u00e9sir\u00e9 NYAHUHIRIRA, Conseiller sp\u00e9cial politique et diplomatique de la Secr\u00e9taire G\u00e9n\u00e9rale de cette organisation, la mission est venue r\u00e9it\u00e9rer,","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-04-10T06:34:00+00:00","article_modified_time":"2025-04-10T06:34:02+00:00","og_image":[{"width":1080,"height":608,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Gabon-Pr\u00e9sidentielle 2025: l&#8217;OIF entend d\u00e9ployer ses Experts sur le terrain.","datePublished":"2025-04-10T06:34:00+00:00","dateModified":"2025-04-10T06:34:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/"},"wordCount":326,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601.jpg","articleSection":["COOPERATION"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/","name":"Gabon-Pr\u00e9sidentielle 2025: l'OIF entend d\u00e9ployer ses Experts sur le terrain. - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601.jpg","datePublished":"2025-04-10T06:34:00+00:00","dateModified":"2025-04-10T06:34:02+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601.jpg","width":1080,"height":608},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/04\/10\/gabon-presidentielle-2025-loif-entend-deployer-ses-experts-sur-le-terrain\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Gabon-Pr\u00e9sidentielle 2025: l&#8217;OIF entend d\u00e9ployer ses Experts sur le terrain."}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/04\/1000723601.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/5671","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=5671"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/5671\/revisions"}],"predecessor-version":[{"id":5673,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/5671\/revisions\/5673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/5672"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=5671"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=5671"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=5671"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}