{"id":4957,"date":"2025-03-19T12:55:40","date_gmt":"2025-03-19T12:55:40","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=4957"},"modified":"2025-03-19T12:57:21","modified_gmt":"2025-03-19T12:57:21","slug":"tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/","title":{"rendered":"Tchad-Energie: Lancement du Projet PAAET avec  le soutien de la Banque Mondiale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> Le Ministre d\u2019\u00c9tat, Ministre des Finances, du Budget, de l\u2019\u00c9conomie, du Plan et de la Coop\u00e9ration internationale, M. Tahir Hamid Nguilin, a pris part le  mercredi 19 mars 2025 \u00e0 Massakory au lancement officiel du Projet d\u2019Accroissement de l\u2019Acc\u00e8s \u00e0 l\u2019\u00c9nergie au Tchad (PAAET).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Plac\u00e9e sous le haut patronage du Premier Ministre, Chef du Gouvernement, Ambassadeur Allah Maye Halina, cette c\u00e9r\u00e9monie marque une avanc\u00e9e majeure dans la strat\u00e9gie nationale d\u2019\u00e9lectrification. Soutenu par la Banque Mondiale, le PAAET vise \u00e0 am\u00e9liorer l\u2019acc\u00e8s \u00e0 l\u2019\u00e9lectricit\u00e9 dans 12 villes du pays (Ab\u00e9ch\u00e9, Biltine, Bol, Bongor, Doba, Faya, Koumra, Mao, Massaguet, Massakory, Moundou et Sarh) \u00e0 travers le d\u00e9ploiement de mini-r\u00e9seaux, de syst\u00e8mes solaires autonomes et l\u2019extension du r\u00e9seau \u00e9lectrique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En mars 2022,<strong>&nbsp;<\/strong>la Banque mondiale avait approuv\u00e9  un don de 295 millions de dollars de l&#8217;Association Internationale de D\u00e9veloppement (IDA) pour soutenir le Tchad dans son extension d\u2019acc\u00e8s \u00e0 l\u2019\u00e9nergie.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644668-1-1024x683.jpg\" alt=\"\" class=\"wp-image-4966\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644668-1-1024x683.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644668-1-300x200.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644668-1-768x512.jpg 768w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644668-1.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le Projet d&#8217;Accroissement de l&#8217;Acc\u00e8s \u00e0 l&#8217;Energie au Tchad (PAAET) vise \u00e0 augmenter l&#8217;acc\u00e8s \u00e0 l&#8217;\u00e9lectricit\u00e9 et aux solutions de cuisson propre gr\u00e2ce \u00e0 l&#8217;\u00e9lectrification via l\u2019extension du r\u00e9seau principal et des mini-r\u00e9seaux, les syst\u00e8mes solaires autonomes, le d\u00e9ploiement de foyers am\u00e9lior\u00e9s et la gestion des ressources naturelles. Il permettra l\u2019expansion de l&#8217;\u00e9lectrification de la capitale N&#8217;Djamena et de 12 villes secondaires dans lesquelles la Soci\u00e9t\u00e9 Nationale d\u2019Electricit\u00e9 (SNE) exploite des mini-r\u00e9seaux, ainsi que l&#8217;acc\u00e8s \u00e0 l&#8217;\u00e9lectricit\u00e9 dans d&#8217;autres villes secondaires et villages, y compris ceux situ\u00e9s \u00e0 proximit\u00e9 des camps de r\u00e9fugi\u00e9s. Des investissements publics et priv\u00e9s permettront de renforcer les capacit\u00e9s de production, de stockage et de distribution d\u2019\u00e9lectricit\u00e9 du pays.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"607\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644658-1-edited.jpg\" alt=\"\" class=\"wp-image-4968\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644658-1-edited.jpg 1080w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644658-1-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644658-1-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644658-1-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\"><em>Les populations de la localit\u00e9 de Massakory lors du lancement du projet le 19\/03\/2025\u00a9 Minist\u00e8re de l&#8217;\u00e9conomie du Tchad<\/em><\/figcaption><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">&nbsp;La strat\u00e9gie de soutien de la Banque pour l&#8217;acc\u00e8s \u00e0 l&#8217;\u00e9nergie au Tchad se fait sur une approche \u00e0 deux volets&nbsp;: d\u2019une part, l&#8217;\u00e9lectrification hors r\u00e9seau men\u00e9e par le secteur priv\u00e9 pour stimuler rapidement l&#8217;acc\u00e8s et d\u2019autre part, l&#8217;\u00e9lectrification nationale bas\u00e9e sur le r\u00e9seau par la SNE qui est strat\u00e9giquement importante,  souligne&nbsp;<strong>Clara de Sousa, directrice des op\u00e9rations pour le Burkina&nbsp;Faso, le Mali, le Niger et Tchad.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">&nbsp;Ce projet ambitionne, avec la participation du secteur priv\u00e9, un acc\u00e8s \u00e0 l\u2019\u00e9nergie passant d&#8217;environ 6 % aujourd&#8217;hui, \u00e0 30 % d\u2019ici 2027 pour environ un million de m\u00e9nages concern\u00e9s, ajoute&nbsp;<strong>Rasit Pertev, repr\u00e9sentant r\u00e9sident de la Banque mondiale au Tchad.<\/strong><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce au PAAET, plus de 6 millions de personnes b\u00e9n\u00e9ficieront des services d&#8217;\u00e9lectricit\u00e9, dont 400 000 r\u00e9fugi\u00e9s et environ 740 000 personnes issues des communaut\u00e9s h\u00f4tes. Le projet permettra \u00e9galement l\u2019\u00e9lectrification d\u2019environ 850 centres m\u00e9dicaux et 700 \u00e9coles, principalement dans les zones rurales, dont 150 centres m\u00e9dicaux et 200 \u00e9coles au profit des r\u00e9fugi\u00e9s et des communaut\u00e9s h\u00f4tes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Source: Minist\u00e8re de l&#8217;\u00e9conomie du Tchad <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Ministre d\u2019\u00c9tat, Ministre des Finances, du Budget, de l\u2019\u00c9conomie, du Plan et de la Coop\u00e9ration internationale, M. Tahir Hamid Nguilin, a pris part le mercredi 19 mars 2025 \u00e0 Massakory au lancement officiel du Projet d\u2019Accroissement de l\u2019Acc\u00e8s \u00e0 l\u2019\u00c9nergie au Tchad (PAAET). Plac\u00e9e sous le haut patronage du<\/p>\n","protected":false},"author":3,"featured_media":4963,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50],"tags":[263,86,250,262,261,260],"class_list":["post-4957","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cooperation","tag-cooperation-tchad-banque-mondiale","tag-diplomatie","tag-energie-pour-tous","tag-ida","tag-projet-paaet-tchad","tag-tchad-energie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited-1080x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Le Ministre d\u2019\u00c9tat, Ministre des Finances, du Budget, de l\u2019\u00c9conomie, du Plan et de la Coop\u00e9ration internationale, M. Tahir Hamid Nguilin, a pris part le mercredi 19 mars 2025 \u00e0 Massakory au lancement officiel du Projet d\u2019Accroissement de l\u2019Acc\u00e8s \u00e0 l\u2019\u00c9nergie au Tchad (PAAET). Plac\u00e9e sous le haut patronage du","magazineBlocksPostCategories":["COOPERATION"],"magazineBlocksPostViewCount":767,"magazineBlocksPostReadTime":3,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited.jpg",1080,607,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-50\">COOPERATION<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tchad-Energie: Lancement du Projet PAAET avec le soutien de la Banque Mondiale - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tchad-Energie: Lancement du Projet PAAET avec le soutien de la Banque Mondiale - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Le Ministre d\u2019\u00c9tat, Ministre des Finances, du Budget, de l\u2019\u00c9conomie, du Plan et de la Coop\u00e9ration internationale, M. Tahir Hamid Nguilin, a pris part le mercredi 19 mars 2025 \u00e0 Massakory au lancement officiel du Projet d\u2019Accroissement de l\u2019Acc\u00e8s \u00e0 l\u2019\u00c9nergie au Tchad (PAAET). Plac\u00e9e sous le haut patronage du\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-19T12:55:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-19T12:57:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Tchad-Energie: Lancement du Projet PAAET avec le soutien de la Banque Mondiale\",\"datePublished\":\"2025-03-19T12:55:40+00:00\",\"dateModified\":\"2025-03-19T12:57:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/\"},\"wordCount\":539,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited.jpg\",\"keywords\":[\"Coop\u00e9ration Tchad -Banque Mondiale\",\"Diplomatie\",\"\u00c9nergie pour tous\",\"IDA\",\"Projet PAAET Tchad\",\"Tchad \u00c9nergie\"],\"articleSection\":[\"COOPERATION\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/\",\"name\":\"Tchad-Energie: Lancement du Projet PAAET avec le soutien de la Banque Mondiale - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited.jpg\",\"datePublished\":\"2025-03-19T12:55:40+00:00\",\"dateModified\":\"2025-03-19T12:57:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited.jpg\",\"width\":1080,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tchad-Energie: Lancement du Projet PAAET avec le soutien de la Banque Mondiale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tchad-Energie: Lancement du Projet PAAET avec le soutien de la Banque Mondiale - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/","og_locale":"fr_FR","og_type":"article","og_title":"Tchad-Energie: Lancement du Projet PAAET avec le soutien de la Banque Mondiale - Cooperation Internationale","og_description":"Le Ministre d\u2019\u00c9tat, Ministre des Finances, du Budget, de l\u2019\u00c9conomie, du Plan et de la Coop\u00e9ration internationale, M. Tahir Hamid Nguilin, a pris part le mercredi 19 mars 2025 \u00e0 Massakory au lancement officiel du Projet d\u2019Accroissement de l\u2019Acc\u00e8s \u00e0 l\u2019\u00c9nergie au Tchad (PAAET). Plac\u00e9e sous le haut patronage du","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-03-19T12:55:40+00:00","article_modified_time":"2025-03-19T12:57:21+00:00","og_image":[{"width":1080,"height":607,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Tchad-Energie: Lancement du Projet PAAET avec le soutien de la Banque Mondiale","datePublished":"2025-03-19T12:55:40+00:00","dateModified":"2025-03-19T12:57:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/"},"wordCount":539,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited.jpg","keywords":["Coop\u00e9ration Tchad -Banque Mondiale","Diplomatie","\u00c9nergie pour tous","IDA","Projet PAAET Tchad","Tchad \u00c9nergie"],"articleSection":["COOPERATION"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/","name":"Tchad-Energie: Lancement du Projet PAAET avec le soutien de la Banque Mondiale - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited.jpg","datePublished":"2025-03-19T12:55:40+00:00","dateModified":"2025-03-19T12:57:21+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited.jpg","width":1080,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/19\/tchad-energie-lancement-du-projet-paaet-avec-le-soutien-de-la-banque-mondiale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Tchad-Energie: Lancement du Projet PAAET avec le soutien de la Banque Mondiale"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000644657-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/4957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=4957"}],"version-history":[{"count":2,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/4957\/revisions"}],"predecessor-version":[{"id":4970,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/4957\/revisions\/4970"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/4963"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=4957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=4957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=4957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}