{"id":4791,"date":"2025-03-15T10:06:29","date_gmt":"2025-03-15T10:06:29","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=4791"},"modified":"2025-03-15T10:06:30","modified_gmt":"2025-03-15T10:06:30","slug":"cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/","title":{"rendered":"C\u00f4te d&#8217;Ivoire : Visite de Travail du Ministre Br\u00e9silien des Relations Ext\u00e9rieures"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dans le cadre d\u2019une visite de travail en C\u00f4te d\u2019Ivoire, M.MAURO VIEIRA, Ministre des Relations Ext\u00e9rieures de la R\u00e9publique F\u00e9d\u00e9rative du Br\u00e9sil, a \u00e9t\u00e9 re\u00e7u en audience par son homologue ivoirien M. L\u00e9on Kacou ADOM, Ministre des Affaires Etrang\u00e8res, de l\u2019Int\u00e9gration Africaine et des Ivoiriens de l\u2019Ext\u00e9rieur, le vendredi 14 mars 2025, \u00e0 son Cabinet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les deux diplomates ont eu un t\u00eate-\u00e0-t\u00eate au Cabinet du Minist\u00e8re des Affaires Etrang\u00e8res suivi d\u2019une s\u00e9ance de travail dans la salle de conf\u00e9rence du minist\u00e8re en pr\u00e9sence des Ministres, Sidi Ti\u00e9moko TOURE, des Ressources Animales et Halieutiques ainsi que de Monsieur Amadou KONE, Ministre des Transports.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"607\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631707-edited.jpg\" alt=\"\" class=\"wp-image-4793\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631707-edited.jpg 1080w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631707-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631707-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631707-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\"><em>M. Leon Kacou ADOM, Ministre des affaires \u00e9trang\u00e8res de C\u00f4t\u00e9 d&#8217;ivoire le 14\/03\/2025 \u00a9 Photo MAE CI<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le Ministre L\u00e9on Kacou ADOM, lors de son allocution, a indiqu\u00e9 que cette rencontre refl\u00e8te l\u2019engagement mutuel \u00e0 renforcer les relations bilat\u00e9rales, la coop\u00e9ration \u00e9conomique, agricole, technologique et les partenariats strat\u00e9giques entre la C\u00f4te d\u2019Ivoire et le Br\u00e9sil.<br>Il s\u2019est par ailleurs r\u00e9joui de la volont\u00e9 des deux pays d\u2019accomplir des pas d\u00e9cisifs vers une intensification plus accrue de leur coop\u00e9ration, \u00e9voquant les liens historiques et culturels.<br>Pour finir, le Chef de la Diplomatie ivoirienne a appel\u00e9 de tous ses v\u0153ux \u00e0 l\u2019ouverture d\u2019une desserte entre Abidjan et l\u2019une des capitales br\u00e9siliennes afin de dynamiser davantage la coop\u00e9ration entre les deux pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Prenant \u00e0 son tour la parole, le Ministre br\u00e9silien a salu\u00e9 les autorit\u00e9s ivoiriennes pour la qualit\u00e9 de l\u2019accueil dont lui et sa d\u00e9l\u00e9gation ont fait l\u2019objet.<br>Il a appr\u00e9ci\u00e9 avec un grand int\u00e9r\u00eat les opportunit\u00e9s d\u2019investissements et les atouts de la C\u00f4te d\u2019Ivoire.<br>Il s\u2019est r\u00e9joui de la qualit\u00e9 de la coop\u00e9ration entre les deux pays et les a invit\u00e9s \u00e0 travailler \u00e0 la renforcer davantage.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"607\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631706-edited.jpg\" alt=\"\" class=\"wp-image-4795\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631706-edited.jpg 1080w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631706-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631706-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631706-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\"><em>M.MAURO VIEIRA, Ministre des Relations Ext\u00e9rieures du Br\u00e9sil, le 14\/03\/2025 \u00e0 Abidjan \u00a9 Photo MAE CIV<\/em><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Le chef de la diplomatie br\u00e9silienne a mis en avant les projets qui illustrent la coop\u00e9ration entre la C\u00f4te d\u2019Ivoire et le Br\u00e9sil, tels que les M\u00e9morandums d\u2019entente pour le commerce et l\u2019Investissement, le Forum d\u2019affaires multisectoriel, le Projet Cotton C\u00f4te d\u2019Ivoire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le ministre br\u00e9silien a saisi l\u2019occasion pour transmettre des invitations au Ministre L\u00e9on Kacou Adom pour des \u00e9v\u00e8nements internationaux, comme la COP 30, et une visite officielle en terre br\u00e9silienne pour faire le point sur le progr\u00e8s de la coop\u00e9ration entre les deux pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ces \u00e9tapes illustrent l\u2019engagement de la C\u00f4te d\u2019Ivoire et du Br\u00e9sil \u00e0 renforcer les relations bilat\u00e9rales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Source: MAE CIV<\/em><\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><\/h1>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre d\u2019une visite de travail en C\u00f4te d\u2019Ivoire, M.MAURO VIEIRA, Ministre des Relations Ext\u00e9rieures de la R\u00e9publique F\u00e9d\u00e9rative du Br\u00e9sil, a \u00e9t\u00e9 re\u00e7u en audience par son homologue ivoirien M. L\u00e9on Kacou ADOM, Ministre des Affaires Etrang\u00e8res, de l\u2019Int\u00e9gration Africaine et des Ivoiriens de l\u2019Ext\u00e9rieur, le vendredi 14<\/p>\n","protected":false},"author":3,"featured_media":4797,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[51],"tags":[182,183,181,180,179],"class_list":["post-4791","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diplomatie","tag-cicg","tag-civ225","tag-cooperation-cote-divoire-bresil","tag-diplomatie-bresilienne","tag-diplomatie-cote-divoire"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Dans le cadre d\u2019une visite de travail en C\u00f4te d\u2019Ivoire, M.MAURO VIEIRA, Ministre des Relations Ext\u00e9rieures de la R\u00e9publique F\u00e9d\u00e9rative du Br\u00e9sil, a \u00e9t\u00e9 re\u00e7u en audience par son homologue ivoirien M. L\u00e9on Kacou ADOM, Ministre des Affaires Etrang\u00e8res, de l\u2019Int\u00e9gration Africaine et des Ivoiriens de l\u2019Ext\u00e9rieur, le vendredi 14","magazineBlocksPostCategories":["DIPLOMATIE"],"magazineBlocksPostViewCount":428,"magazineBlocksPostReadTime":3,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg",1024,576,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-51\">DIPLOMATIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f4te d&#039;Ivoire : Visite de Travail du Ministre Br\u00e9silien des Relations Ext\u00e9rieures - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f4te d&#039;Ivoire : Visite de Travail du Ministre Br\u00e9silien des Relations Ext\u00e9rieures - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Dans le cadre d\u2019une visite de travail en C\u00f4te d\u2019Ivoire, M.MAURO VIEIRA, Ministre des Relations Ext\u00e9rieures de la R\u00e9publique F\u00e9d\u00e9rative du Br\u00e9sil, a \u00e9t\u00e9 re\u00e7u en audience par son homologue ivoirien M. L\u00e9on Kacou ADOM, Ministre des Affaires Etrang\u00e8res, de l\u2019Int\u00e9gration Africaine et des Ivoiriens de l\u2019Ext\u00e9rieur, le vendredi 14\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-15T10:06:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-15T10:06:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"C\u00f4te d&#8217;Ivoire : Visite de Travail du Ministre Br\u00e9silien des Relations Ext\u00e9rieures\",\"datePublished\":\"2025-03-15T10:06:29+00:00\",\"dateModified\":\"2025-03-15T10:06:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/\"},\"wordCount\":502,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg\",\"keywords\":[\"CICG\",\"CIV225\",\"Coop\u00e9ration C\u00f4te d'Ivoire -Bresil\",\"Diplomatie br\u00e9silienne\",\"Diplomatie c\u00f4t\u00e9 d'ivoire\"],\"articleSection\":[\"DIPLOMATIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/\",\"name\":\"C\u00f4te d'Ivoire : Visite de Travail du Ministre Br\u00e9silien des Relations Ext\u00e9rieures - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg\",\"datePublished\":\"2025-03-15T10:06:29+00:00\",\"dateModified\":\"2025-03-15T10:06:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg\",\"width\":1024,\"height\":576},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f4te d&#8217;Ivoire : Visite de Travail du Ministre Br\u00e9silien des Relations Ext\u00e9rieures\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f4te d'Ivoire : Visite de Travail du Ministre Br\u00e9silien des Relations Ext\u00e9rieures - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/","og_locale":"fr_FR","og_type":"article","og_title":"C\u00f4te d'Ivoire : Visite de Travail du Ministre Br\u00e9silien des Relations Ext\u00e9rieures - Cooperation Internationale","og_description":"Dans le cadre d\u2019une visite de travail en C\u00f4te d\u2019Ivoire, M.MAURO VIEIRA, Ministre des Relations Ext\u00e9rieures de la R\u00e9publique F\u00e9d\u00e9rative du Br\u00e9sil, a \u00e9t\u00e9 re\u00e7u en audience par son homologue ivoirien M. L\u00e9on Kacou ADOM, Ministre des Affaires Etrang\u00e8res, de l\u2019Int\u00e9gration Africaine et des Ivoiriens de l\u2019Ext\u00e9rieur, le vendredi 14","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-03-15T10:06:29+00:00","article_modified_time":"2025-03-15T10:06:30+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"C\u00f4te d&#8217;Ivoire : Visite de Travail du Ministre Br\u00e9silien des Relations Ext\u00e9rieures","datePublished":"2025-03-15T10:06:29+00:00","dateModified":"2025-03-15T10:06:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/"},"wordCount":502,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg","keywords":["CICG","CIV225","Coop\u00e9ration C\u00f4te d'Ivoire -Bresil","Diplomatie br\u00e9silienne","Diplomatie c\u00f4t\u00e9 d'ivoire"],"articleSection":["DIPLOMATIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/","name":"C\u00f4te d'Ivoire : Visite de Travail du Ministre Br\u00e9silien des Relations Ext\u00e9rieures - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg","datePublished":"2025-03-15T10:06:29+00:00","dateModified":"2025-03-15T10:06:30+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg","width":1024,"height":576},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/03\/15\/cote-divoire-visite-de-travail-du-ministre-bresilien-des-relations-exterieures\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"C\u00f4te d&#8217;Ivoire : Visite de Travail du Ministre Br\u00e9silien des Relations Ext\u00e9rieures"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/03\/1000631704-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/4791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=4791"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/4791\/revisions"}],"predecessor-version":[{"id":4798,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/4791\/revisions\/4798"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/4797"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=4791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=4791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=4791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}