{"id":4175,"date":"2025-02-21T07:43:23","date_gmt":"2025-02-21T07:43:23","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=4175"},"modified":"2025-02-21T08:05:06","modified_gmt":"2025-02-21T08:05:06","slug":"cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/","title":{"rendered":"CEA: La diversit\u00e9 linguistique, la culture et l&#8217;\u00e9ducation au coeur des d\u00e9bats."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>La Commission \u00e9conomique des Nations Unies pour l&#8217;Afrique (CEA), en collaboration avec la Ligue des \u00c9tats arabes, l&#8217;UNESCO, l&#8217;Organisation internationale de la Francophonie, l&#8217;ambassade du Bangladesh, l&#8217;ambassade d&#8217;Arm\u00e9nie et d&#8217;autres missions diplomatiques en \u00c9thiopie, a marqu\u00e9 le jubil\u00e9 d&#8217;argent de la Journ\u00e9e internationale de la langue maternelle avec une c\u00e9l\u00e9bration d\u00e9di\u00e9e \u00e0 la diversit\u00e9 linguistique, au patrimoine culturel et \u00e0 l&#8217;\u00e9ducation multilingue.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette manifestation, qui s&#8217;est tenue le jeudi 20 f\u00e9vrier 2025 au Centre de conf\u00e9rences des Nations Unies \u00e0 la CEA sis \u00e0 Addis Abeba, a mis en \u00e9vidence le r\u00f4le vital des langues maternelles dans l&#8217;\u00e9ducation, l&#8217;int\u00e9gration sociale et la formation . Dans son propos pr\u00e9liminaire,  au nom du Secr\u00e9taire ex\u00e9cutif, Aboubakri Diaw, Chef de cabinet du Secr\u00e9taire ex\u00e9cutif de la CEA, a soulign\u00e9 l&#8217;importance de la diversit\u00e9 linguistique dans l&#8217;\u00e9dification de soci\u00e9t\u00e9s inclusives. <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"607\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/1000565130-edited.jpg\" alt=\"\" class=\"wp-image-4179\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/1000565130-edited.jpg 1080w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/1000565130-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/1000565130-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/1000565130-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\"><em>M.Aboubakri Diaw, Chef de Cabinet du Secr\u00e9taire Ex\u00e9cutif de la CEA, le 20\/02\/2025 \u00e0 Addis Abeba \u00a9 Photo CEA<\/em><\/figcaption><\/figure>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Les langues ne sont pas seulement des moyens de communication ; elles sont des porteurs de culture, de connaissances et d&#8217;identit\u00e9. La pr\u00e9servation des langues maternelles est essentielle pour parvenir au d\u00e9veloppement durable et promouvoir la paix \u00bb<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">  , a-t-il d\u00e9clar\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La c\u00e9l\u00e9bration a r\u00e9uni des ambassadeurs, des fonctionnaires gouvernementaux, des universitaires et des repr\u00e9sentants culturels. Parmi les orateurs cl\u00e9s figurait ALI DAOU, repr\u00e9sentant du Bureau de liaison de l\u2019UNESCO, qui a r\u00e9affirm\u00e9 l\u2019engagement de l\u2019UNESCO \u00e0 prot\u00e9ger les langues menac\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;\u00e9v\u00e9nement comprenait des pr\u00e9sentations sur le r\u00f4le des langues maternelles dans l&#8217;\u00e9ducation, y compris une discussion sur leur importance dans le paysage linguistique de l&#8217;\u00c9thiopie. Les participants ont \u00e9galement appr\u00e9ci\u00e9 des r\u00e9citals de po\u00e9sie et des vitrines culturelles qui ont mis en lumi\u00e8re la beaut\u00e9 et la richesse de diff\u00e9rentes langues.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">R\u00e9fl\u00e9chissant aux 25 derni\u00e8res ann\u00e9es de progr\u00e8s, l&#8217;\u00e9v\u00e9nement a mis l&#8217;accent sur la n\u00e9cessit\u00e9 urgente d&#8217;acc\u00e9l\u00e9rer les efforts pour prot\u00e9ger les langues menac\u00e9es. Selon l&#8217;UNESCO, pr\u00e8s de 40 % de la population mondiale n&#8217;a pas acc\u00e8s \u00e0 l&#8217;\u00e9ducation dans sa langue maternelle, et si les tendances actuelles persistent, 90 % des langues pourraient dispara\u00eetre d&#8217;ici la fin du si\u00e8cle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans ses remarques finales, Irene Onyancha, Chef de la Section des services de gestion des connaissances de la CEA, a encourag\u00e9 une collaboration plus pouss\u00e9e pour promouvoir la diversit\u00e9 linguistique, exprimant sa gratitude \u00e0 tous les partenaires impliqu\u00e9s. Elle a invit\u00e9 les participants \u00e0 continuer de plaider en faveur du multilinguisme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>source: CEA , Addis Abeba <\/em><\/p>\n\n\n\n<h1 class=\"wp-block-heading\"><\/h1>\n","protected":false},"excerpt":{"rendered":"<p>La Commission \u00e9conomique des Nations Unies pour l&#8217;Afrique (CEA), en collaboration avec la Ligue des \u00c9tats arabes, l&#8217;UNESCO, l&#8217;Organisation internationale de la Francophonie, l&#8217;ambassade du Bangladesh, l&#8217;ambassade d&#8217;Arm\u00e9nie et d&#8217;autres missions diplomatiques en \u00c9thiopie, a marqu\u00e9 le jubil\u00e9 d&#8217;argent de la Journ\u00e9e internationale de la langue maternelle avec une c\u00e9l\u00e9bration<\/p>\n","protected":false},"author":3,"featured_media":4176,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[51],"tags":[],"class_list":["post-4175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diplomatie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158-300x200.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158-768x512.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158-1024x683.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158-1080x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"La Commission \u00e9conomique des Nations Unies pour l&#8217;Afrique (CEA), en collaboration avec la Ligue des \u00c9tats arabes, l&#8217;UNESCO, l&#8217;Organisation internationale de la Francophonie, l&#8217;ambassade du Bangladesh, l&#8217;ambassade d&#8217;Arm\u00e9nie et d&#8217;autres missions diplomatiques en \u00c9thiopie, a marqu\u00e9 le jubil\u00e9 d&#8217;argent de la Journ\u00e9e internationale de la langue maternelle avec une c\u00e9l\u00e9bration","magazineBlocksPostCategories":["DIPLOMATIE"],"magazineBlocksPostViewCount":381,"magazineBlocksPostReadTime":3,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158.jpg",1080,720,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158-300x200.jpg",300,200,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-51\">DIPLOMATIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CEA: La diversit\u00e9 linguistique, la culture et l&#039;\u00e9ducation au coeur des d\u00e9bats. - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CEA: La diversit\u00e9 linguistique, la culture et l&#039;\u00e9ducation au coeur des d\u00e9bats. - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"La Commission \u00e9conomique des Nations Unies pour l&#8217;Afrique (CEA), en collaboration avec la Ligue des \u00c9tats arabes, l&#8217;UNESCO, l&#8217;Organisation internationale de la Francophonie, l&#8217;ambassade du Bangladesh, l&#8217;ambassade d&#8217;Arm\u00e9nie et d&#8217;autres missions diplomatiques en \u00c9thiopie, a marqu\u00e9 le jubil\u00e9 d&#8217;argent de la Journ\u00e9e internationale de la langue maternelle avec une c\u00e9l\u00e9bration\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-21T07:43:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-21T08:05:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"CEA: La diversit\u00e9 linguistique, la culture et l&#8217;\u00e9ducation au coeur des d\u00e9bats.\",\"datePublished\":\"2025-02-21T07:43:23+00:00\",\"dateModified\":\"2025-02-21T08:05:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/\"},\"wordCount\":478,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158.jpg\",\"articleSection\":[\"DIPLOMATIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/\",\"name\":\"CEA: La diversit\u00e9 linguistique, la culture et l'\u00e9ducation au coeur des d\u00e9bats. - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158.jpg\",\"datePublished\":\"2025-02-21T07:43:23+00:00\",\"dateModified\":\"2025-02-21T08:05:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158.jpg\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CEA: La diversit\u00e9 linguistique, la culture et l&#8217;\u00e9ducation au coeur des d\u00e9bats.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CEA: La diversit\u00e9 linguistique, la culture et l'\u00e9ducation au coeur des d\u00e9bats. - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/","og_locale":"fr_FR","og_type":"article","og_title":"CEA: La diversit\u00e9 linguistique, la culture et l'\u00e9ducation au coeur des d\u00e9bats. - Cooperation Internationale","og_description":"La Commission \u00e9conomique des Nations Unies pour l&#8217;Afrique (CEA), en collaboration avec la Ligue des \u00c9tats arabes, l&#8217;UNESCO, l&#8217;Organisation internationale de la Francophonie, l&#8217;ambassade du Bangladesh, l&#8217;ambassade d&#8217;Arm\u00e9nie et d&#8217;autres missions diplomatiques en \u00c9thiopie, a marqu\u00e9 le jubil\u00e9 d&#8217;argent de la Journ\u00e9e internationale de la langue maternelle avec une c\u00e9l\u00e9bration","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-02-21T07:43:23+00:00","article_modified_time":"2025-02-21T08:05:06+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"CEA: La diversit\u00e9 linguistique, la culture et l&#8217;\u00e9ducation au coeur des d\u00e9bats.","datePublished":"2025-02-21T07:43:23+00:00","dateModified":"2025-02-21T08:05:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/"},"wordCount":478,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158.jpg","articleSection":["DIPLOMATIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/","name":"CEA: La diversit\u00e9 linguistique, la culture et l'\u00e9ducation au coeur des d\u00e9bats. - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158.jpg","datePublished":"2025-02-21T07:43:23+00:00","dateModified":"2025-02-21T08:05:06+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158.jpg","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/21\/cea-la-diversite-linguistique-la-culture-et-leducation-au-coeur-des-debats\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"CEA: La diversit\u00e9 linguistique, la culture et l&#8217;\u00e9ducation au coeur des d\u00e9bats."}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1740123113158.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/4175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=4175"}],"version-history":[{"count":2,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/4175\/revisions"}],"predecessor-version":[{"id":4181,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/4175\/revisions\/4181"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/4176"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=4175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=4175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=4175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}