{"id":4078,"date":"2025-02-18T11:08:36","date_gmt":"2025-02-18T11:08:36","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=4078"},"modified":"2025-02-18T11:15:20","modified_gmt":"2025-02-18T11:15:20","slug":"urgent-russie-us-les-pourparlers-a-riyadh-commencent","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/","title":{"rendered":"Arabie saoudite : les pourparlers entre la Russie et les \u00c9tats-Unis d\u00e9marrent \u00e0 Riyad"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\"><strong>Les pourparlers entre la Russie et les \u00c9tats-Unis visent \u00e0 r\u00e9tablir les relations entre les deux nations et \u00e0 r\u00e9soudre le conflit en Ukraine.<\/strong>Les pourparlers entre la Russie et les \u00c9tats-Unis visant \u00e0 r\u00e9tablir les relations entre les deux nations et \u00e0 r\u00e9soudre le conflit en Ukraine ont d\u00e9but\u00e9 mardi \u00e0 Riyad, la capitale de l&#8217;Arabie saoudite, selon les m\u00e9dias russes.<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\">Avant le d\u00e9but du principal cycle de n\u00e9gociations, les repr\u00e9sentants des deux pays ont eu des contacts informels, a d\u00e9clar\u00e9 \u00e0 la presse Kirill Dmitriev, directeur du Fonds russe d&#8217;investissement direct et membre de la d\u00e9l\u00e9gation russe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Selon ses estimations, les entreprises am\u00e9ricaines ont perdu plus de 300 milliards de dollars en quittant le march\u00e9 russe.\u2028<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Trouver des voies \u00e9conomiques communes et des solutions positives aux probl\u00e8mes est extr\u00eamement important, principalement pour les \u00c9tats-Unis et de nombreux autres pays qui commencent \u00e0 comprendre que le march\u00e9 russe est extr\u00eamement attractif et qu&#8217;il est n\u00e9cessaire d&#8217;y \u00eatre pr\u00e9sent&#8221;<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">, a-t-il d\u00e9clar\u00e9.\u2028<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lundi, Dmitri Peskov, le porte-parole du Kremlin, a d\u00e9clar\u00e9 que la r\u00e9union porterait sur les relations bilat\u00e9rales entre la Russie et les \u00c9tats-Unis, les pr\u00e9paratifs des n\u00e9gociations sur le r\u00e8glement de la question ukrainienne et une \u00e9ventuelle rencontre entre les pr\u00e9sidents des deux pays, Vladimir Poutine et Donald Trump.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;Arabie saoudite a \u00e9t\u00e9 choisie comme lieu de rencontre parce qu&#8217;elle convient aux deux parties, a d\u00e9clar\u00e9 Dmitri Peskov, ajoutant que les discussions sur la participation de l&#8217;Europe aux n\u00e9gociations sur le r\u00e8glement ukrainien \u00e9taient pr\u00e9matur\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Elena Teslova |AA| Moscou <\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les pourparlers entre la Russie et les \u00c9tats-Unis visent \u00e0 r\u00e9tablir les relations entre les deux nations et \u00e0 r\u00e9soudre le conflit en Ukraine.Les pourparlers entre la Russie et les \u00c9tats-Unis visant \u00e0 r\u00e9tablir les relations entre les deux nations et \u00e0 r\u00e9soudre le conflit en Ukraine ont d\u00e9but\u00e9 mardi<\/p>\n","protected":false},"author":3,"featured_media":4079,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[51],"tags":[],"class_list":["post-4078","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diplomatie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380-300x200.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380-768x512.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380-1024x683.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380-1080x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Les pourparlers entre la Russie et les \u00c9tats-Unis visent \u00e0 r\u00e9tablir les relations entre les deux nations et \u00e0 r\u00e9soudre le conflit en Ukraine.Les pourparlers entre la Russie et les \u00c9tats-Unis visant \u00e0 r\u00e9tablir les relations entre les deux nations et \u00e0 r\u00e9soudre le conflit en Ukraine ont d\u00e9but\u00e9 mardi","magazineBlocksPostCategories":["DIPLOMATIE"],"magazineBlocksPostViewCount":434,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380.jpg",1080,720,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380-300x200.jpg",300,200,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-51\">DIPLOMATIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Arabie saoudite : les pourparlers entre la Russie et les \u00c9tats-Unis d\u00e9marrent \u00e0 Riyad - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arabie saoudite : les pourparlers entre la Russie et les \u00c9tats-Unis d\u00e9marrent \u00e0 Riyad - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Les pourparlers entre la Russie et les \u00c9tats-Unis visent \u00e0 r\u00e9tablir les relations entre les deux nations et \u00e0 r\u00e9soudre le conflit en Ukraine.Les pourparlers entre la Russie et les \u00c9tats-Unis visant \u00e0 r\u00e9tablir les relations entre les deux nations et \u00e0 r\u00e9soudre le conflit en Ukraine ont d\u00e9but\u00e9 mardi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-18T11:08:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-18T11:15:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Arabie saoudite : les pourparlers entre la Russie et les \u00c9tats-Unis d\u00e9marrent \u00e0 Riyad\",\"datePublished\":\"2025-02-18T11:08:36+00:00\",\"dateModified\":\"2025-02-18T11:15:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/\"},\"wordCount\":293,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380.jpg\",\"articleSection\":[\"DIPLOMATIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/\",\"name\":\"Arabie saoudite : les pourparlers entre la Russie et les \u00c9tats-Unis d\u00e9marrent \u00e0 Riyad - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380.jpg\",\"datePublished\":\"2025-02-18T11:08:36+00:00\",\"dateModified\":\"2025-02-18T11:15:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380.jpg\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arabie saoudite : les pourparlers entre la Russie et les \u00c9tats-Unis d\u00e9marrent \u00e0 Riyad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arabie saoudite : les pourparlers entre la Russie et les \u00c9tats-Unis d\u00e9marrent \u00e0 Riyad - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/","og_locale":"fr_FR","og_type":"article","og_title":"Arabie saoudite : les pourparlers entre la Russie et les \u00c9tats-Unis d\u00e9marrent \u00e0 Riyad - Cooperation Internationale","og_description":"Les pourparlers entre la Russie et les \u00c9tats-Unis visent \u00e0 r\u00e9tablir les relations entre les deux nations et \u00e0 r\u00e9soudre le conflit en Ukraine.Les pourparlers entre la Russie et les \u00c9tats-Unis visant \u00e0 r\u00e9tablir les relations entre les deux nations et \u00e0 r\u00e9soudre le conflit en Ukraine ont d\u00e9but\u00e9 mardi","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-02-18T11:08:36+00:00","article_modified_time":"2025-02-18T11:15:20+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Arabie saoudite : les pourparlers entre la Russie et les \u00c9tats-Unis d\u00e9marrent \u00e0 Riyad","datePublished":"2025-02-18T11:08:36+00:00","dateModified":"2025-02-18T11:15:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/"},"wordCount":293,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380.jpg","articleSection":["DIPLOMATIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/","name":"Arabie saoudite : les pourparlers entre la Russie et les \u00c9tats-Unis d\u00e9marrent \u00e0 Riyad - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380.jpg","datePublished":"2025-02-18T11:08:36+00:00","dateModified":"2025-02-18T11:15:20+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380.jpg","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/02\/18\/urgent-russie-us-les-pourparlers-a-riyadh-commencent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Arabie saoudite : les pourparlers entre la Russie et les \u00c9tats-Unis d\u00e9marrent \u00e0 Riyad"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/02\/FB_IMG_1739876603380.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/4078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=4078"}],"version-history":[{"count":2,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/4078\/revisions"}],"predecessor-version":[{"id":4082,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/4078\/revisions\/4082"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/4079"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=4078"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=4078"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=4078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}