{"id":3158,"date":"2025-01-14T09:01:59","date_gmt":"2025-01-14T09:01:59","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=3158"},"modified":"2025-01-14T09:03:40","modified_gmt":"2025-01-14T09:03:40","slug":"gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/","title":{"rendered":"Gabon: Le Vice-pr\u00e9sident de la BDEAC en visite \u00e0 Libreville."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le jeudi 09 Janvier 2025, Monsieur Charles M\u2019BA, ministre des Comptes Publics, a re\u00e7u Monsieur Jean Paterne MEGNE EKOGA, Vice-Pr\u00e9sident de la Banque de D\u00e9veloppement des Etats d\u2019 Afrique Centrale (BDEAC) qu\u2019 accompagnait le Repr\u00e9sentant R\u00e9sident au Gabon de l\u2019 Institution, venu principalement partager \u00e0 son h\u00f4te les r\u00e9solutions de l\u2019Assembl\u00e9e G\u00e9n\u00e9rale de la Banque tenue \u00e0 Paris le 3 janvier dernier.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s des \u00e9changes de v\u0153ux pour la nouvelle ann\u00e9e 2025, les deux hommes ont \u00e9voqu\u00e9 les sujets relatifs au partenariat entre le Gabon et la Banque. A cet \u00e9gard, le Vice-Pr\u00e9sident a relay\u00e9 l\u2019 engagement du Pr\u00e9sident de la Banque \u00e0 soutenir les plus hautes autorit\u00e9s dans leur volont\u00e9 d\u2019acc\u00e9l\u00e9rer la transformation structurelle du Gabon.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En retour, Monsieur le ministre a r\u00e9it\u00e9r\u00e9 sa disponibilit\u00e9 et celle des Hautes autorit\u00e9s \u00e0 soutenir la Banque dans sa qu\u00eate de se doter des capacit\u00e9s humaines et financi\u00e8res \u00e0 m\u00eame d\u2019 impacter davantage le d\u00e9veloppement \u00e9conomique et social du Gabon \u00e0 travers notamment, la mise en place des infrastructures de d\u00e9veloppement au profit du bien-\u00eatre des populations.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Source: Communication gouvernementale <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le jeudi 09 Janvier 2025, Monsieur Charles M\u2019BA, ministre des Comptes Publics, a re\u00e7u Monsieur Jean Paterne MEGNE EKOGA, Vice-Pr\u00e9sident de la Banque de D\u00e9veloppement des Etats d\u2019 Afrique Centrale (BDEAC) qu\u2019 accompagnait le Repr\u00e9sentant R\u00e9sident au Gabon de l\u2019 Institution, venu principalement partager \u00e0 son h\u00f4te les r\u00e9solutions de<\/p>\n","protected":false},"author":3,"featured_media":3159,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50],"tags":[],"class_list":["post-3158","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cooperation"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797-300x200.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797-768x511.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797-1024x682.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797-1080x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Le jeudi 09 Janvier 2025, Monsieur Charles M\u2019BA, ministre des Comptes Publics, a re\u00e7u Monsieur Jean Paterne MEGNE EKOGA, Vice-Pr\u00e9sident de la Banque de D\u00e9veloppement des Etats d\u2019 Afrique Centrale (BDEAC) qu\u2019 accompagnait le Repr\u00e9sentant R\u00e9sident au Gabon de l\u2019 Institution, venu principalement partager \u00e0 son h\u00f4te les r\u00e9solutions de","magazineBlocksPostCategories":["COOPERATION"],"magazineBlocksPostViewCount":513,"magazineBlocksPostReadTime":1,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797.jpg",1080,719,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797-300x200.jpg",300,200,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-50\">COOPERATION<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gabon: Le Vice-pr\u00e9sident de la BDEAC en visite \u00e0 Libreville. - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gabon: Le Vice-pr\u00e9sident de la BDEAC en visite \u00e0 Libreville. - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Le jeudi 09 Janvier 2025, Monsieur Charles M\u2019BA, ministre des Comptes Publics, a re\u00e7u Monsieur Jean Paterne MEGNE EKOGA, Vice-Pr\u00e9sident de la Banque de D\u00e9veloppement des Etats d\u2019 Afrique Centrale (BDEAC) qu\u2019 accompagnait le Repr\u00e9sentant R\u00e9sident au Gabon de l\u2019 Institution, venu principalement partager \u00e0 son h\u00f4te les r\u00e9solutions de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-14T09:01:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-14T09:03:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"719\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Gabon: Le Vice-pr\u00e9sident de la BDEAC en visite \u00e0 Libreville.\",\"datePublished\":\"2025-01-14T09:01:59+00:00\",\"dateModified\":\"2025-01-14T09:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/\"},\"wordCount\":209,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797.jpg\",\"articleSection\":[\"COOPERATION\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/\",\"name\":\"Gabon: Le Vice-pr\u00e9sident de la BDEAC en visite \u00e0 Libreville. - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797.jpg\",\"datePublished\":\"2025-01-14T09:01:59+00:00\",\"dateModified\":\"2025-01-14T09:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797.jpg\",\"width\":1080,\"height\":719},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gabon: Le Vice-pr\u00e9sident de la BDEAC en visite \u00e0 Libreville.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gabon: Le Vice-pr\u00e9sident de la BDEAC en visite \u00e0 Libreville. - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/","og_locale":"fr_FR","og_type":"article","og_title":"Gabon: Le Vice-pr\u00e9sident de la BDEAC en visite \u00e0 Libreville. - Cooperation Internationale","og_description":"Le jeudi 09 Janvier 2025, Monsieur Charles M\u2019BA, ministre des Comptes Publics, a re\u00e7u Monsieur Jean Paterne MEGNE EKOGA, Vice-Pr\u00e9sident de la Banque de D\u00e9veloppement des Etats d\u2019 Afrique Centrale (BDEAC) qu\u2019 accompagnait le Repr\u00e9sentant R\u00e9sident au Gabon de l\u2019 Institution, venu principalement partager \u00e0 son h\u00f4te les r\u00e9solutions de","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-01-14T09:01:59+00:00","article_modified_time":"2025-01-14T09:03:40+00:00","og_image":[{"width":1080,"height":719,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Gabon: Le Vice-pr\u00e9sident de la BDEAC en visite \u00e0 Libreville.","datePublished":"2025-01-14T09:01:59+00:00","dateModified":"2025-01-14T09:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/"},"wordCount":209,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797.jpg","articleSection":["COOPERATION"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/","name":"Gabon: Le Vice-pr\u00e9sident de la BDEAC en visite \u00e0 Libreville. - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797.jpg","datePublished":"2025-01-14T09:01:59+00:00","dateModified":"2025-01-14T09:03:40+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797.jpg","width":1080,"height":719},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/01\/14\/gabon-le-vice-president-de-la-bdeac-en-visite-a-libreville\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Gabon: Le Vice-pr\u00e9sident de la BDEAC en visite \u00e0 Libreville."}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/FB_IMG_1736844987797.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/3158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=3158"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/3158\/revisions"}],"predecessor-version":[{"id":3160,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/3158\/revisions\/3160"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/3159"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=3158"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=3158"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=3158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}