{"id":2082,"date":"2024-12-09T19:27:56","date_gmt":"2024-12-09T19:27:56","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=2082"},"modified":"2024-12-09T19:30:43","modified_gmt":"2024-12-09T19:30:43","slug":"energie-reunion-devaluation-des-projets-en-eau-et-en-electricite","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/","title":{"rendered":"Energie: R\u00e9union d&#8217;\u00e9valuation des projets en eau et en \u00e9lectricit\u00e9."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le cadre de la Feuille de Route qui lui a \u00e9t\u00e9 assign\u00e9e par le Pr\u00e9sident de la Transition, Pr\u00e9sident de la R\u00e9publique, Chef de l&#8217;Etat \u00e0 savoir: <strong>&#8221; <em>trouver des solutions durables et pratiques pour un acc\u00e8s \u00e0 l&#8217;eau potable et \u00e0 l&#8217;\u00e9lectricit\u00e9 de tous les m\u00e9nage<\/em>s &#8220;<\/strong>, le Ministre de l&#8217;Energie et des Ressources Hydrauliques, Monsieur Jeannot KALIMA a organis\u00e9 une s\u00e9rie de rencontres avec les entit\u00e9s sous tutelle et les partenaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il a re\u00e7u tour \u00e0 tour:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La Soci\u00e9t\u00e9 de Patrimoine (SP) ;<\/li>\n\n\n\n<li>Le Conseil National de l&#8217;Eau et de l&#8217;Electricit\u00e9 (CNEE) ;<\/li>\n\n\n\n<li>La Soci\u00e9t\u00e9 d&#8217;Electricit\u00e9 de T\u00e9l\u00e9phone et d&#8217;Eau du Gabon (SETEG) ;<\/li>\n\n\n\n<li>La Soci\u00e9t\u00e9 d&#8217;Energie et d&#8217;Eau du Gabon (SEEG);<\/li>\n\n\n\n<li>L&#8217;unit\u00e9 de Coordination du Projet PIAEPAL;<\/li>\n\n\n\n<li>Gabon Power Company (GPC).<\/li>\n<\/ul>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"608\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/1000368546-edited.jpg\" alt=\"\" class=\"wp-image-2088\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/1000368546-edited.jpg 1080w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/1000368546-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/1000368546-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/1000368546-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;objectif \u00e9tait de faire le point sur l&#8217;\u00e9tat d&#8217;avancement des projets en eau et en \u00e9lectricit\u00e9 en cours de r\u00e9alisation et \u00e9ventuellement les perspectives.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au terme de ces rencontres, il est \u00e0 noter que des efforts consid\u00e9rables ont \u00e9t\u00e9 fait dans l&#8217;ex\u00e9cution des diff\u00e9rents chantiers, en d\u00e9pit des difficult\u00e9s rencontr\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Membre du Gouvernement en charge de l&#8217;\u00e9nergie et des ressources hydrauliques a exhort\u00e9 les uns et les autres \u00e0 acc\u00e9l\u00e9rer la cadence en vue d&#8217;une am\u00e9lioration totale de la desserte en eau et en \u00e9lectricit\u00e9 sur l&#8217;ensemble du territoire national.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Source : Communication gouvernementale<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de la Feuille de Route qui lui a \u00e9t\u00e9 assign\u00e9e par le Pr\u00e9sident de la Transition, Pr\u00e9sident de la R\u00e9publique, Chef de l&#8217;Etat \u00e0 savoir: &#8221; trouver des solutions durables et pratiques pour un acc\u00e8s \u00e0 l&#8217;eau potable et \u00e0 l&#8217;\u00e9lectricit\u00e9 de tous les m\u00e9nages &#8220;, le<\/p>\n","protected":false},"author":3,"featured_media":2083,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[58],"tags":[],"class_list":["post-2082","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-national"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225-300x200.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225-768x512.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225-1024x683.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225-1080x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Dans le cadre de la Feuille de Route qui lui a \u00e9t\u00e9 assign\u00e9e par le Pr\u00e9sident de la Transition, Pr\u00e9sident de la R\u00e9publique, Chef de l&#8217;Etat \u00e0 savoir: &#8221; trouver des solutions durables et pratiques pour un acc\u00e8s \u00e0 l&#8217;eau potable et \u00e0 l&#8217;\u00e9lectricit\u00e9 de tous les m\u00e9nages &#8220;, le","magazineBlocksPostCategories":["NATIONAL"],"magazineBlocksPostViewCount":398,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225.jpg",1080,720,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225-300x200.jpg",300,200,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-58\">NATIONAL<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Energie: R\u00e9union d&#039;\u00e9valuation des projets en eau et en \u00e9lectricit\u00e9. - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Energie: R\u00e9union d&#039;\u00e9valuation des projets en eau et en \u00e9lectricit\u00e9. - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Dans le cadre de la Feuille de Route qui lui a \u00e9t\u00e9 assign\u00e9e par le Pr\u00e9sident de la Transition, Pr\u00e9sident de la R\u00e9publique, Chef de l&#8217;Etat \u00e0 savoir: &#8221; trouver des solutions durables et pratiques pour un acc\u00e8s \u00e0 l&#8217;eau potable et \u00e0 l&#8217;\u00e9lectricit\u00e9 de tous les m\u00e9nages &#8220;, le\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-09T19:27:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-09T19:30:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Energie: R\u00e9union d&#8217;\u00e9valuation des projets en eau et en \u00e9lectricit\u00e9.\",\"datePublished\":\"2024-12-09T19:27:56+00:00\",\"dateModified\":\"2024-12-09T19:30:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/\"},\"wordCount\":262,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225.jpg\",\"articleSection\":[\"NATIONAL\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/\",\"name\":\"Energie: R\u00e9union d'\u00e9valuation des projets en eau et en \u00e9lectricit\u00e9. - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225.jpg\",\"datePublished\":\"2024-12-09T19:27:56+00:00\",\"dateModified\":\"2024-12-09T19:30:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225.jpg\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Energie: R\u00e9union d&#8217;\u00e9valuation des projets en eau et en \u00e9lectricit\u00e9.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Energie: R\u00e9union d'\u00e9valuation des projets en eau et en \u00e9lectricit\u00e9. - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/","og_locale":"fr_FR","og_type":"article","og_title":"Energie: R\u00e9union d'\u00e9valuation des projets en eau et en \u00e9lectricit\u00e9. - Cooperation Internationale","og_description":"Dans le cadre de la Feuille de Route qui lui a \u00e9t\u00e9 assign\u00e9e par le Pr\u00e9sident de la Transition, Pr\u00e9sident de la R\u00e9publique, Chef de l&#8217;Etat \u00e0 savoir: &#8221; trouver des solutions durables et pratiques pour un acc\u00e8s \u00e0 l&#8217;eau potable et \u00e0 l&#8217;\u00e9lectricit\u00e9 de tous les m\u00e9nages &#8220;, le","og_url":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2024-12-09T19:27:56+00:00","article_modified_time":"2024-12-09T19:30:43+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Energie: R\u00e9union d&#8217;\u00e9valuation des projets en eau et en \u00e9lectricit\u00e9.","datePublished":"2024-12-09T19:27:56+00:00","dateModified":"2024-12-09T19:30:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/"},"wordCount":262,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225.jpg","articleSection":["NATIONAL"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/","url":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/","name":"Energie: R\u00e9union d'\u00e9valuation des projets en eau et en \u00e9lectricit\u00e9. - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225.jpg","datePublished":"2024-12-09T19:27:56+00:00","dateModified":"2024-12-09T19:30:43+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225.jpg","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/09\/energie-reunion-devaluation-des-projets-en-eau-et-en-electricite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Energie: R\u00e9union d&#8217;\u00e9valuation des projets en eau et en \u00e9lectricit\u00e9."}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733772304225.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/2082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=2082"}],"version-history":[{"count":3,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/2082\/revisions"}],"predecessor-version":[{"id":2090,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/2082\/revisions\/2090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/2083"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=2082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=2082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=2082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}