{"id":1920,"date":"2024-12-02T15:08:28","date_gmt":"2024-12-02T15:08:28","guid":{"rendered":"https:\/\/kind-wu.57-128-124-134.plesk.page\/?p=1920"},"modified":"2024-12-02T15:09:16","modified_gmt":"2024-12-02T15:09:16","slug":"gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/","title":{"rendered":"Gabon-UE: l&#8217;UE accorde une  subvention de 30 millions d&#8217;euros pour la modernisation du Transgabonais."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Apr\u00e8s une s\u00e9rie de rencontres \u00e0 Libreville entre le ministre des Transports, Dieudonn\u00e9 Lo\u00efc Ndinga Moudouma, et l\u2019ambassadrice de l\u2019Union europ\u00e9enne, C\u00e9cile Abadie, un accord historique a \u00e9t\u00e9 sign\u00e9, aboutissant \u00e0 l\u2019octroi d\u2019une subvention de 30 millions d\u2019euros pour la modernisation du Transgabonais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Une subvention est une aide financi\u00e8re accord\u00e9e par une institution publique ou priv\u00e9e pour soutenir des projets d\u2019int\u00e9r\u00eat g\u00e9n\u00e9ral. Contrairement \u00e0 un pr\u00eat, elle n\u2019implique pas de remboursement, ce qui en fait un soutien financier non contraignant pour la partie gabonaise.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le Transgabonais, inaugur\u00e9 en 1978, est le principal r\u00e9seau ferroviaire du Gabon, reliant le port d\u2019Owendo, pr\u00e8s de Libreville, \u00e0 Franceville sur une distance de 669 km. Cette infrastructure constitue un pilier central du transport des marchandises et des passagers \u00e0 l\u2019\u00e9chelle nationale. Cependant, au fil des d\u00e9cennies, elle a souffert d\u2019un manque d\u2019entretien, entra\u00eenant une d\u00e9gradation significative de ses performances et de la s\u00e9curit\u00e9 des voyageurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le plan de remise \u00e0 niveau vise \u00e0 moderniser cette ligne ferroviaire essentielle, en rempla\u00e7ant les infrastructures obsol\u00e8tes, en am\u00e9liorant la s\u00e9curit\u00e9 et en augmentant la capacit\u00e9 de transport. La subvention de l\u2019Union europ\u00e9enne constitue une contribution majeure \u00e0 ce projet ambitieux, refl\u00e9tant l\u2019engagement de l\u2019UE \u00e0 soutenir le d\u00e9veloppement des infrastructures en Afrique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En accordant cette subvention, l\u2019Union europ\u00e9enne r\u00e9affirme son appui \u00e0 la transition gabonaise, saluant les efforts entrepris pour moderniser les infrastructures et impulser une nouvelle dynamique \u00e9conomique mettant en lumi\u00e8re des efforts qui portent d\u00e9j\u00e0 leurs fruits.<br>Cette \u00e9tape marque un tournant majeur dans la coop\u00e9ration entre le Gabon et l\u2019Union europ\u00e9enne, favorisant une transformation durable du secteur des transports tout en consolidant les relations entre les deux partenaires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Source : Service Com minist\u00e8re des transports.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s une s\u00e9rie de rencontres \u00e0 Libreville entre le ministre des Transports, Dieudonn\u00e9 Lo\u00efc Ndinga Moudouma, et l\u2019ambassadrice de l\u2019Union europ\u00e9enne, C\u00e9cile Abadie, un accord historique a \u00e9t\u00e9 sign\u00e9, aboutissant \u00e0 l\u2019octroi d\u2019une subvention de 30 millions d\u2019euros pour la modernisation du Transgabonais. Une subvention est une aide financi\u00e8re accord\u00e9e<\/p>\n","protected":false},"author":3,"featured_media":1921,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[57],"tags":[],"class_list":["post-1920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-transport"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115-300x150.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115-768x384.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115-1024x512.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Apr\u00e8s une s\u00e9rie de rencontres \u00e0 Libreville entre le ministre des Transports, Dieudonn\u00e9 Lo\u00efc Ndinga Moudouma, et l\u2019ambassadrice de l\u2019Union europ\u00e9enne, C\u00e9cile Abadie, un accord historique a \u00e9t\u00e9 sign\u00e9, aboutissant \u00e0 l\u2019octroi d\u2019une subvention de 30 millions d\u2019euros pour la modernisation du Transgabonais. Une subvention est une aide financi\u00e8re accord\u00e9e","magazineBlocksPostCategories":["TRANSPORT"],"magazineBlocksPostViewCount":402,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg",1080,540,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115-300x150.jpg",300,150,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-57\">TRANSPORT<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gabon-UE: l&#039;UE accorde une subvention de 30 millions d&#039;euros pour la modernisation du Transgabonais. - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gabon-UE: l&#039;UE accorde une subvention de 30 millions d&#039;euros pour la modernisation du Transgabonais. - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s une s\u00e9rie de rencontres \u00e0 Libreville entre le ministre des Transports, Dieudonn\u00e9 Lo\u00efc Ndinga Moudouma, et l\u2019ambassadrice de l\u2019Union europ\u00e9enne, C\u00e9cile Abadie, un accord historique a \u00e9t\u00e9 sign\u00e9, aboutissant \u00e0 l\u2019octroi d\u2019une subvention de 30 millions d\u2019euros pour la modernisation du Transgabonais. Une subvention est une aide financi\u00e8re accord\u00e9e\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-02T15:08:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-02T15:09:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"540\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Gabon-UE: l&#8217;UE accorde une subvention de 30 millions d&#8217;euros pour la modernisation du Transgabonais.\",\"datePublished\":\"2024-12-02T15:08:28+00:00\",\"dateModified\":\"2024-12-02T15:09:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/\"},\"wordCount\":331,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg\",\"articleSection\":[\"TRANSPORT\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/\",\"name\":\"Gabon-UE: l'UE accorde une subvention de 30 millions d'euros pour la modernisation du Transgabonais. - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg\",\"datePublished\":\"2024-12-02T15:08:28+00:00\",\"dateModified\":\"2024-12-02T15:09:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg\",\"width\":1080,\"height\":540},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gabon-UE: l&rsquo;UE accorde une subvention de 30 millions d&rsquo;euros pour la modernisation du Transgabonais.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gabon-UE: l'UE accorde une subvention de 30 millions d'euros pour la modernisation du Transgabonais. - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/","og_locale":"fr_FR","og_type":"article","og_title":"Gabon-UE: l'UE accorde une subvention de 30 millions d'euros pour la modernisation du Transgabonais. - Cooperation Internationale","og_description":"Apr\u00e8s une s\u00e9rie de rencontres \u00e0 Libreville entre le ministre des Transports, Dieudonn\u00e9 Lo\u00efc Ndinga Moudouma, et l\u2019ambassadrice de l\u2019Union europ\u00e9enne, C\u00e9cile Abadie, un accord historique a \u00e9t\u00e9 sign\u00e9, aboutissant \u00e0 l\u2019octroi d\u2019une subvention de 30 millions d\u2019euros pour la modernisation du Transgabonais. Une subvention est une aide financi\u00e8re accord\u00e9e","og_url":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2024-12-02T15:08:28+00:00","article_modified_time":"2024-12-02T15:09:16+00:00","og_image":[{"width":1080,"height":540,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Gabon-UE: l&#8217;UE accorde une subvention de 30 millions d&#8217;euros pour la modernisation du Transgabonais.","datePublished":"2024-12-02T15:08:28+00:00","dateModified":"2024-12-02T15:09:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/"},"wordCount":331,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg","articleSection":["TRANSPORT"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/","url":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/","name":"Gabon-UE: l'UE accorde une subvention de 30 millions d'euros pour la modernisation du Transgabonais. - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg","datePublished":"2024-12-02T15:08:28+00:00","dateModified":"2024-12-02T15:09:16+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg","width":1080,"height":540},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/gabon-ue-lue-accorde-une-subvention-de-30-millions-deuros-pour-la-modernisation-du-transgabonais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Gabon-UE: l&rsquo;UE accorde une subvention de 30 millions d&rsquo;euros pour la modernisation du Transgabonais."}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/FB_IMG_1733151773115.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=1920"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1920\/revisions"}],"predecessor-version":[{"id":1922,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1920\/revisions\/1922"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/1921"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=1920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=1920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=1920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}