{"id":1906,"date":"2024-12-02T14:34:43","date_gmt":"2024-12-02T14:34:43","guid":{"rendered":"https:\/\/kind-wu.57-128-124-134.plesk.page\/?p=1906"},"modified":"2024-12-02T14:34:44","modified_gmt":"2024-12-02T14:34:44","slug":"centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/","title":{"rendered":"Centrafrique :  Le Communiqu\u00e9 de l&#8217;Accord financi\u00e8re d&#8217;aide budg\u00e9taire avec la France."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Signature de la convention financi\u00e8re d&#8217;aide budg\u00e9taire global entre la R\u00e9publique Centrafricaine et la R\u00e9publique Fran\u00e7aise en date du 13 novembre 2024.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"772\" height=\"1024\" src=\"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/12\/1000352230-772x1024.jpg\" alt=\"\" class=\"wp-image-1907\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/1000352230-772x1024.jpg 772w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/1000352230-226x300.jpg 226w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/1000352230-768x1019.jpg 768w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/1000352230.jpg 1080w\" sizes=\"auto, (max-width: 772px) 100vw, 772px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/12\/1000352231-768x1024.jpg\" alt=\"\" class=\"wp-image-1908\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/1000352231-768x1024.jpg 768w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/1000352231-225x300.jpg 225w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/1000352231.jpg 1080w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Source: Minist\u00e8re centrafricain de la Communication.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Signature de la convention financi\u00e8re d&#8217;aide budg\u00e9taire global entre la R\u00e9publique Centrafricaine et la R\u00e9publique Fran\u00e7aise en date du 13 novembre 2024. Source: Minist\u00e8re centrafricain de la Communication.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[50],"tags":[],"class_list":["post-1906","post","type-post","status-publish","format-standard","hentry","category-cooperation"],"magazineBlocksPostFeaturedMedia":{"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"colormag-highlighted-post":false,"colormag-featured-post-medium":false,"colormag-featured-post-small":false,"colormag-featured-image":false,"colormag-default-news":false,"colormag-featured-image-large":false},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Signature de la convention financi\u00e8re d&#8217;aide budg\u00e9taire global entre la R\u00e9publique Centrafricaine et la R\u00e9publique Fran\u00e7aise en date du 13 novembre 2024. Source: Minist\u00e8re centrafricain de la Communication.","magazineBlocksPostCategories":["COOPERATION"],"magazineBlocksPostViewCount":395,"magazineBlocksPostReadTime":1,"magazine_blocks_featured_image_url":{"full":false,"medium":false,"thumbnail":false},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-50\">COOPERATION<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Centrafrique : Le Communiqu\u00e9 de l&#039;Accord financi\u00e8re d&#039;aide budg\u00e9taire avec la France. - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centrafrique : Le Communiqu\u00e9 de l&#039;Accord financi\u00e8re d&#039;aide budg\u00e9taire avec la France. - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Signature de la convention financi\u00e8re d&#8217;aide budg\u00e9taire global entre la R\u00e9publique Centrafricaine et la R\u00e9publique Fran\u00e7aise en date du 13 novembre 2024. Source: Minist\u00e8re centrafricain de la Communication.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-02T14:34:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-02T14:34:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/12\/1000352230-772x1024.jpg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Centrafrique : Le Communiqu\u00e9 de l&#8217;Accord financi\u00e8re d&#8217;aide budg\u00e9taire avec la France.\",\"datePublished\":\"2024-12-02T14:34:43+00:00\",\"dateModified\":\"2024-12-02T14:34:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/\"},\"wordCount\":48,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/12\/1000352230-772x1024.jpg\",\"articleSection\":[\"COOPERATION\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/\",\"name\":\"Centrafrique : Le Communiqu\u00e9 de l'Accord financi\u00e8re d'aide budg\u00e9taire avec la France. - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/12\/1000352230-772x1024.jpg\",\"datePublished\":\"2024-12-02T14:34:43+00:00\",\"dateModified\":\"2024-12-02T14:34:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/#primaryimage\",\"url\":\"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/12\/1000352230-772x1024.jpg\",\"contentUrl\":\"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/12\/1000352230-772x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centrafrique : Le Communiqu\u00e9 de l&rsquo;Accord financi\u00e8re d&rsquo;aide budg\u00e9taire avec la France.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centrafrique : Le Communiqu\u00e9 de l'Accord financi\u00e8re d'aide budg\u00e9taire avec la France. - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/","og_locale":"fr_FR","og_type":"article","og_title":"Centrafrique : Le Communiqu\u00e9 de l'Accord financi\u00e8re d'aide budg\u00e9taire avec la France. - Cooperation Internationale","og_description":"Signature de la convention financi\u00e8re d&#8217;aide budg\u00e9taire global entre la R\u00e9publique Centrafricaine et la R\u00e9publique Fran\u00e7aise en date du 13 novembre 2024. Source: Minist\u00e8re centrafricain de la Communication.","og_url":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2024-12-02T14:34:43+00:00","article_modified_time":"2024-12-02T14:34:44+00:00","og_image":[{"url":"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/12\/1000352230-772x1024.jpg","type":"","width":"","height":""}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Centrafrique : Le Communiqu\u00e9 de l&#8217;Accord financi\u00e8re d&#8217;aide budg\u00e9taire avec la France.","datePublished":"2024-12-02T14:34:43+00:00","dateModified":"2024-12-02T14:34:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/"},"wordCount":48,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/#primaryimage"},"thumbnailUrl":"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/12\/1000352230-772x1024.jpg","articleSection":["COOPERATION"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/","url":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/","name":"Centrafrique : Le Communiqu\u00e9 de l'Accord financi\u00e8re d'aide budg\u00e9taire avec la France. - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/#primaryimage"},"thumbnailUrl":"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/12\/1000352230-772x1024.jpg","datePublished":"2024-12-02T14:34:43+00:00","dateModified":"2024-12-02T14:34:44+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/#primaryimage","url":"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/12\/1000352230-772x1024.jpg","contentUrl":"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/12\/1000352230-772x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/12\/02\/centrafrique-le-communique-de-laccord-financiere-daide-budgetaire-avec-la-france\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Centrafrique : Le Communiqu\u00e9 de l&rsquo;Accord financi\u00e8re d&rsquo;aide budg\u00e9taire avec la France."}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=1906"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1906\/revisions"}],"predecessor-version":[{"id":1909,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1906\/revisions\/1909"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=1906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=1906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=1906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}