{"id":1478,"date":"2024-11-24T14:42:21","date_gmt":"2024-11-24T14:42:21","guid":{"rendered":"https:\/\/kind-wu.57-128-124-134.plesk.page\/?p=1478"},"modified":"2024-11-24T14:45:28","modified_gmt":"2024-11-24T14:45:28","slug":"cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/","title":{"rendered":"Mali#cop29Baku: Amadou SAMAKE et ses homologues animent un panel de haut niveau sur la protection des bassins fluviaux"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/11\/1000334278-1024x768.jpg\" alt=\"\" class=\"wp-image-1479\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/1000334278-1024x768.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/1000334278-300x225.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/1000334278-768x576.jpg 768w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/1000334278.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En marge de la COP29 sur les Changements climatiques et \u00e0 l&#8217;initiative de l&#8217;OMVS, le ministre de l\u2019environnement, de l&#8217;assainissement et du d\u00e9veloppement durable, M. Mamadou SAMAKE a co-anim\u00e9, avec ses homologues de la Guin\u00e9e et du S\u00e9n\u00e9gal, un panel de haut niveau sur la protection des bassins fluviaux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Mme le ministre de la Guin\u00e9e a partag\u00e9 l&#8217;exp\u00e9rience de son pays sur la protection et la pr\u00e9servation des immenses richesses du Fouta Djallon. Quant au ministre s\u00e9n\u00e9galais, il a entretenu l&#8217;assistance sur l&#8217;exceptionnelle mont\u00e9e des eaux dans la r\u00e9gion de Bakel o\u00f9 l&#8217;\u00e9tat d\u00e9ploie de nos jours des efforts colossaux pour prot\u00e9ger et soulager les populations.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/11\/1000334279-1024x768.jpg\" alt=\"\" class=\"wp-image-1480\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/1000334279-1024x768.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/1000334279-300x225.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/1000334279-768x576.jpg 768w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/1000334279.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Quand au ministre Mamadou SAMAKE, il a tir\u00e9 la sonnette d&#8217;alarme sur le cas de la Faleme, bras du fleuve S\u00e9n\u00e9gal, aujourd&#8217;hui, menac\u00e9e de disparition.Le ministre SAMAKE a rappel\u00e9 le nouveau Code minier du Mali qui interdit purement et simplement les dragages sur l&#8217;ensemble des cours d&#8217;eau, y compris la Faleme.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Le ministre SAMAKE a \u00e9galement rappel\u00e9 les efforts d\u00e9ploy\u00e9s par les services des Eaux et For\u00eats qui m\u00e8nent une lutte implacable contre ceux qui exploitent, de fa\u00e7on illicite, les ressources de notre sous-sol tout en d\u00e9truisant notre couvert v\u00e9g\u00e9tal.<br>Afin de sauver la Faleme, le ministre SAMAKE propose la mise en place d&#8217;un projet de sauvetage de ce bras du fleuve S\u00e9n\u00e9gal dans le cadre de L&#8217;OMVS.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u00c9galement, il a mis l&#8217;accent sur la coop\u00e9ration transfrontaliere entre le Mali, le S\u00e9n\u00e9gal et la Mauritanie car lorsque ces exploitants ill\u00e9gaux sont traqu\u00e9s du c\u00f4t\u00e9 S\u00e9n\u00e9gal, ils viennent se cacher c\u00f4t\u00e9s malien et mauritanien et vis versa.Le ministre SAMAKE propose jusqu&#8217;au droit de poursuite dans cette lutte contre l&#8217;exploitation ill\u00e9gale des ressources naturelles.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En marge de la COP29 sur les Changements climatiques et \u00e0 l&#8217;initiative de l&#8217;OMVS, le ministre de l\u2019environnement, de l&#8217;assainissement et du d\u00e9veloppement durable, M. Mamadou SAMAKE a co-anim\u00e9, avec ses homologues de la Guin\u00e9e et du S\u00e9n\u00e9gal, un panel de haut niveau sur la protection des bassins fluviaux. Mme<\/p>\n","protected":false},"author":3,"featured_media":1481,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11],"tags":[],"class_list":["post-1478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecologie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762-300x225.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762-768x576.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762-1024x768.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762-1080x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"En marge de la COP29 sur les Changements climatiques et \u00e0 l&#8217;initiative de l&#8217;OMVS, le ministre de l\u2019environnement, de l&#8217;assainissement et du d\u00e9veloppement durable, M. Mamadou SAMAKE a co-anim\u00e9, avec ses homologues de la Guin\u00e9e et du S\u00e9n\u00e9gal, un panel de haut niveau sur la protection des bassins fluviaux. Mme","magazineBlocksPostCategories":["ECOLOGIE"],"magazineBlocksPostViewCount":381,"magazineBlocksPostReadTime":2,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762.jpg",1080,810,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762-300x225.jpg",300,225,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-11\">ECOLOGIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mali#cop29Baku: Amadou SAMAKE et ses homologues animent un panel de haut niveau sur la protection des bassins fluviaux - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mali#cop29Baku: Amadou SAMAKE et ses homologues animent un panel de haut niveau sur la protection des bassins fluviaux - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"En marge de la COP29 sur les Changements climatiques et \u00e0 l&#8217;initiative de l&#8217;OMVS, le ministre de l\u2019environnement, de l&#8217;assainissement et du d\u00e9veloppement durable, M. Mamadou SAMAKE a co-anim\u00e9, avec ses homologues de la Guin\u00e9e et du S\u00e9n\u00e9gal, un panel de haut niveau sur la protection des bassins fluviaux. Mme\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-24T14:42:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-24T14:45:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Mali#cop29Baku: Amadou SAMAKE et ses homologues animent un panel de haut niveau sur la protection des bassins fluviaux\",\"datePublished\":\"2024-11-24T14:42:21+00:00\",\"dateModified\":\"2024-11-24T14:45:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/\"},\"wordCount\":353,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762.jpg\",\"articleSection\":[\"ECOLOGIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/\",\"name\":\"Mali#cop29Baku: Amadou SAMAKE et ses homologues animent un panel de haut niveau sur la protection des bassins fluviaux - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762.jpg\",\"datePublished\":\"2024-11-24T14:42:21+00:00\",\"dateModified\":\"2024-11-24T14:45:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762.jpg\",\"width\":1080,\"height\":810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mali#cop29Baku: Amadou SAMAKE et ses homologues animent un panel de haut niveau sur la protection des bassins fluviaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mali#cop29Baku: Amadou SAMAKE et ses homologues animent un panel de haut niveau sur la protection des bassins fluviaux - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/","og_locale":"fr_FR","og_type":"article","og_title":"Mali#cop29Baku: Amadou SAMAKE et ses homologues animent un panel de haut niveau sur la protection des bassins fluviaux - Cooperation Internationale","og_description":"En marge de la COP29 sur les Changements climatiques et \u00e0 l&#8217;initiative de l&#8217;OMVS, le ministre de l\u2019environnement, de l&#8217;assainissement et du d\u00e9veloppement durable, M. Mamadou SAMAKE a co-anim\u00e9, avec ses homologues de la Guin\u00e9e et du S\u00e9n\u00e9gal, un panel de haut niveau sur la protection des bassins fluviaux. Mme","og_url":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2024-11-24T14:42:21+00:00","article_modified_time":"2024-11-24T14:45:28+00:00","og_image":[{"width":1080,"height":810,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Mali#cop29Baku: Amadou SAMAKE et ses homologues animent un panel de haut niveau sur la protection des bassins fluviaux","datePublished":"2024-11-24T14:42:21+00:00","dateModified":"2024-11-24T14:45:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/"},"wordCount":353,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762.jpg","articleSection":["ECOLOGIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/","url":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/","name":"Mali#cop29Baku: Amadou SAMAKE et ses homologues animent un panel de haut niveau sur la protection des bassins fluviaux - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762.jpg","datePublished":"2024-11-24T14:42:21+00:00","dateModified":"2024-11-24T14:45:28+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762.jpg","width":1080,"height":810},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/24\/cop29baku-amadou-samake-anime-un-panel-de-haut-niveau-sur-la-protection-des-bassins-fluviaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Mali#cop29Baku: Amadou SAMAKE et ses homologues animent un panel de haut niveau sur la protection des bassins fluviaux"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/FB_IMG_1732458937762.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=1478"}],"version-history":[{"count":2,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1478\/revisions"}],"predecessor-version":[{"id":1485,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1478\/revisions\/1485"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/1481"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=1478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=1478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=1478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}