{"id":1377,"date":"2024-11-19T11:29:41","date_gmt":"2024-11-19T11:29:41","guid":{"rendered":"https:\/\/kind-wu.57-128-124-134.plesk.page\/?p=1377"},"modified":"2024-11-19T11:29:42","modified_gmt":"2024-11-19T11:29:42","slug":"cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/","title":{"rendered":"COP16 sur la biodiversit\u00e9 : accords historiques sur les donn\u00e9es g\u00e9n\u00e9tiques, les autochtones et personnes d\u2019ascendance africaine"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Le plus grand sommet mondial sur la biodiversit\u00e9, COP16, s&#8217;est achev\u00e9 ce week-end en Colombie, avec la prise de plusieurs d\u00e9cisions historiques, dont les premiers accords sur les donn\u00e9es g\u00e9n\u00e9tiques de la nature et sur la reconnaissance des personnes d&#8217;ascendance africaine et des peuples autochtones en tant que responsables cl\u00e9s des efforts de conservation.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Il s&#8217;agit d&#8217;un \u00e9v\u00e9nement sans pr\u00e9c\u00e9dent dans l&#8217;histoire des accords multilat\u00e9raux sur l&#8217;environnement&nbsp;\u00bb, a d\u00e9clar\u00e9 \u00e0&nbsp;<em>ONU Info&nbsp;<\/em>Camila Paz Romero, porte-parole des peuples autochtones au sommet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Les peuples autochtones et les communaut\u00e9s locales du monde entier &#8211; li\u00e9s par nos syst\u00e8mes de connaissances en mati\u00e8re de protection de la vie et de la biodiversit\u00e9 &#8211; se souviennent du long chemin que nous avons parcouru pour parvenir \u00e0 cet accord \u00bb, a-t-elle ajout\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les efforts d\u00e9ploy\u00e9s pour obtenir un si\u00e8ge \u00e0 la table des n\u00e9gociations se sont \u00e9tendus sur trois d\u00e9cennies.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c0 Cali, le 16e Conf\u00e9rence des parties \u00e0 la Convention des Nations Unies sur la diversit\u00e9 biologique a pris fin apr\u00e8s 12 jours de discussions intenses entre 170 d\u00e9l\u00e9gations, selon le minist\u00e8re colombien de l&#8217;Environnement et du d\u00e9veloppement durable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;objectif principal de la Convention, adopt\u00e9e par 196 pays en 1992, est de promouvoir des mesures qui conduisent \u00e0 un avenir durable.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"464\" src=\"https:\/\/kind-wu.57-128-124-134.plesk.page\/wp-content\/uploads\/2024\/11\/image1170x530cropped-1024x464.jpg\" alt=\"\" class=\"wp-image-1378\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1170x530cropped-1024x464.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1170x530cropped-300x136.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1170x530cropped-768x348.jpg 768w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1170x530cropped.jpg 1170w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Une r\u00e9f\u00e9rence pour le monde<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un accord a \u00e9t\u00e9 conclu apr\u00e8s de longs d\u00e9bats et discussions \u00e0 la fin de la COP16, reconnaissant les peuples autochtones, les personnes d&#8217;ascendance africaine et leurs communaut\u00e9s en tant que protagonistes de la conservation de la biodiversit\u00e9, tout en d\u00e9cidant de cr\u00e9er un organe subsidiaire pour eux en vertu de l&#8217;article 8J de la Convention.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab Ce nouvel organe subsidiaire est une r\u00e9f\u00e9rence pour le reste du monde, dans laquelle les parties reconnaissent la n\u00e9cessit\u00e9 permanente de notre participation pleine et effective, de nos connaissances, de nos innovations, de nos technologies et de nos pratiques traditionnelles pour atteindre les objectifs de la Convention \u00bb, a soulign\u00e9 Mme Paz.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cette disposition pr\u00e9voit notamment que chaque pays signataire respecte, pr\u00e9serve et maintient les connaissances, innovations et pratiques des communaut\u00e9s autochtones et locales qui incarnent des modes de vie traditionnels pr\u00e9sentant un int\u00e9r\u00eat pour la conservation et l&#8217;utilisation durable de la diversit\u00e9 biologique.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>De nouveaux pouvoirs de d\u00e9cision<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le tout nouvel organe subsidiaire se traduit par un espace permanent permettant aux peuples autochtones et aux communaut\u00e9s locales de participer \u00e0 la prise de d\u00e9cision en mati\u00e8re de biodiversit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cet espace permettra \u00e9galement de renforcer le dialogue entre les pays et les peuples autochtones et les communaut\u00e9s locales afin de d\u00e9finir des actions contribuant \u00e0 la protection de la nature.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les deux autres organes subsidiaires pr\u00e9sents \u00e0 la COP16 sont l&#8217;organe consultatif scientifique, technique et technologique, qui r\u00e9alise des \u00e9valuations de l&#8217;\u00e9tat de la biodiversit\u00e9, et la branche mise en \u0153uvre, qui formule des recommandations sur les aspects techniques et scientifiques de la mise en \u0153uvre de la Convention.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Le Fonds de Cali pour les donn\u00e9es g\u00e9n\u00e9tiques de la nature<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Autre premi\u00e8re, les d\u00e9l\u00e9gu\u00e9s \u00e0 la COP16 ont d\u00e9cid\u00e9 de cr\u00e9er un fonds mondial destin\u00e9 \u00e0 collecter les ressources \u00e9conomiques provenant de l&#8217;utilisation des informations sur les s\u00e9quences num\u00e9riques &#8211; codes g\u00e9n\u00e9tiques provenant d&#8217;\u00e9chantillons d&#8217;organismes qui sont souvent partag\u00e9s num\u00e9riquement &#8211; et \u00e0 les distribuer de mani\u00e8re juste et \u00e9quitable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainsi, les entreprises qui utilisent ces informations pour d\u00e9velopper des produits devront affecter une partie de leurs b\u00e9n\u00e9fices \u00e0 ce qui est appel\u00e9 le Fonds de Cali, dont les ressources seront allou\u00e9es aux peuples autochtones et aux communaut\u00e9s locales, directement ou par l&#8217;interm\u00e9diaire des gouvernements.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le partage des b\u00e9n\u00e9fices tiendra \u00e9galement compte de crit\u00e8res tels que les besoins nationaux en mati\u00e8re de conservation et la richesse de la biodiversit\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Deux questions \u00e0 suivre<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Toutefois, deux questions sont rest\u00e9es en suspens, toutes deux d\u00e9terminantes pour la mise en \u0153uvre du Cadre mondial pour la biodiversit\u00e9 de Kunming-Montr\u00e9al, un plan mondial adopt\u00e9 lors de la COP15 au Canada en vue de stopper et d&#8217;inverser l&#8217;\u00e9rosion de la biodiversit\u00e9 d&#8217;ici \u00e0 2030.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;une d&#8217;entre elles est l&#8217;absence de d\u00e9finition d&#8217;un mod\u00e8le de financement permettant de concr\u00e9tiser le plan de protection de la biodiversit\u00e9. Selon les calculs, environ 700 milliards de dollars sont n\u00e9cessaires pour mettre en \u0153uvre le cadre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;autre question en suspens est celle d&#8217;un m\u00e9canisme de suivi permettant de mesurer les progr\u00e8s accomplis par les pays dans la mise en \u0153uvre de la feuille de route pour la protection de la biodiversit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les discussions sur ces questions ont \u00e9t\u00e9 suspendues \u00e0 la fin du sommet, parce qu\u2019il n\u2019y avait plus assez de n\u00e9gociateurs pr\u00e9sents pour parvenir \u00e0 un accord.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>La COP des peuples<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Une \u00ab zone verte \u00bb a \u00e9t\u00e9 cr\u00e9\u00e9e sn marge du sommet pour les groupes de la soci\u00e9t\u00e9 civile, selon la ministre colombienne de l&#8217;Environnement, Susana Muhamad, qui a signal\u00e9 que quelques 40.000 personnes ont particip\u00e9 aux activit\u00e9s connexes et que la zone a attir\u00e9 environ un million de visites.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab En bref, cela a \u00e9t\u00e9 la COP du peuple \u00bb, a d\u00e9clar\u00e9 Mme Muhamad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La coalition \u00ab paix avec la nature \u00bb a \u00e9t\u00e9 mise en place et il a \u00e9t\u00e9 possible de mobiliser la campagne d&#8217;\u00e9ducation peut-\u00eatre la plus importante de l&#8217;histoire de la Colombie et de voir tant de gens s&#8217;enthousiasmer pour la biodiversit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Source: Nations-Unies<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le plus grand sommet mondial sur la biodiversit\u00e9, COP16, s&#8217;est achev\u00e9 ce week-end en Colombie, avec la prise de plusieurs d\u00e9cisions historiques, dont les premiers accords sur les donn\u00e9es g\u00e9n\u00e9tiques de la nature et sur la reconnaissance des personnes d&#8217;ascendance africaine et des peuples autochtones en tant que responsables cl\u00e9s<\/p>\n","protected":false},"author":3,"featured_media":1379,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[11],"tags":[],"class_list":["post-1377","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ecologie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768-300x200.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768-768x512.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768-1024x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Le plus grand sommet mondial sur la biodiversit\u00e9, COP16, s&#8217;est achev\u00e9 ce week-end en Colombie, avec la prise de plusieurs d\u00e9cisions historiques, dont les premiers accords sur les donn\u00e9es g\u00e9n\u00e9tiques de la nature et sur la reconnaissance des personnes d&#8217;ascendance africaine et des peuples autochtones en tant que responsables cl\u00e9s","magazineBlocksPostCategories":["ECOLOGIE"],"magazineBlocksPostViewCount":411,"magazineBlocksPostReadTime":5,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg",1024,682,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768-300x200.jpg",300,200,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-11\">ECOLOGIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>COP16 sur la biodiversit\u00e9 : accords historiques sur les donn\u00e9es g\u00e9n\u00e9tiques, les autochtones et personnes d\u2019ascendance africaine - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COP16 sur la biodiversit\u00e9 : accords historiques sur les donn\u00e9es g\u00e9n\u00e9tiques, les autochtones et personnes d\u2019ascendance africaine - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Le plus grand sommet mondial sur la biodiversit\u00e9, COP16, s&#8217;est achev\u00e9 ce week-end en Colombie, avec la prise de plusieurs d\u00e9cisions historiques, dont les premiers accords sur les donn\u00e9es g\u00e9n\u00e9tiques de la nature et sur la reconnaissance des personnes d&#8217;ascendance africaine et des peuples autochtones en tant que responsables cl\u00e9s\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-19T11:29:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-19T11:29:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"COP16 sur la biodiversit\u00e9 : accords historiques sur les donn\u00e9es g\u00e9n\u00e9tiques, les autochtones et personnes d\u2019ascendance africaine\",\"datePublished\":\"2024-11-19T11:29:41+00:00\",\"dateModified\":\"2024-11-19T11:29:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/\"},\"wordCount\":982,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg\",\"articleSection\":[\"ECOLOGIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/\",\"name\":\"COP16 sur la biodiversit\u00e9 : accords historiques sur les donn\u00e9es g\u00e9n\u00e9tiques, les autochtones et personnes d\u2019ascendance africaine - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg\",\"datePublished\":\"2024-11-19T11:29:41+00:00\",\"dateModified\":\"2024-11-19T11:29:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg\",\"width\":1024,\"height\":682,\"caption\":\"UN Biodiversity Une participante \u00e0 la COP16 \u00e0 Cali, Colombie, lors de la pl\u00e9ni\u00e8re du 1er novembre 2024.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"COP16 sur la biodiversit\u00e9 : accords historiques sur les donn\u00e9es g\u00e9n\u00e9tiques, les autochtones et personnes d\u2019ascendance africaine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COP16 sur la biodiversit\u00e9 : accords historiques sur les donn\u00e9es g\u00e9n\u00e9tiques, les autochtones et personnes d\u2019ascendance africaine - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/","og_locale":"fr_FR","og_type":"article","og_title":"COP16 sur la biodiversit\u00e9 : accords historiques sur les donn\u00e9es g\u00e9n\u00e9tiques, les autochtones et personnes d\u2019ascendance africaine - Cooperation Internationale","og_description":"Le plus grand sommet mondial sur la biodiversit\u00e9, COP16, s&#8217;est achev\u00e9 ce week-end en Colombie, avec la prise de plusieurs d\u00e9cisions historiques, dont les premiers accords sur les donn\u00e9es g\u00e9n\u00e9tiques de la nature et sur la reconnaissance des personnes d&#8217;ascendance africaine et des peuples autochtones en tant que responsables cl\u00e9s","og_url":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2024-11-19T11:29:41+00:00","article_modified_time":"2024-11-19T11:29:42+00:00","og_image":[{"width":1024,"height":682,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"COP16 sur la biodiversit\u00e9 : accords historiques sur les donn\u00e9es g\u00e9n\u00e9tiques, les autochtones et personnes d\u2019ascendance africaine","datePublished":"2024-11-19T11:29:41+00:00","dateModified":"2024-11-19T11:29:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/"},"wordCount":982,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg","articleSection":["ECOLOGIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/","url":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/","name":"COP16 sur la biodiversit\u00e9 : accords historiques sur les donn\u00e9es g\u00e9n\u00e9tiques, les autochtones et personnes d\u2019ascendance africaine - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg","datePublished":"2024-11-19T11:29:41+00:00","dateModified":"2024-11-19T11:29:42+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg","width":1024,"height":682,"caption":"UN Biodiversity Une participante \u00e0 la COP16 \u00e0 Cali, Colombie, lors de la pl\u00e9ni\u00e8re du 1er novembre 2024."},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/11\/19\/cop16-sur-la-biodiversite-accords-historiques-sur-les-donnees-genetiques-les-autochtones-et-personnes-dascendance-africaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"COP16 sur la biodiversit\u00e9 : accords historiques sur les donn\u00e9es g\u00e9n\u00e9tiques, les autochtones et personnes d\u2019ascendance africaine"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/11\/image1024x768.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=1377"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1377\/revisions"}],"predecessor-version":[{"id":1380,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1377\/revisions\/1380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/1379"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=1377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=1377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=1377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}