{"id":1083,"date":"2024-10-24T11:07:24","date_gmt":"2024-10-24T11:07:24","guid":{"rendered":"https:\/\/kind-wu.57-128-124-134.plesk.page\/?p=1083"},"modified":"2025-01-01T19:58:49","modified_gmt":"2025-01-01T19:58:49","slug":"se-m-shin-song-bum-ambassadeur-de-coree-au-gabon","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/","title":{"rendered":"SE.M. SHIN SONG BUM, Ambassadeur de Cor\u00e9e au Gabon"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">L\u2019exp\u00e9rience Cor\u00e9enne en mati\u00e8re de d\u00e9mocratisation et de d\u00e9veloppement sera d\u2019une grande aide au Gabon.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A la t\u00eate de la mission diplomatique de la R\u00e9publique de Cor\u00e9e depuis un an, SE SHIN SONG BUM, ambassadeur de Cor\u00e9e au Gabon nous a accord\u00e9 cette interview exclusive express. M. SHIN s\u2019est prononc\u00e9 sur l\u2019\u00e9volution de la relation bilat\u00e9rale entre le Gabon et la Cor\u00e9e. Pour lui, l\u2019exp\u00e9rience Cor\u00e9enne en mati\u00e8re de d\u00e9mocratisation et de croissance \u00e9conomique au cours des derni\u00e8res d\u00e9cennies peut \u00eatre un atout pr\u00e9cieux pour le Gabon qui ouvre une nouvelle \u00e8re d\u2019espoir par les r\u00e9formes. Un entretien conduit par Brice NDONG pour Coop\u00e9ration Internationale (C.I) Journal<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C.I&nbsp;: Quel historique des relations entre le Gabon et le Cor\u00e9e&nbsp;?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ambassadeur SHIN&nbsp;: Bien que la Cor\u00e9e et le Gabon soient \u00e9loign\u00e9s g\u00e9ographiquement, leurs relations bilat\u00e9rales ont \u00e9t\u00e9 \u00e9tablies le 1er octobre 1962. Depuis lors, les deux pays ont travaill\u00e9 ensemble dans divers domaines, notamment le climat, l&#8217;\u00e9ducation, la sant\u00e9, l\u2019agriculture et le d\u00e9veloppement \u00e9conomique. &nbsp;Le Gabon est consid\u00e9r\u00e9 comme un pays ami en Afrique qui a toujours pleinement soutenu notre position sur la sc\u00e8ne internationale. L\u2019ancien Pr\u00e9sident Omar Bongo s\u2019est rendu en Cor\u00e9e au total quatre fois (1975, 1984, 1996 et 2007), faisant de lui le Pr\u00e9sident africain qui a le plus visit\u00e9 la Cor\u00e9e. C\u2019est en 1975, \u00e0 la suite de la visite d\u2019Etat du Pr\u00e9sident Bongo que l\u2019Ambassade du Gabon en Cor\u00e9e fut cr\u00e9\u00e9e. Depuis cette date, les relations de coop\u00e9ration et d\u2019amiti\u00e9 entre&nbsp; les deux pays n&#8217;ont cess\u00e9 de se d\u00e9velopper.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C.I&nbsp;: <\/strong><strong>&nbsp;La r\u00e9volution du 30 aout 2023 au Gabon ouvre une nouvelle \u00e8re d\u2019espoir pour les r\u00e9formes. Quels sont les domaines d\u2019\u00e9changes qui int\u00e9ressent la Cor\u00e9e?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ambassadeur SHIN&nbsp;: <\/strong>Les changements politiques survenus au Gabon en ao\u00fbt de l&#8217;ann\u00e9e derni\u00e8re apportent non seulement des d\u00e9fis mais aussi de l&#8217;espoir \u00e0 de nombreux Gabonais. La Cor\u00e9e est une rare r\u00e9ussite dans la soci\u00e9t\u00e9 moderne qui a surmont\u00e9 diverses crises et a atteint simultan\u00e9ment la croissance \u00e9conomique et la d\u00e9mocratisation. Nous sommes convaincus que l&#8217;exp\u00e9rience cor\u00e9enne en mati\u00e8re de d\u00e9mocratisation et de d\u00e9veloppement sera d&#8217;une grande aide au Gabon, qui s&#8217;efforce de construire une nouvelle nation par la r\u00e9forme.Le gouvernement cor\u00e9en appr\u00e9cie hautement les efforts du gouvernement de transition du Gabon, y compris l&#8217;annonce du chronogramme visant \u00e0 effectuer la passation du r\u00e9gime militaire \u00e0 une administration civile et \u00e0 mettre en \u0153uvre diverses r\u00e9formes institutionnelles pour am\u00e9liorer les moyens de subsistance de la population, et esp\u00e8re que ces efforts contribueront grandement au d\u00e9veloppement national du Gabon ainsi qu&#8217;\u00e0 la promotion des relations bilat\u00e9rales entre la Cor\u00e9e et le Gabon.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C.I: Quels sont les domaines prioritaires de votre coop\u00e9reation&nbsp; avec le Gabon?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ambassadeur SHIN: <\/strong>Dans la coop\u00e9ration avec le Gabon , l\u2019Ambassade Cor\u00e9en , promeut cinq domaines prioritaires avec le Gabon \u00e0 savoir: \u25b4<strong>l\u2019<\/strong><strong>\u00c9ducation, la Sant\u00e9, l\u2019Infrastructure <\/strong><strong>, le <\/strong><strong>Changement climatique <\/strong><strong>,l\u2019<\/strong><strong>Environnement et \u00e9nergie<\/strong>. Au cours de ces sept derniers mois, le gouvernement de la transition a beaucoup travaill\u00e9 dans les domaines de l\u2019\u00e9ducation , la sant\u00e9 et des infrastructures. Ce sont des domaines dans lesquels nous avons beaucoup investi et obtenu des r\u00e9sultats significtaifs. Nous pensons que plusieurs opportunit\u00e9s de coop\u00e9ration dans ces domainses pseront cr\u00e9\u00e9es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C.I: De maniere plus concr\u00e8te , quelles sont les actions que nous pouvons retenir?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ambassadeur SHIN: <\/strong>Plus pr\u00e9cis\u00e9ment, les entreprises cor\u00e9ennes pourront coop\u00e9rer de diverses mani\u00e8res pour construire les infrastructures au Gabon en offrant leur haute technologie et de leur riche exp\u00e9rience en mati\u00e8re de d\u00e9veloppement \u00e0 l&#8217;\u00e9tranger. En outre, les entreprises cor\u00e9ennes qui ont de l\u2019exp\u00e9rience dans la r\u00e9alisation d\u2019\u00e9tudes de faisabilit\u00e9 , peuvent contribuer \u00e0 la construction d&#8217;un nouvel a\u00e9roport ou d&#8217;une raffinerie de p\u00e9trole,des projets importants du gouvernement de la transition.Dans le domaine de la sant\u00e9, la Cor\u00e9e a fait un don d&#8217;ambulances, d&#8217;\u00e9quipements m\u00e9dicaux et de kits de diagnostic COVID-19 au Gabon, et&nbsp; cette ann\u00e9e, notre gouvernement va conduire un projet pilote pour soutenir le gouvernement gabonais dans l\u2019acquisition des v\u00e9hicules m\u00e9dicaux (cliniques mobiles) . Nous cherchons \u00e0 \u00e9largir la coop\u00e9ration en mati\u00e8re de sant\u00e9. Dans le secteur agricole, l&#8217;Initiative de coop\u00e9ration technologique agroalimentaire Cor\u00e9e-Afrique (KAFACI) a \u00e9t\u00e9 sign\u00e9e en 2010, et&nbsp; c\u2019est en 2012 que nous avons d\u00e9but\u00e9 au Gabon par le soutien au projet de m\u00e9canisation de la riziculture . Les quatre projets actuellement d\u00e9velopp\u00e9s sont :&nbsp; Le d\u00e9veloppement de vari\u00e9t\u00e9s de riz ;le d\u00e9veloppement de technologie globale de lutte antiparasitaire ; l\u2019am\u00e9lioration de la productivit\u00e9 des tomates et des oignons &nbsp;et , les m\u00e9thodes agricoles utilisant du compost et du fumier de b\u00e9tail. &nbsp;Sachant que&nbsp; le gouvernement de la transition a r\u00e9cemment prix&nbsp; diverses mesures pour stabiliser les prix, l&#8217;augmentation de la productivit\u00e9 gr\u00e2ce au d\u00e9veloppement technologique contribuera \u00e0 la stabilit\u00e9 des prix et \u00e0 la s\u00e9curit\u00e9 alimentaire au Gabon.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>CI<\/strong><strong>&nbsp;<\/strong><strong>: Quelle coop<\/strong><strong>\u00e9<\/strong><strong>ration dans le secteur de l\u2019Enseignement et de l\u2019Education?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ambassadeur SHIN&nbsp;: <\/strong>Chaque ann\u00e9e, notre gouvernement offre exceptionnellement aux \u00e9tudiants gabonais la possibilit\u00e9 de b\u00e9n\u00e9ficier&nbsp; des bourses et d&#8217;\u00e9tudier dans nos universit\u00e9s gr\u00e2ce au programme de bourses d&#8217;\u00e9tudes \u00e9trang\u00e8res (GKS).Nous s\u00e9lectionnons 2 \u00e0 3 \u00e9tudiants gabonais par an et, actuellement, environ 30 \u00e9tudiants sont rentr\u00e9s au Gabon apr\u00e8s leur formation en Cor\u00e9e et travaillent dans divers domaines. Ils constituent les atouts importants&nbsp; pour le d\u00e9veloppement des relations entre les deux pays.De plus, depuis le lancement en 2013 du \u2018Club Koica Gabon\u2019, une association \u00e0 but non lucratif d\u2019anciens participants de Koica programmes de formation, des \u00e9v\u00e9nements sont organis\u00e9s chaque ann\u00e9e, notamment la r\u00e9habilitation des comme des \u00e9coles, l\u2019accompagnement des plus d\u00e9favoris\u00e9s, des s\u00e9minaires, et des c\u00e9r\u00e9monies de \u2018Friendship dinner\u2019. <strong>&nbsp;<\/strong>Afin d&#8217;aider les \u00e9l\u00e8ves gabonais \u00e0 comprendre le d\u00e9veloppement, l&#8217;histoire et la culture de la Cor\u00e9e, notre gouvernement collabore avec le minist\u00e8re gabonais de l&#8217;\u00c9ducation depuis 2017 pour distribuer un manuel compl\u00e9mentaire en fran\u00e7ais <strong>\u00ab LA COREE DANS MONDE \u00bb<\/strong> qui pr\u00e9sente la Cor\u00e9e aux lyc\u00e9es. Nous coop\u00e9rations de diverses manieres. Cependant, lors de r\u00e9centes r\u00e9unions avec le ministre gabonais de l&#8217;\u00c9ducation, le ministre de l&#8217;Enseignement sup\u00e9rieur et le Recteur de l&#8217;Universit\u00e9 Omar Bongo, nous avons convenu d\u2019\u00e9laregir d\u2019avantage notre coop\u00e9ration. Bien qu\u2019elle soit un pays pauvre en ressources, la Cor\u00e9e a atteint un d\u00e9veloppement \u00e9conomique et une d\u00e9mocratisation bas\u00e9s sur son niveau \u00e9lev\u00e9 d\u2019\u00e9ducation. \u00c9tant donn\u00e9 que de nombreuses entreprises cor\u00e9ennes fournissent des services \u00e9ducatifs de haut niveau en Europe, en Asie et au Moyen-Orient en promouvant la transformation num\u00e9rique dans le domaine de l&#8217;\u00e9ducation appel\u00e9e <strong>e-learning <\/strong>m\u00eame avant le coronavirus, les deux pays pourraient devenir des partenaires optimaux de coop\u00e9ration, en particulier dans le domaine de <strong>l&#8217;E-learning.<\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">la Cor\u00e9e pr\u00e9voit de r\u00e9duire ses \u00e9missions de gaz \u00e0 effet de serre de 40% d\u2019ici 2030 et, \u00e0 cette effet, elle pr\u00e9voit de r\u00e9duire 33,5 millions de tonnes \u00e0 l\u2019\u00e9tranger, soit 11,5 % de la r\u00e9duction totale<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C.I&nbsp;: Le Gabon est consid\u00e9r\u00e9 comme un pays leaders sur la sc\u00e8ne internationale en mati\u00e8re de Climat. Comment la Cor\u00e9e peut-elle renforcer sa coop\u00e9ration &nbsp;en cette mati\u00e8re&nbsp;?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ambassadeur SHIN:<\/strong> Le Gabon, avec 88% de sa superficie couverte de for\u00eat, est l&#8217;un des principaux pays neutres en carbone qui absorbant 100 millions de tonnes de carbone chaque ann\u00e9e, soit quatre fois ses \u00e9missions de carbone. Par rapport \u00e0 2018, la Cor\u00e9e pr\u00e9voit de r\u00e9duire ses \u00e9missions de gaz \u00e0 effet de serre de 40% d\u2019ici 2030 et, \u00e0 cette effet, elle pr\u00e9voit de r\u00e9duire 33,5 millions de tonnes \u00e0 l\u2019\u00e9tranger, soit 11,5 % de la r\u00e9duction totale. Si les deux pays r\u00e9alisent conjointement un projet de r\u00e9duction des gaz \u00e0 effet de serre dans le secteur forestier conform\u00e9ment \u00e0 <strong>\u00ab l&#8217;Accord-cadre de coop\u00e9ration sur le changement climatique entre le Gouvernement de la R\u00e9publique de Cor\u00e9e et le Gouvernement de la R\u00e9publique Gabonaise\u00bb<\/strong> , sign\u00e9 en mai 2023, les deux pays pourront en b\u00e9n\u00e9ficier.En outre, si les deux pays poursuivent conjointement des projets \u00e9nerg\u00e9tiques respectueux de l&#8217;environnement, tels que des projets d&#8217;\u00e9nergies nouvelles et renouvelables gr\u00e2ce \u00e0 la production d&#8217;\u00e9nergie solaire, le Gabon r\u00e9alisera des b\u00e9n\u00e9fices tout en pr\u00e9servant l&#8217;environnement naturel, comme les for\u00eats pr\u00e9cieuses, et la Cor\u00e9e remplira son r\u00f4le de pays pivot mondial en mettant en \u0153uvre une r\u00e9duction des gaz \u00e0 effet de serre<strong>.<\/strong> Nous pr\u00e9voyons d\u2019organiser cette ann\u00e9e, dans la continuit\u00e9 de 2022, <strong>la \u00ab Conf\u00e9rence sur la coop\u00e9ration Cor\u00e9e-Gabon sur le changement climatique \u00bb,<\/strong> et nous esp\u00e9rons que cette conf\u00e9rence sera l\u2019occasion d\u2019explorer les moyens pratiques de coop\u00e9rer pour r\u00e9pondre au changement climatique entre les deux pays.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>C.I: <\/strong><strong>Quels sont les perspectives d\u2019avenir dans la relation bilat\u00e9rale entre le Gabon et la R\u00e9publique de Cor\u00e9e?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ambassadeur SHIN:<\/strong> Alors que l&#8217;histoire des relations diplomatiques entre la Cor\u00e9e et le Gabon approche les 60 prochaines ann\u00e9es, la Cor\u00e9e cherche \u00e0 \u00e9largir davantage les horizons de coop\u00e9ration entre les deux pays dans divers domaines tels que la politique, la culture, l&#8217;\u00e9conomie et la sant\u00e9. La popularit\u00e9 de la vague cor\u00e9enne telle que la K-pop, le K-drama et les films augmente parmi les jeunes au Gabon, et cet int\u00e9r\u00eat croissant pour la culture cor\u00e9enne montre symboliquement que l\u2019avenir de la relation entre les deux pays est positif. L&#8217;int\u00e9r\u00eat croissant du peuple gabonais pour la culture cor\u00e9enne \u00e0 travers la diplomatie publique pourrait jouer un r\u00f4le majeur dans l\u2019avenir de nos relations bilat\u00e9rales. Notre ambassade s&#8217;efforce de revitaliser la diplomatie publique en organisant chaque ann\u00e9e le concours d&#8217;expression oral cor\u00e9en et le concours de K-pop. De plus, le Taekwondo, qui peut \u00eatre consid\u00e9r\u00e9 comme l&#8217;origine de la vague cor\u00e9enne, est un sport important au Gabon et consid\u00e9r\u00e9 comme une source de fiert\u00e9 nationale. Nous attendons beaucoup de la performance du Gabon aux Jeux olympiques de Paris de cette ann\u00e9e. Pour finir, cette ann\u00e9e, l\u2019ambassade de la R\u00e9publique de Cor\u00e9e s&#8217;efforcera de revitaliser la diplomatie sportive entre les deux pays en promouvant divers \u00e9v\u00e9nements de taekwondo, tels que la Coupe de l&#8217;Ambassadeur Taekwondo et la performance de l\u2019\u00e9quipe repr\u00e9sentant cor\u00e9enne de Taekwondo.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"810\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/thumbnail-edited.jpeg\" alt=\"\" class=\"wp-image-2843\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/thumbnail-edited.jpeg 1080w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/thumbnail-edited-300x225.jpeg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/thumbnail-edited-1024x768.jpeg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/01\/thumbnail-edited-768x576.jpeg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">L&#8217;ambassadeur SHIN SONG BUM et Brice NDONG \u00e0 la fin de l&#8217;entretien \u00e0 l&#8217;ambassade de Cor\u00e9e \u00e0 Libreville \u00ae photo CI<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bilan du Projet de Coop\u00e9ration entre le Gabon et la Cor\u00e9e\u00a0<\/strong>. Veuillez t\u00e9l\u00e9charger l&#8217;int\u00e9gralit\u00e9 du journal CI N\u00b089 sur le lien suivant : <a href=\"https:\/\/www.e-kiosque-sodipresse.com\/fr\/a-la-carte\/mensuelle\/cooperation-internationale\/\">https:\/\/www.e-kiosque-sodipresse.com\/fr\/a-la-carte\/mensuelle\/cooperation-internationale\/<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019exp\u00e9rience Cor\u00e9enne en mati\u00e8re de d\u00e9mocratisation et de d\u00e9veloppement sera d\u2019une grande aide au Gabon. A la t\u00eate de la mission diplomatique de la R\u00e9publique de Cor\u00e9e depuis un an, SE SHIN SONG BUM, ambassadeur de Cor\u00e9e au Gabon nous a accord\u00e9 cette interview exclusive express. M. SHIN s\u2019est prononc\u00e9<\/p>\n","protected":false},"author":1,"featured_media":2487,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[54],"tags":[],"class_list":["post-1083","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-interview"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1-150x150.jpeg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1-300x164.jpeg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1-392x270.jpeg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1-390x205.jpeg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1-130x90.jpeg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1-150x150.jpeg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg"},"magazineBlocksPostAuthor":{"name":"admin","avatar":"https:\/\/secure.gravatar.com\/avatar\/d543a13863f9ae9e07f53081df2cc13fbbf8b9a846bceee655f5385123457172?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"L\u2019exp\u00e9rience Cor\u00e9enne en mati\u00e8re de d\u00e9mocratisation et de d\u00e9veloppement sera d\u2019une grande aide au Gabon. A la t\u00eate de la mission diplomatique de la R\u00e9publique de Cor\u00e9e depuis un an, SE SHIN SONG BUM, ambassadeur de Cor\u00e9e au Gabon nous a accord\u00e9 cette interview exclusive express. M. SHIN s\u2019est prononc\u00e9","magazineBlocksPostCategories":["INTERVIEW"],"magazineBlocksPostViewCount":615,"magazineBlocksPostReadTime":10,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg",494,270,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1-300x164.jpeg",300,164,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1-150x150.jpeg",150,150,true]},"magazine_blocks_author":{"display_name":"admin","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/dondiajhoelyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/d543a13863f9ae9e07f53081df2cc13fbbf8b9a846bceee655f5385123457172?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-54\">INTERVIEW<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SE.M. SHIN SONG BUM, Ambassadeur de Cor\u00e9e au Gabon - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SE.M. SHIN SONG BUM, Ambassadeur de Cor\u00e9e au Gabon - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"L\u2019exp\u00e9rience Cor\u00e9enne en mati\u00e8re de d\u00e9mocratisation et de d\u00e9veloppement sera d\u2019une grande aide au Gabon. A la t\u00eate de la mission diplomatique de la R\u00e9publique de Cor\u00e9e depuis un an, SE SHIN SONG BUM, ambassadeur de Cor\u00e9e au Gabon nous a accord\u00e9 cette interview exclusive express. M. SHIN s\u2019est prononc\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-24T11:07:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-01T19:58:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"494\" \/>\n\t<meta property=\"og:image:height\" content=\"270\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/9fd1c151622a753e2def2a23f0bf2105\"},\"headline\":\"SE.M. SHIN SONG BUM, Ambassadeur de Cor\u00e9e au Gabon\",\"datePublished\":\"2024-10-24T11:07:24+00:00\",\"dateModified\":\"2025-01-01T19:58:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/\"},\"wordCount\":1965,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg\",\"articleSection\":[\"INTERVIEW\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/\",\"name\":\"SE.M. SHIN SONG BUM, Ambassadeur de Cor\u00e9e au Gabon - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg\",\"datePublished\":\"2024-10-24T11:07:24+00:00\",\"dateModified\":\"2025-01-01T19:58:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg\",\"width\":494,\"height\":270},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SE.M. SHIN SONG BUM, Ambassadeur de Cor\u00e9e au Gabon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/9fd1c151622a753e2def2a23f0bf2105\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d543a13863f9ae9e07f53081df2cc13fbbf8b9a846bceee655f5385123457172?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d543a13863f9ae9e07f53081df2cc13fbbf8b9a846bceee655f5385123457172?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"https:\/\/kind-wu.57-128-124-134.plesk.page\"],\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/dondiajhoelyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SE.M. SHIN SONG BUM, Ambassadeur de Cor\u00e9e au Gabon - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/","og_locale":"fr_FR","og_type":"article","og_title":"SE.M. SHIN SONG BUM, Ambassadeur de Cor\u00e9e au Gabon - Cooperation Internationale","og_description":"L\u2019exp\u00e9rience Cor\u00e9enne en mati\u00e8re de d\u00e9mocratisation et de d\u00e9veloppement sera d\u2019une grande aide au Gabon. A la t\u00eate de la mission diplomatique de la R\u00e9publique de Cor\u00e9e depuis un an, SE SHIN SONG BUM, ambassadeur de Cor\u00e9e au Gabon nous a accord\u00e9 cette interview exclusive express. M. SHIN s\u2019est prononc\u00e9","og_url":"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2024-10-24T11:07:24+00:00","article_modified_time":"2025-01-01T19:58:49+00:00","og_image":[{"width":494,"height":270,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/"},"author":{"name":"admin","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/9fd1c151622a753e2def2a23f0bf2105"},"headline":"SE.M. SHIN SONG BUM, Ambassadeur de Cor\u00e9e au Gabon","datePublished":"2024-10-24T11:07:24+00:00","dateModified":"2025-01-01T19:58:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/"},"wordCount":1965,"commentCount":0,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg","articleSection":["INTERVIEW"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/","url":"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/","name":"SE.M. SHIN SONG BUM, Ambassadeur de Cor\u00e9e au Gabon - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg","datePublished":"2024-10-24T11:07:24+00:00","dateModified":"2025-01-01T19:58:49+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg","width":494,"height":270},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2024\/10\/24\/se-m-shin-song-bum-ambassadeur-de-coree-au-gabon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"SE.M. SHIN SONG BUM, Ambassadeur de Cor\u00e9e au Gabon"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/9fd1c151622a753e2def2a23f0bf2105","name":"admin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d543a13863f9ae9e07f53081df2cc13fbbf8b9a846bceee655f5385123457172?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d543a13863f9ae9e07f53081df2cc13fbbf8b9a846bceee655f5385123457172?s=96&d=mm&r=g","caption":"admin"},"sameAs":["https:\/\/kind-wu.57-128-124-134.plesk.page"],"url":"https:\/\/www.lejournalci.org\/index.php\/author\/dondiajhoelyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/10\/thumbnail-1.jpeg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1083","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=1083"}],"version-history":[{"count":6,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1083\/revisions"}],"predecessor-version":[{"id":2845,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/1083\/revisions\/2845"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/2487"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=1083"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=1083"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=1083"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}