{"id":10650,"date":"2026-01-03T07:38:27","date_gmt":"2026-01-03T07:38:27","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=10650"},"modified":"2026-01-03T07:38:28","modified_gmt":"2026-01-03T07:38:28","slug":"guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/","title":{"rendered":"Guin\u00e9e \u00c9quatoriale : Le Pr\u00e9sident proclame Djibloho comme nouvelle Capitale du Pays."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Lors d&#8217;une journ\u00e9e historique pour la nation, le Pr\u00e9sident de la R\u00e9publique de Guin\u00e9e \u00c9quatoriale, Obiang Nguema Mbasogo a proclam\u00e9 la&#8221; Ville de la Paix &#8220;- capitale de la province de Djibloho , comme la nouvelle capitale de la R\u00e9publique. Au cours de sa d\u00e9claration solennelle , le chef de l&#8217;\u00c9tat Equatoguin\u00e9en a \u00e9voqu\u00e9 notamment les raisons de s\u00e9curit\u00e9, la n\u00e9cessit\u00e9 d&#8217;une meilleure r\u00e9partition territoriale et de moderniser les structures h\u00e9rit\u00e9es de la colonisation<\/strong>. <strong>Pour sa part, le Vice-Pr\u00e9sident Nguema Obiang Mangue via son compte social X, a \u00e9galement fix\u00e9 les d\u00e9lais d&#8217;ex\u00e9cution de cette importante d\u00e9cision.<\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Vendredi 2 janvier 2026, une journ\u00e9e m\u00e9morable <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Le si\u00e8ge de la pr\u00e9sidence de la R\u00e9publique \u00e0 la Cit\u00e9 de la Paix, chef-lieu de la province de Djibloho, a \u00e9t\u00e9 le th\u00e9\u00e2tre le vendredi 2 janvier 2026, de la signature d&#8217;un d\u00e9cret-loi et de la d\u00e9claration institutionnelle par laquelle le Pr\u00e9sident de la R\u00e9publique de a proclam\u00e9 cette ville comme nouvelle capitale de la Guin\u00e9e \u00e9quatoriale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La manifestation s&#8217;est d\u00e9roul\u00e9e en pr\u00e9sence du Vice-Pr\u00e9sident de la R\u00e9publique, de la Premi\u00e8re Dame, des pr\u00e9sidents des organes constitutionnels, de certains membres du gouvernement en t\u00eate desquels le Premier Ministre, des gouverneurs provinciaux, des pr\u00e9sidents des commissions de suivi du PDGE, le parti au pouvoir et des d\u00e9l\u00e9gu\u00e9s gouvernementaux situ\u00e9s \u00e0 la R\u00e9gion 1continentale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dans son allocution, le chef de l&#8217;\u00c9tat Obiang Nguema Mbasog a \u00e9voqu\u00e9 sa politique de structuration du territoire national depuis le 3 ao\u00fbt 1979, qui a r\u00e9parti la nation en des juridictions territoriales r\u00e9parties dans les provinces, districts, municipalit\u00e9s, districts urbains et conseils de village pour assurer un d\u00e9veloppement socio\u00e9conomique et culturel efficace.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"607\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609808-1-edited.jpg\" alt=\"\" class=\"wp-image-10660\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609808-1-edited.jpg 1080w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609808-1-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609808-1-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609808-1-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><figcaption class=\"wp-element-caption\">Le Pr\u00e9sident Obiang Nguema Mbasogo lors de la signature du d\u00e9cret portant transfert de la capitale de Malabo \u00e0 Djibloho, le 2 \/01\/2026 \u00a9 Photo GE<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">&#8211;<strong><em>\u00ab La relocalisation de la capitale nationale, du point de vue de la s\u00e9curit\u00e9, constitue une \u00e9tape fondamentale si l&#8217;on consid\u00e8re que le gouvernement a \u00e9t\u00e9 victime de plusieurs attaques venant de l&#8217;ext\u00e9rieur par voie maritime, l&#8217;une lors de l&#8217;attaque des banques \u00e0 Bata et l&#8217;autre \u00e0 Malabo contre la pr\u00e9sidence de la R\u00e9publique, ce qui a sans aucun doute d\u00e9montr\u00e9 la situation de vuln\u00e9rabilit\u00e9 des si\u00e8ges du Gouvernement \u00e0 Malabo et Bata \u00bb, <\/em><\/strong>a rappel\u00e9, le Pr\u00e9sident, qui a notamment fait mention du coup d&#8217;\u00c9tat de 2017 d\u00e9jou\u00e9 par les forces de s\u00e9curit\u00e9, \u00e0 la fronti\u00e8re avec le Cameroun dans le district d&#8217;Ebibeyin; emp\u00eachant l&#8217;ennemi d&#8217;atteindre ses objectifs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le transfert de la capitale politique \u00e0 la capitale de la province de Djiploho vise \u00e0 pr\u00e9venir toute tentative \u00e9ventuelle de d\u00e9stabilisation des institutions en se situant dans une zone appropri\u00e9e permettant d&#8217;assurer une meilleure d\u00e9fense de l&#8217;int\u00e9grit\u00e9 territoriale nationale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En outre, en se fondant sur l&#8217;histoire, le Pr\u00e9sident Obiang Nguema Nbasogo a pris des exemples de certains pays qui ont fait de m\u00eame, comme le Nig\u00e9ria qui a transf\u00e9r\u00e9 sa capitale \u00e0 Abuja pour mettre fin aux coups d&#8217;\u00c9tat r\u00e9currents que subissait le pays \u00e0 Lagos. Le Br\u00e9sil &#8211; s&#8217;est -il rappel\u00e9 , a \u00e9galement pris cette d\u00e9cision en emmenant la capitale de Sao Paolo \u00e0 Brasilia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour les dirigeants de la Guin\u00e9e \u00c9quatoriale, ancienne colonie espagnole, cette d\u00e9cision rompt \u00e9galement avec la structuration h\u00e9rit\u00e9e de l&#8217;administration coloniale apr\u00e8s 57 ans d&#8217; ind\u00e9pendance, et pour que l&#8217;administration se d\u00e9tache des structures coloniales obsol\u00e8tes qui n&#8217;ont plus rien \u00e0 voir avec la modernisation actuelle du pays. Obiang Nguema Mbasogo affirme que cette d\u00e9cision apportera des avantages positifs en garantissant la stabilit\u00e9 politique de la nation, en \u00e9vitant les mouvements migratoires vers les grandes villes comme Malabo et Bata.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Ville de la Paix , appel\u00e9e &#8220;Ciudad de la Paz &#8221; en espagnol, est un centre convergent de la r\u00e9gion continentale, il est tr\u00e8s facile d&#8217;y acc\u00e9der depuis n&#8217;importe quel district de la r\u00e9gion, on estime qu&#8217;il n&#8217;y a pas de distance d&#8217;un dur\u00e9e de plus de 3 heures avec les autres localit\u00e9s du pays. Le Pr\u00e9sident de la R\u00e9publique a conclu son allocution en exhortant le Gouvernement et les organes constitutionnels \u00e0 respecter cette volont\u00e9 politique.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609811-edited-1024x576.jpg\" alt=\"\" class=\"wp-image-10658\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609811-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609811-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609811-edited-768x432.jpg 768w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609811-edited.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Le Vice-pr\u00e9sident Nguema Obiang Mangue et la premi\u00e8re dame Constancia Mangue Obiang le 2\/01\/2026 \u00e0 Djibloho \u00a9 Photo GE<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Pour sa part, le Vice-Pr\u00e9sident de la R\u00e9publique a \u00e9galement rendu compte de cet \u00e9v\u00e9nement historique pour le pays via son r\u00e9seau social X, indiquant que cette d\u00e9cision s&#8217;inscrit <strong><em>\u00ab dans le cadre d&#8217;une vision moderne de l&#8217;organisation territoriale et du renforcement de l&#8217;\u00c9tat \u00bb.<\/em><\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Cette d\u00e9cision r\u00e9pond \u00e0 des crit\u00e8res de s\u00e9curit\u00e9, de stabilit\u00e9 politique et de meilleure r\u00e9gulation du flux migratoire, ainsi qu\u2019\u00e0 l\u2019emplacement strat\u00e9gique et central de la Ciudad de la Paz, con\u00e7ue pour assurer une administration plus \u00e9quilibr\u00e9e, efficace et coh\u00e9rente sur tout le territoire national. En outre, ce processus permettra de cr\u00e9er des milliers d&#8217;emplois, fruit des infrastructures que le Gouvernement est d\u00e9j\u00e0 en train de construire et continuera de d\u00e9velopper pour accueillir les nouvelles institutions de l&#8217;\u00c9tat, les services publics et l&#8217;activit\u00e9 \u00e9conomique associ\u00e9e \u00bb, a \u00e9galement d\u00e9clar\u00e9 le Vice-Pr\u00e9sident<\/p>\n<\/blockquote>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">\u00ab La nouvelle capitale repr\u00e9sente aussi une ferme d\u00e9termination vers la consolidation de notre souverainet\u00e9 et de notre identit\u00e9, projetant une capitale con\u00e7ue depuis et pour la Guin\u00e9e \u00e9quatoriale et rompant ainsi avec les structures h\u00e9rit\u00e9es de la p\u00e9riode coloniale apr\u00e8s 57 ans d&#8217;ind\u00e9pendance. Un d\u00e9lai d&#8217;un an est fix\u00e9 pour prendre les mesures n\u00e9cessaires afin de permettre le transfert institutionnel et l&#8217;installation progressive des structures de l&#8217;\u00c9tat dans la Cit\u00e9 de la paix, garantissant un processus ordonn\u00e9, planifi\u00e9 et conforme aux int\u00e9r\u00eats nationaux. , a conclu le Vice-pr\u00e9sident Nguema Obiang.<\/p>\n<\/blockquote>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"607\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/FB_IMG_1767407062531-edited.jpg\" alt=\"\" class=\"wp-image-10662\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/FB_IMG_1767407062531-edited.jpg 1080w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/FB_IMG_1767407062531-edited-300x169.jpg 300w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/FB_IMG_1767407062531-edited-1024x576.jpg 1024w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/FB_IMG_1767407062531-edited-768x432.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><em>SOURCE: Pr\u00e9sidence de la R\u00e9publique de Guin\u00e9e \u00c9quatoriale &amp; Cabinet du Vice-pr\u00e9sident de la R\u00e9publique.<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lors d&#8217;une journ\u00e9e historique pour la nation, le Pr\u00e9sident de la R\u00e9publique de Guin\u00e9e \u00c9quatoriale, Obiang Nguema Mbasogo a proclam\u00e9 la&#8221; Ville de la Paix &#8220;- capitale de la province de Djibloho , comme la nouvelle capitale de la R\u00e9publique. Au cours de sa d\u00e9claration solennelle , le chef de<\/p>\n","protected":false},"author":3,"featured_media":10652,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[51],"tags":[],"class_list":["post-10650","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diplomatie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited-1080x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Lors d&#8217;une journ\u00e9e historique pour la nation, le Pr\u00e9sident de la R\u00e9publique de Guin\u00e9e \u00c9quatoriale, Obiang Nguema Mbasogo a proclam\u00e9 la&#8221; Ville de la Paix &#8220;- capitale de la province de Djibloho , comme la nouvelle capitale de la R\u00e9publique. Au cours de sa d\u00e9claration solennelle , le chef de","magazineBlocksPostCategories":["DIPLOMATIE"],"magazineBlocksPostViewCount":1914,"magazineBlocksPostReadTime":6,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited.jpg",1080,607,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-51\">DIPLOMATIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Guin\u00e9e \u00c9quatoriale : Le Pr\u00e9sident proclame Djibloho comme nouvelle Capitale du Pays. - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Guin\u00e9e \u00c9quatoriale : Le Pr\u00e9sident proclame Djibloho comme nouvelle Capitale du Pays. - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Lors d&#8217;une journ\u00e9e historique pour la nation, le Pr\u00e9sident de la R\u00e9publique de Guin\u00e9e \u00c9quatoriale, Obiang Nguema Mbasogo a proclam\u00e9 la&#8221; Ville de la Paix &#8220;- capitale de la province de Djibloho , comme la nouvelle capitale de la R\u00e9publique. Au cours de sa d\u00e9claration solennelle , le chef de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-03T07:38:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-03T07:38:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Guin\u00e9e \u00c9quatoriale : Le Pr\u00e9sident proclame Djibloho comme nouvelle Capitale du Pays.\",\"datePublished\":\"2026-01-03T07:38:27+00:00\",\"dateModified\":\"2026-01-03T07:38:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/\"},\"wordCount\":1077,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited.jpg\",\"articleSection\":[\"DIPLOMATIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/\",\"name\":\"Guin\u00e9e \u00c9quatoriale : Le Pr\u00e9sident proclame Djibloho comme nouvelle Capitale du Pays. - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited.jpg\",\"datePublished\":\"2026-01-03T07:38:27+00:00\",\"dateModified\":\"2026-01-03T07:38:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited.jpg\",\"width\":1080,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Guin\u00e9e \u00c9quatoriale : Le Pr\u00e9sident proclame Djibloho comme nouvelle Capitale du Pays.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Guin\u00e9e \u00c9quatoriale : Le Pr\u00e9sident proclame Djibloho comme nouvelle Capitale du Pays. - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/","og_locale":"fr_FR","og_type":"article","og_title":"Guin\u00e9e \u00c9quatoriale : Le Pr\u00e9sident proclame Djibloho comme nouvelle Capitale du Pays. - Cooperation Internationale","og_description":"Lors d&#8217;une journ\u00e9e historique pour la nation, le Pr\u00e9sident de la R\u00e9publique de Guin\u00e9e \u00c9quatoriale, Obiang Nguema Mbasogo a proclam\u00e9 la&#8221; Ville de la Paix &#8220;- capitale de la province de Djibloho , comme la nouvelle capitale de la R\u00e9publique. Au cours de sa d\u00e9claration solennelle , le chef de","og_url":"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2026-01-03T07:38:27+00:00","article_modified_time":"2026-01-03T07:38:28+00:00","og_image":[{"width":1080,"height":607,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Guin\u00e9e \u00c9quatoriale : Le Pr\u00e9sident proclame Djibloho comme nouvelle Capitale du Pays.","datePublished":"2026-01-03T07:38:27+00:00","dateModified":"2026-01-03T07:38:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/"},"wordCount":1077,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited.jpg","articleSection":["DIPLOMATIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/","url":"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/","name":"Guin\u00e9e \u00c9quatoriale : Le Pr\u00e9sident proclame Djibloho comme nouvelle Capitale du Pays. - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited.jpg","datePublished":"2026-01-03T07:38:27+00:00","dateModified":"2026-01-03T07:38:28+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited.jpg","width":1080,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2026\/01\/03\/guinee-equatoriale-le-president-proclame-djibloho-comme-nouvelle-capitale-du-pays\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Guin\u00e9e \u00c9quatoriale : Le Pr\u00e9sident proclame Djibloho comme nouvelle Capitale du Pays."}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2026\/01\/1001609809-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/10650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=10650"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/10650\/revisions"}],"predecessor-version":[{"id":10663,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/10650\/revisions\/10663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/10652"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=10650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=10650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=10650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}