{"id":10030,"date":"2025-11-16T10:48:34","date_gmt":"2025-11-16T10:48:34","guid":{"rendered":"https:\/\/www.lejournalci.org\/?p=10030"},"modified":"2025-11-16T10:48:36","modified_gmt":"2025-11-16T10:48:36","slug":"grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl","status":"publish","type":"post","link":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/","title":{"rendered":"Grands Lacs : F\u00e9lix Tshisekedi prend la t\u00eate de la pr\u00e9sidence de la CIRGL"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Kinshasa, la capitale de la R\u00e9publique D\u00e9mocratique du Congo (RDC) a accueilli, le samedi 15 Novembre 2025 au Palais du peuple, le 9\u00e8me Sommet ordinaire des Chefs d\u2019\u00c9tat et des gouvernements de la Conf\u00e9rence internationale sur la r\u00e9gion des Grands Lacs (CIRGL).\u00a0Ce grand \u00e9v\u00e9nement,qui intervient \u00a0cinq ans apr\u00e8s le dernier sommet tenu par visioconf\u00e9rence en novembre 2020, \u00e0 \u00a0pour th\u00e8me : <strong><em>\u201cConsolider la paix et la s\u00e9curit\u00e9 pour le d\u00e9veloppement durable dans la r\u00e9gion des Grands Lacs\u201d.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La c\u00e9r\u00e9monie d\u2019ouverture a \u00e9t\u00e9 marqu\u00e9e par plusieurs allocutions notamment celle de Monsieur Huang Xia, Repr\u00e9sentant personnel du Secr\u00e9taire g\u00e9n\u00e9ral des Nations Unies Antonio Guterres. <strong><em>\u00ab&nbsp;Les hostilit\u00e9s dans l\u2019Est de la RDC doivent cesser imm\u00e9diatement et l\u2019acc\u00e8s humanitaire doit \u00eatre garanti pour apporter l\u2019aide n\u00e9cessaire aux populations touch\u00e9es&nbsp;\u00bb, a d\u00e9clar\u00e9 l\u2019\u00e9missaire du SG des Nations Unies, d\u2019un ton clair.&nbsp;<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00ab\u00a0C\u2019est avec humilit\u00e9 et d\u00e9termination que j\u2019accepte, au nom de la R\u00e9publique D\u00e9mocratique du Congo, la Pr\u00e9sidence tournante de la CIRGL pour les deux prochaines ann\u00e9es\u00a0\u00bb.<br>C\u2019est par cette phrase toute simple mais empreinte d\u2019une grande symbolique que le Pr\u00e9sident de la R\u00e9publique a pris officiellement la t\u00eate de la Conf\u00e9rence internationale sur la r\u00e9gion des Grands Lacs (CIRGL).\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De mani\u00e8re succincte, le Pr\u00e9sident entrant de la CIRGL a pr\u00e9sent\u00e9 les priorit\u00e9s de son mandat dit des r\u00e9sultats, \u00e0 savoir : \u00ab\u00a0la r\u00e9forme institutionnelle de la CIRGL ; le r\u00e9tablissement et la consolidation de la paix, de la s\u00e9curit\u00e9 et de la stabilit\u00e9 r\u00e9gionale; le renforcement de la coop\u00e9ration judiciaire; le renforcement de la lutte contre l\u2019exploitation et le commerce illicites des ressources naturelles au travers d\u2019un Programme effectif de tra\u00e7abilit\u00e9 des minerais; l\u2019int\u00e9gration \u00e9conomique r\u00e9gionale\u00a0\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Poursuivant la pr\u00e9sentation du fonctionnement de la CIRGL sous sa pr\u00e9sidence, le Pr\u00e9sident F\u00e9lix Tshisekedi a annonc\u00e9 : \u00ab\u00a0notre Pr\u00e9sidence sera intransigeante sur les principes souverainet\u00e9, int\u00e9grit\u00e9 territoriale, non-agression, refus de tout appui aux groupes arm\u00e9s et r\u00e9solument ouverte au dialogue en vue des solutions politiques durables, inclusives des femmes, des jeunes, des autorit\u00e9s locales et des communaut\u00e9s\u00a0\u00bb.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"526\" height=\"296\" src=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001451430-edited.jpg\" alt=\"\" class=\"wp-image-10033\" srcset=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001451430-edited.jpg 526w, https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001451430-edited-300x169.jpg 300w\" sizes=\"auto, (max-width: 526px) 100vw, 526px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Avant d\u2019ouvrir de mani\u00e8re solennelle les travaux de ce 9\u00e8me sommet des Chefs d\u2019\u00c9tat et de gouvernement de la CIRGL, le Pr\u00e9sident Tshisekedi a d\u00e9voil\u00e9 sa recette pour le d\u00e9veloppement de la r\u00e9gion des Grands Lacs. \u00ab\u00a0Il n\u2019y aura pas de paix sans justice, pas de stabilit\u00e9 sans s\u00e9curit\u00e9 partag\u00e9e, pas de d\u00e9veloppement sans int\u00e9gration r\u00e9elle\u00a0\u00bb, a-t-il conclu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a0Au terme de cette c\u00e9r\u00e9monie solennelle, les Chefs d\u2019\u00c9tat et de gouvernement des pays membres de la Conf\u00e9rence internationale sur la r\u00e9gion des Grands Lacs se sont retir\u00e9s pour une s\u00e9ance de travail \u00e0 huis clos dans la salle de banquets du Palais du peuple.<br>Pour rappel, cinq (5) Chefs d\u2019\u00c9tat ont assist\u00e9 \u00e0 cette c\u00e9r\u00e9monie d\u2019ouverture notamment le Pr\u00e9sident Jo\u00e2o Louren\u00e7o de l\u2019Angola, Faustin Archange Touadera de la RCA, Denis Sassou Nguesso du Congo, \u00c9variste Ndayishimiye du Burundi et F\u00e9lix Antoine Tshisekedi Tshilombo de la RDC.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>SOURCE: Pr\u00e9sidence de la R\u00e9publique D\u00e9mocratique du Congo.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kinshasa, la capitale de la R\u00e9publique D\u00e9mocratique du Congo (RDC) a accueilli, le samedi 15 Novembre 2025 au Palais du peuple, le 9\u00e8me Sommet ordinaire des Chefs d\u2019\u00c9tat et des gouvernements de la Conf\u00e9rence internationale sur la r\u00e9gion des Grands Lacs (CIRGL).\u00a0Ce grand \u00e9v\u00e9nement,qui intervient \u00a0cinq ans apr\u00e8s le dernier<\/p>\n","protected":false},"author":3,"featured_media":10035,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout","_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[51],"tags":[],"class_list":["post-10030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-diplomatie"],"magazineBlocksPostFeaturedMedia":{"thumbnail":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited-150x150.jpg","medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited-300x169.jpg","medium_large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited-768x432.jpg","large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited-1024x576.jpg","1536x1536":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited-1536x864.jpg","2048x2048":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited.jpg","colormag-highlighted-post":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited-392x272.jpg","colormag-featured-post-medium":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited-390x205.jpg","colormag-featured-post-small":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited-130x90.jpg","colormag-featured-image":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited-800x445.jpg","colormag-default-news":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited-150x150.jpg","colormag-featured-image-large":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited-1400x600.jpg"},"magazineBlocksPostAuthor":{"name":"La R\u00e9daction CI","avatar":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g"},"magazineBlocksPostCommentsNumber":false,"magazineBlocksPostExcerpt":"Kinshasa, la capitale de la R\u00e9publique D\u00e9mocratique du Congo (RDC) a accueilli, le samedi 15 Novembre 2025 au Palais du peuple, le 9\u00e8me Sommet ordinaire des Chefs d\u2019\u00c9tat et des gouvernements de la Conf\u00e9rence internationale sur la r\u00e9gion des Grands Lacs (CIRGL).\u00a0Ce grand \u00e9v\u00e9nement,qui intervient \u00a0cinq ans apr\u00e8s le dernier","magazineBlocksPostCategories":["DIPLOMATIE"],"magazineBlocksPostViewCount":873,"magazineBlocksPostReadTime":3,"magazine_blocks_featured_image_url":{"full":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited.jpg",2048,1152,false],"medium":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited-300x169.jpg",300,169,true],"thumbnail":["https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited-150x150.jpg",150,150,true]},"magazine_blocks_author":{"display_name":"La R\u00e9daction CI","author_link":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"},"magazine_blocks_comment":0,"magazine_blocks_author_image":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","magazine_blocks_category":"<a href=\"#\" class=\"category-link category-link-51\">DIPLOMATIE<\/a>","yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Grands Lacs : F\u00e9lix Tshisekedi prend la t\u00eate de la pr\u00e9sidence de la CIRGL - Cooperation Internationale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grands Lacs : F\u00e9lix Tshisekedi prend la t\u00eate de la pr\u00e9sidence de la CIRGL - Cooperation Internationale\" \/>\n<meta property=\"og:description\" content=\"Kinshasa, la capitale de la R\u00e9publique D\u00e9mocratique du Congo (RDC) a accueilli, le samedi 15 Novembre 2025 au Palais du peuple, le 9\u00e8me Sommet ordinaire des Chefs d\u2019\u00c9tat et des gouvernements de la Conf\u00e9rence internationale sur la r\u00e9gion des Grands Lacs (CIRGL).\u00a0Ce grand \u00e9v\u00e9nement,qui intervient \u00a0cinq ans apr\u00e8s le dernier\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/\" \/>\n<meta property=\"og:site_name\" content=\"Cooperation Internationale\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/journalCI\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-16T10:48:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-16T10:48:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1152\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"La R\u00e9daction CI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:site\" content=\"@lejournalc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"La R\u00e9daction CI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/\"},\"author\":{\"name\":\"La R\u00e9daction CI\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\"},\"headline\":\"Grands Lacs : F\u00e9lix Tshisekedi prend la t\u00eate de la pr\u00e9sidence de la CIRGL\",\"datePublished\":\"2025-11-16T10:48:34+00:00\",\"dateModified\":\"2025-11-16T10:48:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/\"},\"wordCount\":595,\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited.jpg\",\"articleSection\":[\"DIPLOMATIE\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/\",\"url\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/\",\"name\":\"Grands Lacs : F\u00e9lix Tshisekedi prend la t\u00eate de la pr\u00e9sidence de la CIRGL - Cooperation Internationale\",\"isPartOf\":{\"@id\":\"https:\/\/www.lejournalci.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited.jpg\",\"datePublished\":\"2025-11-16T10:48:34+00:00\",\"dateModified\":\"2025-11-16T10:48:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/#primaryimage\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited.jpg\",\"width\":2048,\"height\":1152},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lejournalci.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grands Lacs : F\u00e9lix Tshisekedi prend la t\u00eate de la pr\u00e9sidence de la CIRGL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lejournalci.org\/#website\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"name\":\"Cooperation Internationale\",\"description\":\"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement\",\"publisher\":{\"@id\":\"https:\/\/www.lejournalci.org\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lejournalci.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lejournalci.org\/#organization\",\"name\":\"Cooperation Internationale\",\"url\":\"https:\/\/www.lejournalci.org\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"contentUrl\":\"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg\",\"width\":700,\"height\":214,\"caption\":\"Cooperation Internationale\"},\"image\":{\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/journalCI\/\",\"https:\/\/x.com\/lejournalc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b\",\"name\":\"La R\u00e9daction CI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g\",\"caption\":\"La R\u00e9daction CI\"},\"url\":\"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grands Lacs : F\u00e9lix Tshisekedi prend la t\u00eate de la pr\u00e9sidence de la CIRGL - Cooperation Internationale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/","og_locale":"fr_FR","og_type":"article","og_title":"Grands Lacs : F\u00e9lix Tshisekedi prend la t\u00eate de la pr\u00e9sidence de la CIRGL - Cooperation Internationale","og_description":"Kinshasa, la capitale de la R\u00e9publique D\u00e9mocratique du Congo (RDC) a accueilli, le samedi 15 Novembre 2025 au Palais du peuple, le 9\u00e8me Sommet ordinaire des Chefs d\u2019\u00c9tat et des gouvernements de la Conf\u00e9rence internationale sur la r\u00e9gion des Grands Lacs (CIRGL).\u00a0Ce grand \u00e9v\u00e9nement,qui intervient \u00a0cinq ans apr\u00e8s le dernier","og_url":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/","og_site_name":"Cooperation Internationale","article_publisher":"https:\/\/www.facebook.com\/journalCI\/","article_published_time":"2025-11-16T10:48:34+00:00","article_modified_time":"2025-11-16T10:48:36+00:00","og_image":[{"width":2048,"height":1152,"url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited.jpg","type":"image\/jpeg"}],"author":"La R\u00e9daction CI","twitter_card":"summary_large_image","twitter_creator":"@lejournalc","twitter_site":"@lejournalc","twitter_misc":{"\u00c9crit par":"La R\u00e9daction CI","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/#article","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/"},"author":{"name":"La R\u00e9daction CI","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b"},"headline":"Grands Lacs : F\u00e9lix Tshisekedi prend la t\u00eate de la pr\u00e9sidence de la CIRGL","datePublished":"2025-11-16T10:48:34+00:00","dateModified":"2025-11-16T10:48:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/"},"wordCount":595,"publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited.jpg","articleSection":["DIPLOMATIE"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/","url":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/","name":"Grands Lacs : F\u00e9lix Tshisekedi prend la t\u00eate de la pr\u00e9sidence de la CIRGL - Cooperation Internationale","isPartOf":{"@id":"https:\/\/www.lejournalci.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/#primaryimage"},"image":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/#primaryimage"},"thumbnailUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited.jpg","datePublished":"2025-11-16T10:48:34+00:00","dateModified":"2025-11-16T10:48:36+00:00","breadcrumb":{"@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/#primaryimage","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited.jpg","width":2048,"height":1152},{"@type":"BreadcrumbList","@id":"https:\/\/www.lejournalci.org\/index.php\/2025\/11\/16\/grands-lacs-felix-tshisekedi-prend-la-tete-de-la-presidence-de-la-cirgl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lejournalci.org\/"},{"@type":"ListItem","position":2,"name":"Grands Lacs : F\u00e9lix Tshisekedi prend la t\u00eate de la pr\u00e9sidence de la CIRGL"}]},{"@type":"WebSite","@id":"https:\/\/www.lejournalci.org\/#website","url":"https:\/\/www.lejournalci.org\/","name":"Cooperation Internationale","description":"Faire de la Coop\u00e9ration un Puissant Instrument de D\u00e9veloppement","publisher":{"@id":"https:\/\/www.lejournalci.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lejournalci.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lejournalci.org\/#organization","name":"Cooperation Internationale","url":"https:\/\/www.lejournalci.org\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","contentUrl":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2024\/12\/logo-coopint_HD_3.jpg","width":700,"height":214,"caption":"Cooperation Internationale"},"image":{"@id":"https:\/\/www.lejournalci.org\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/journalCI\/","https:\/\/x.com\/lejournalc"]},{"@type":"Person","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/2efe42dc5459aaaf6d89cb27e736002b","name":"La R\u00e9daction CI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lejournalci.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e63ab2ab378e283740d8889fbe2ec43fdcee7ac714a480d705f61cb1e5675c4c?s=96&d=mm&r=g","caption":"La R\u00e9daction CI"},"url":"https:\/\/www.lejournalci.org\/index.php\/author\/noebricendongyahoo-fr\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.lejournalci.org\/wp-content\/uploads\/2025\/11\/1001453163-edited.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/10030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/comments?post=10030"}],"version-history":[{"count":1,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/10030\/revisions"}],"predecessor-version":[{"id":10036,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/posts\/10030\/revisions\/10036"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media\/10035"}],"wp:attachment":[{"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/media?parent=10030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/categories?post=10030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lejournalci.org\/index.php\/wp-json\/wp\/v2\/tags?post=10030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}